﻿{"id":233028,"date":"2025-09-23T07:40:03","date_gmt":"2025-09-23T05:40:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=233028"},"modified":"2025-09-24T12:57:29","modified_gmt":"2025-09-24T10:57:29","slug":"affido-presentazione-del-libro-larcobaleno-di-sofia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/","title":{"rendered":"Affido. Presentazione del libro &#8220;L&#8217;arcobaleno di Sofia&#8221;"},"content":{"rendered":"<h2>Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l&#8217;incontro con l&#8217;autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia<!--more--><\/h2>\n<p>Dopo la recente riapertura (<a href=\"https:\/\/www.aibi.it\/ita\/affido-familiare-family-point-misinto\/\">QUI<\/a>), il <strong>Family Point\u00a0<\/strong>di\u00a0<strong>Ai.Bi. Amici dei Bambini<\/strong>, sta per inaugurare una nuova serie di incontri dedicati al tema dell&#8217;affido e dell&#8217;accoglienza.<\/p>\n<h3>La presentazione<\/h3>\n<p>La nuova stagione del Family Point si apre con un momento di festa e riflessione per tutta la comunit\u00e0,\u00a0<strong>venerd\u00ec 26\u00a0<\/strong><strong>settembre\u00a0<\/strong><strong>alle ore 10.00,<\/strong>\u00a0presso la sede di via D. Padovan 49.<br \/>\nCon la riapertura, riparte anche il ciclo di incontri dedicati alla\u00a0<strong>sensibilizzazione sull\u2019accoglienza familiare<\/strong>.<br \/>\nIl primo appuntamento \u00e8 fissato per il\u00a0<strong>26\u00a0<\/strong><strong>settembre\u00a0<\/strong><strong>alle ore 20.30<\/strong>, con\u00a0<strong>Nazzareno Coppola<\/strong>, da oltre vent\u2019anni pap\u00e0 affidatario e coordinatore della Casa-famiglia Pollicino di Imperia, docente e formatore sull\u2019Affido Familiare, nonch\u00e9 membro del Tavolo Nazionale Affido. Durante la serata Coppola presenter\u00e0 il suo ultimo libro, che racconta la vera storia di una donna segnata da abusi e abbandono infantile, ma capace di rinascere. L\u2019autore ha gi\u00e0 pubblicato altre due opere autobiografiche,\u00a0<strong>Ho imparato ad ASPETTARE<\/strong>\u00a0e\u00a0<strong>La mia Alba<\/strong>, che ripercorrono il suo cammino personale e la sua dedizione all\u2019affido.<br \/>\nL\u2019incontro vedr\u00e0 anche la partecipazione di\u00a0<strong>Cristina Riccardi<\/strong>, vicepresidente di Ai.Bi. e del Forum Nazionale delle Associazioni Familiari, e di\u00a0<strong>Stefania Balzaretti<\/strong>, responsabile del Family Point. Sar\u00e0 un\u2019occasione preziosa per conoscere da vicino l\u2019affido familiare, esperienza complessa ma capace di trasformarsi in un viaggio ricco di emozioni, condivisione e amore.<\/p>\n<h3>Informazioni e richieste sull\u2019affido familiare<\/h3>\n<p>Chiunque volesse approfondire la conoscenza dell\u2019<strong>affido familiare\u00a0<\/strong>e riflettere sulla propria disponibilit\u00e0 a\u00a0<strong>intraprendere questo percorso<\/strong>, pu\u00f2 partecipare agli\u00a0<strong>incontri organizzati da Amici dei Bambini<\/strong><br \/>\nTutte le informazioni si trovano alla\u00a0<a href=\"http:\/\/www.aibi.it\/affido\"><strong>pagina dedicata<\/strong><\/a>\u00a0del sito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd&igrave; 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l&rsquo;incontro con l&rsquo;autore Nazzareno Coppola, gi&agrave; padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia<\/p>\n","protected":false},"author":133,"featured_media":233029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-233028","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affido. Presentazione del libro &quot;L&#039;arcobaleno di Sofia&quot;<\/title>\n<meta name=\"description\" content=\"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l&#039;incontro con l&#039;autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affido. Presentazione del libro &quot;L&#039;arcobaleno di Sofia&quot;\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l&#039;incontro con l&#039;autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T05:40:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T10:57:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Affido. Presentazione del libro &#8220;L&#8217;arcobaleno di Sofia&#8221;\",\"datePublished\":\"2025-09-23T05:40:03+00:00\",\"dateModified\":\"2025-09-24T10:57:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/arcobaleno-di-Sofia.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/\",\"name\":\"Affido. Presentazione del libro \\\"L'arcobaleno di Sofia\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/arcobaleno-di-Sofia.jpg\",\"datePublished\":\"2025-09-23T05:40:03+00:00\",\"dateModified\":\"2025-09-24T10:57:29+00:00\",\"description\":\"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l'incontro con l'autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/arcobaleno-di-Sofia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/09\\\/arcobaleno-di-Sofia.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/affido-presentazione-del-libro-larcobaleno-di-sofia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affido. Presentazione del libro &#8220;L&#8217;arcobaleno di Sofia&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affido. Presentazione del libro \"L'arcobaleno di Sofia\"","description":"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l'incontro con l'autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/","og_locale":"it_IT","og_type":"article","og_title":"Affido. Presentazione del libro \"L'arcobaleno di Sofia\"","og_description":"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l'incontro con l'autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia","og_url":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-09-23T05:40:03+00:00","article_modified_time":"2025-09-24T10:57:29+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Affido. Presentazione del libro &#8220;L&#8217;arcobaleno di Sofia&#8221;","datePublished":"2025-09-23T05:40:03+00:00","dateModified":"2025-09-24T10:57:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/"},"wordCount":305,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/","url":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/","name":"Affido. Presentazione del libro \"L'arcobaleno di Sofia\"","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg","datePublished":"2025-09-23T05:40:03+00:00","dateModified":"2025-09-24T10:57:29+00:00","description":"Venerd\u00ec 26 settembre presso il Family Point di Ai.Bi. Amici dei Bambini si tiene l'incontro con l'autore Nazzareno Coppola, gi\u00e0 padre affidatario e coordinatore della Casa-famiglia Pollicino di Imperia","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/09\/arcobaleno-di-Sofia.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/affido-presentazione-del-libro-larcobaleno-di-sofia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Affido. Presentazione del libro &#8220;L&#8217;arcobaleno di Sofia&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:13:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/233028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=233028"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/233028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/233029"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=233028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=233028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=233028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}