﻿{"id":234192,"date":"2025-11-19T07:50:38","date_gmt":"2025-11-19T06:50:38","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=234192"},"modified":"2025-11-19T17:22:33","modified_gmt":"2025-11-19T16:22:33","slug":"settimana-sensibilizzazione-accoglienza-adozione-voci-storie","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/","title":{"rendered":"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi"},"content":{"rendered":"<h2>&#8220;Essere genitori significa amare con il cuore.&#8221;\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza<\/h2>\n<p><!--more--><\/p>\n<p>Si \u00e8 tenuta presso il\u00a0<strong>Centro Pastorale di Bolzano<\/strong> la presentazione della\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/bolzano-settimana-sensibilizzazione-accoglienza-adozione\/\">Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione<\/a>. L\u2019obiettivo dell\u2019iniziativa \u00e8 quello di\u00a0<strong>far conoscere alla popolazione l\u2019adozione internazionale<\/strong>, illustrandone le novit\u00e0 e offrendo\u00a0<strong>informazioni utili<\/strong>\u00a0a superare alcuni stereotipi ancora diffusi. Protagoniste della serata sono state\u00a0<strong>le famiglie adottive e i loro figli<\/strong>, che attraverso le loro testimonianze hanno raccontato l\u2019adozione vissuta nella quotidianit\u00e0.<\/p>\n<h3>La presentazione della settimana<\/h3>\n<p><strong>Valentina Lazzarotto<\/strong>\u00a0ha parlato dei suoi figli,\u00a0oggi\u00a0adolescenti, che ogni giorno affrontano la vita dando il meglio di s\u00e9. Il maggiore, proveniente dalla\u00a0<strong>Cambogia<\/strong>, ha un grande talento nella manualit\u00e0, \u00e8 generoso e premuroso; il suo carattere tranquillo lo aiuta ad affrontare con serenit\u00e0 la vita di tutti i giorni. Il secondogenito, originario della\u00a0<strong>Cina<\/strong>, \u00e8 invece una promessa sportiva nel settore giovanile del salto con gli sci: quest\u2019anno\u00a0<strong>parteciper\u00e0 all\u2019apertura delle Olimpiadi della Neve<\/strong>. Nella sua determinazione si ritrovano le sue origini. La terzogenita, figlia biologica, chiede spesso alla mamma perch\u00e9 lei non sia nata in luoghi esotici come i fratelli. Vivere con tre adolescenti significa affrontare alti e bassi, ma forte \u00e8 il legame che li unisce e il loro sentirsi pienamente famiglia.<br \/>\nLa\u00a0<strong>coppia Achammer<\/strong>\u00a0ha condiviso la propria esperienza parlando della\u00a0<strong>bellezza dell\u2019adozione<\/strong>, un atto d\u2019amore che porta soprattutto tanta gioia. Il loro desiderio di adottare \u00e8 nato quando erano giovani e, dopo la nascita del loro figlio biologico, hanno coronato il loro sogno accogliendo una bambina dal\u00a0<strong>Burundi.<\/strong>\u00a0Con la loro testimonianza hanno incoraggiato le coppie a non temere l\u2019adozione: troppo spesso, infatti, si parla principalmente delle difficolt\u00e0, lasciando poco spazio alla gioia che questo percorso pu\u00f2 portare.<br \/>\n<strong>Alessia Demelas<\/strong>, mamma adottiva di un bambino proveniente dal\u00a0<strong>Per\u00f9,<\/strong>\u00a0ha posto l\u2019attenzione sulla\u00a0<strong>straordinaria capacit\u00e0 dei bambini di fidarsi dei nuovi genitori<\/strong>\u00a0e di tornare ad amare affidandosi a loro. Ha per\u00f2 sottolineato anche le difficolt\u00e0 incontrate nel contesto scolastico, dove non sempre \u00e8 facile far comprendere paure e reazioni tipiche del vissuto adottivo. Il bambino ha portato grande gioia in famiglia e ha trovato il suo equilibrio, ma resta ancora molto da fare nel dialogo con la scuola.<br \/>\nA portare la voce dei figli adottivi \u00e8 stato\u00a0<strong>Artiom Cecchetti<\/strong>, adottato in\u00a0<strong>Moldavia<\/strong>\u00a0molti anni fa e\u00a0oggi\u00a0<strong>laureando in Filosofia<\/strong>. Raccontando la sua storia, ha evidenziato l\u2019importanza di preparare i bambini all\u2019adozione: lui, infatti, si \u00e8 trovato da un giorno all\u2019altro con una nuova famiglia, ma nonostante lo smarrimento iniziale ha saputo fidarsi perch\u00e9 ha percepito molto amore. Ha riflettuto anche sul\u00a0<strong>significato dell\u2019essere figli<\/strong>, spesso messo in discussione da domande ingenue come\u00a0<strong>\u201cVi sentite genitori veri?\u201d<\/strong>, che mettono in imbarazzo per la loro banalit\u00e0. Essere genitori, ha ricordato, significa<strong>\u00a0amare con il cuore<\/strong>.<\/p>\n<h3>Arte\u00a0e accoglienza<\/h3>\n<p>La mattinata si \u00e8 conclusa con un suggestivo\u00a0<strong>accostamento tra adozione e arte<\/strong>. L\u2019artista<strong>\u00a0Tessandra Lo Cicero<\/strong>\u00a0ha infatti guidato i partecipanti alla scoperta del suo quadro\u00a0<strong>Nuova Vita<\/strong>, illustrandone le varie fasi creative e svelando l\u2019opera completata. Il dipinto raffigura l\u2019arcangelo Gabriele, protettore dei bambini e considerato un \u201cCustode Luminoso dell\u2019Innocenza\u201d. L\u2019arcangelo veglia su un albero dalle radici profonde, simbolo dei legami intrecciati nell\u2019adozione; sul tronco prende forma l\u2019immagine di una coppia che, con il proprio amore, accoglie il volto di una bambina. L\u2019opera ha suscitato un lungo e caloroso applauso da parte del pubblico.<br \/>\nOggi\u00a0la settimana prosegue con un flash mob nella Valle, dove i bambini delle scuole elementari e della scuola dell\u2019infanzia ci attendono per danzare insieme e partecipare al laboratorio creativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ldquo;Essere genitori significa amare con il cuore.&rdquo;&nbsp;Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell&rsquo;accoglienza<\/p>\n","protected":false},"author":133,"featured_media":234195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[],"class_list":["post-234192","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Settimana accoglienza e adozione: voci, storie e nuovi sguardi<\/title>\n<meta name=\"description\" content=\"&quot;Essere genitori significa amare con il cuore.&quot;\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi\" \/>\n<meta property=\"og:description\" content=\"&quot;Essere genitori significa amare con il cuore.&quot;\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T06:50:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T16:22:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi\",\"datePublished\":\"2025-11-19T06:50:38+00:00\",\"dateModified\":\"2025-11-19T16:22:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/\"},\"wordCount\":630,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg\",\"articleSection\":[\"Adozione Internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/\",\"name\":\"Settimana accoglienza e adozione: voci, storie e nuovi sguardi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg\",\"datePublished\":\"2025-11-19T06:50:38+00:00\",\"dateModified\":\"2025-11-19T16:22:33+00:00\",\"description\":\"\\\"Essere genitori significa amare con il cuore.\\\"\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Tessandra Lo Cicero e il suo quadro Nuova Vita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Settimana accoglienza e adozione: voci, storie e nuovi sguardi","description":"\"Essere genitori significa amare con il cuore.\"\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/","og_locale":"it_IT","og_type":"article","og_title":"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi","og_description":"\"Essere genitori significa amare con il cuore.\"\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza","og_url":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-11-19T06:50:38+00:00","article_modified_time":"2025-11-19T16:22:33+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi","datePublished":"2025-11-19T06:50:38+00:00","dateModified":"2025-11-19T16:22:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/"},"wordCount":630,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg","articleSection":["Adozione Internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/","url":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/","name":"Settimana accoglienza e adozione: voci, storie e nuovi sguardi","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg","datePublished":"2025-11-19T06:50:38+00:00","dateModified":"2025-11-19T16:22:33+00:00","description":"\"Essere genitori significa amare con il cuore.\"\u00a0Famiglie, figli adottivi e professionisti riuniti a Bolzano per superare stereotipi e valorizzare la bellezza dell\u2019accoglienza","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/Nuova-Vita-di-Tessandra-Lo-Cicero.jpg","width":1200,"height":630,"caption":"Tessandra Lo Cicero e il suo quadro Nuova Vita"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/settimana-sensibilizzazione-accoglienza-adozione-voci-storie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Settimana di sensibilizzazione sull\u2019accoglienza e sull\u2019adozione: voci, storie e nuovi sguardi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:43:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=234192"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/234195"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=234192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=234192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=234192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}