﻿


{"id":234352,"date":"2025-11-27T07:40:37","date_gmt":"2025-11-27T06:40:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=234352"},"modified":"2025-11-27T12:01:07","modified_gmt":"2025-11-27T11:01:07","slug":"accoglienza-webinar-bambini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/","title":{"rendered":"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi"},"content":{"rendered":"<h2>Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli<\/h2>\n<p><!--more--><\/p>\n<p>Gioved\u00ec 4\u00a0dicembre\u00a0alle 20:00 si terr\u00e0 su piattaforma Zoom il webinar gratuito\u00a0<strong>Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza<\/strong>, un appuntamento dedicato a tutti coloro che desiderano comprendere meglio il mondo dei minori in difficolt\u00e0 familiare, in Italia e nel mondo.<\/p>\n<h3>Le diverse forme di accoglienza<\/h3>\n<p>L\u2019incontro offrir\u00e0 uno sguardo chiaro e diretto sulle\u00a0<strong>diverse forme di accoglienza<\/strong>\u00a0oggi\u00a0possibili: dall\u2019affido familiare all\u2019adozione nazionale e internazionale, fino al ruolo \u2013 ancora poco conosciuto ma fondamentale \u2013 dei\u00a0<strong>tutori volontari<\/strong>\u00a0per i Minori Stranieri Non Accompagnati.<br \/>\nIl webinar vuole essere un primo orientamento per chi sente il desiderio di dare il proprio contributo, mettendo a disposizione tempo, ascolto e disponibilit\u00e0 verso bambini e bambine che hanno bisogno di un punto di riferimento stabile e significativo.<br \/>\nLa serata sar\u00e0 guidata da\u00a0<strong>Michela De Santi<\/strong>, referente di\u00a0<strong>Ai.Bi. Amici dei Bambini\u00a0<\/strong>per la sede di Bolzano,\u00a0che accompagner\u00e0 i partecipanti in un\u00a0<strong>percorso informativo<\/strong> semplice, accessibile e ricco di spunti per avvicinarsi con consapevolezza all\u2019accoglienza familiare.<\/p>\n<h3>Informazioni<\/h3>\n<p>Bambini da accogliere, chi e come? Aprirsi all\u2019accoglienza<br \/>\nGioved\u00ec 4\u00a0dicembre\u00a0alle ore 20:00<br \/>\nPer maggiori dettagli, clicca\u00a0<a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-bambini-da-accogliere-chi-e-come-aprirsi-allaccoglienza-2\/\">QUI<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per orientarsi tra affido, adozione e tutela dei minori in difficolt&agrave;, Ai.Bi. organizza per il 4&nbsp;dicembre&nbsp;un incontro online dedicato. Ecco i dettagli<\/p>\n","protected":false},"author":133,"featured_media":234353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[435,320,718],"class_list":["post-234352","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-accoglienza","tag-affido","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprirsi all\u2019accoglienza: il webinar<\/title>\n<meta name=\"description\" content=\"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi\" \/>\n<meta property=\"og:description\" content=\"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T06:40:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T11:01:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi\",\"datePublished\":\"2025-11-27T06:40:37+00:00\",\"dateModified\":\"2025-11-27T11:01:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/accoglienza-famiglia.jpg\",\"keywords\":[\"accoglienza\",\"affido\",\"Webinar\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/\",\"name\":\"Aprirsi all\u2019accoglienza: il webinar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/accoglienza-famiglia.jpg\",\"datePublished\":\"2025-11-27T06:40:37+00:00\",\"dateModified\":\"2025-11-27T11:01:07+00:00\",\"description\":\"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/accoglienza-famiglia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/11\\\/accoglienza-famiglia.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/accoglienza-webinar-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprirsi all\u2019accoglienza: il webinar","description":"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi","og_description":"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli","og_url":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-11-27T06:40:37+00:00","article_modified_time":"2025-11-27T11:01:07+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi","datePublished":"2025-11-27T06:40:37+00:00","dateModified":"2025-11-27T11:01:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg","keywords":["accoglienza","affido","Webinar"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/","url":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/","name":"Aprirsi all\u2019accoglienza: il webinar","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg","datePublished":"2025-11-27T06:40:37+00:00","dateModified":"2025-11-27T11:01:07+00:00","description":"Per orientarsi tra affido, adozione e tutela dei minori in difficolt\u00e0, Ai.Bi. organizza per il 4\u00a0dicembre\u00a0un incontro online dedicato. Ecco i dettagli","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/11\/accoglienza-famiglia.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/accoglienza-webinar-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Aprirsi all\u2019accoglienza: il webinar gratuito per scoprire chi sono i bambini da accogliere\u00a0oggi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=234352"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/234353"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=234352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=234352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=234352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}