﻿{"id":234952,"date":"2025-12-22T11:00:58","date_gmt":"2025-12-22T10:00:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=234952"},"modified":"2025-12-22T17:54:13","modified_gmt":"2025-12-22T16:54:13","slug":"chiave-volta-tutela-infanzia-calabria","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/","title":{"rendered":"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria"},"content":{"rendered":"<h2>Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili<\/h2>\n<p><!--more--><\/p>\n<p>La Cooperativa Sociale\u00a0<strong>La Chiave di Volta<\/strong>\u00a0di Gioia Tauro (RC) e\u00a0<strong>Ai.Bi. Amici dei Bambini ETS<\/strong>\u00a0annunciano una nuova collaborazione a sostegno delle famiglie e dei minori. L\u2019accordo prevede iniziative di sensibilizzazione, formazione e orientamento, oltre allo sviluppo di progetti comuni su scala nazionale. Una sinergia tra enti del Terzo Settore che punta a rafforzare le reti di solidariet\u00e0 e a\u00a0<strong>rispondere in modo concreto ai bisogni sociali<\/strong>, unendo le competenze nel campo dell\u2019accoglienza e\u00a0<strong>promuovendo congiuntamente l&#8217;adozione e la cultura dell\u2019affido familiare<\/strong>, cos\u00ec da mettere al centro i bisogni dei minori e delle famiglie in difficolt\u00e0.<br \/>\nAbbiamo raggiunto il presidente della cooperativa, Marco Dato che illustra la natura delle attivit\u00e0 e lo spirito con il quale \u00e8 nata questa importante collaborazione.<\/p>\n<h3>Conosciamo la Cooperativa &#8220;Chiave di Volta&#8221;<\/h3>\n<p><strong>Raccontiamo in breve, per chi non vi conosce, di cosa si occupa la Cooperative Chiave di Volta?\u00a0<\/strong><\/p>\n<p>\u201cLa Chiave di Volta opera mettendo al centro la persona e il territorio, occupandosi dell\u2019accompagnamento dei minori e dell\u2019inclusione di soggetti fragili. Ci occupiamo di accompagnare i minori, sostenere i nuclei familiari in difficolt\u00e0 e promuovere percorsi di inclusione per chi vive situazioni di vulnerabilit\u00e0.\u00a0<strong>Sosteniamo inoltre la cultura dell\u2019adozione e dell\u2019affido su tutto il territorio nazionale<\/strong>, camminando al fianco delle famiglie. Infine promuoviamo corsi di formazione sull\u2019affido familiare in co-progettazione con l\u2019amministrazione comunale e offriamo servizi dedicati alla comunit\u00e0\u201d.<\/p>\n<p><strong>Come \u00e8 avvenuto l\u2019incontro con Ai.Bi.?<\/strong><\/p>\n<p>Le nostre strade si sono incrociate grazie a un intento comune:\u00a0<strong>mettere al centro i bisogni dei minori e delle famiglie<\/strong>. Non esistevano collaborazioni pregresse, ma condividiamo la volont\u00e0 di avviare in futuro progetti dedicati all\u2019infanzia, costruiti su una visione condivisa dei\u00a0servizi alla comunit\u00e0.<\/p>\n<p><strong>Quali iniziative sono in programma nell\u2019immediato futuro?<\/strong><\/p>\n<p>Il piano d\u2019azione futuro prevede l\u2019organizzazione di convegni e momenti pubblici di sensibilizzazione, per promuovere l\u2019importanza della collaborazione tra la nostra cooperativa e Ai.Bi. Queste iniziative mirano a diffondere una corretta informazione sull\u2019affido e rafforzando, contemporaneamente, la rete territoriale di supporto alle famiglie.<\/p>\n<p><strong>Come valuterebbe la situazione attuale dell\u2019affido nel vostro territorio?<\/strong><\/p>\n<p>Nonostante le sfide culturali, il bilancio degli ultimi anni mostra un\u00a0<strong>segnale positivo<\/strong>: cresce l\u2019interesse dei nuclei familiari verso l\u2019accoglienza e l\u2019affido familiare. Tuttavia, c\u2019\u00e8 ancora molto da fare per abbattere pregiudizi e diffondere una corretta informazione. Per questo riteniamo fondamentale continuare a investire nella sensibilizzazione e nella formazione.<\/p>\n<p><strong>Esiste gi\u00e0 una rete di famiglie pronta e interessata a questa forma di protezione dell\u2019infanzia?<\/strong><\/p>\n<p>Ad\u00a0oggi, la cooperativa pu\u00f2 contare su una rete solida di circa 60 famiglie gi\u00e0 formate e preparate, pronte ad accogliere con consapevolezza, responsabilit\u00e0 e spirito di solidariet\u00e0. Questa rete rappresenta una risorsa preziosa per il territorio e per i minori che necessitano di un ambiente sicuro.<br \/>\nTante sono le iniziative che gi\u00e0 si vedono all&#8217;o0rizzonte. Ma per dare qualche elemento in pi\u00f9 che aiuti a conoscere la Cooperativa Chiave di Volta fin da subito, si pu\u00f2 vedere,\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=gGjgJssCvLw\">QUI<\/a>, il recente video realizzato per raccontare &#8220;con delicatezza e intensit\u00e0, la storia di un bambino in affido e della luce che nasce quando qualcuno sceglie di accoglierlo&#8221;.<\/p>\n<h3>Informazioni e richieste sull\u2019affido familiare<\/h3>\n<p>Chiunque volesse approfondire la conoscenza dell\u2019<strong>affido familiare\u00a0<\/strong>e riflettere sulla propria disponibilit\u00e0 a\u00a0<strong>intraprendere questo percorso<\/strong>, pu\u00f2 partecipare agli\u00a0<strong>incontri organizzati da Amici dei Bambini<\/strong><br \/>\nTutte le informazioni si trovano alla\u00a0<a href=\"http:\/\/www.aibi.it\/affido\"><strong>pagina dedicata<\/strong><\/a>\u00a0del sito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell&rsquo;affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili<\/p>\n","protected":false},"author":133,"featured_media":234953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[652],"tags":[320],"class_list":["post-234952","post","type-post","status-publish","format-standard","has-post-thumbnail","category-affido","tag-affido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ai.Bi. e La Chiave di Volta per la tutela dell\u2019infanzia<\/title>\n<meta name=\"description\" content=\"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria\" \/>\n<meta property=\"og:description\" content=\"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-22T10:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T16:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria\",\"datePublished\":\"2025-12-22T10:00:58+00:00\",\"dateModified\":\"2025-12-22T16:54:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/12\\\/aiuto-collaborazione.jpg\",\"keywords\":[\"affido\"],\"articleSection\":[\"Affido &amp; Accoglienza Familiare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/\",\"name\":\"Ai.Bi. e La Chiave di Volta per la tutela dell\u2019infanzia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/12\\\/aiuto-collaborazione.jpg\",\"datePublished\":\"2025-12-22T10:00:58+00:00\",\"dateModified\":\"2025-12-22T16:54:13+00:00\",\"description\":\"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/12\\\/aiuto-collaborazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2025\\\/12\\\/aiuto-collaborazione.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/chiave-volta-tutela-infanzia-calabria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affido &amp; Accoglienza Familiare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/affido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ai.Bi. e La Chiave di Volta per la tutela dell\u2019infanzia","description":"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/","og_locale":"it_IT","og_type":"article","og_title":"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria","og_description":"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili","og_url":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2025-12-22T10:00:58+00:00","article_modified_time":"2025-12-22T16:54:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria","datePublished":"2025-12-22T10:00:58+00:00","dateModified":"2025-12-22T16:54:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg","keywords":["affido"],"articleSection":["Affido &amp; Accoglienza Familiare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/","url":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/","name":"Ai.Bi. e La Chiave di Volta per la tutela dell\u2019infanzia","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg","datePublished":"2025-12-22T10:00:58+00:00","dateModified":"2025-12-22T16:54:13+00:00","description":"Siglata la collaborazione con una cooperativa di Gioia Tauro per rafforzare la cultura dell\u2019affido familiare e costruire una rete di sostegno ai minori e alle famiglie fragili","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2025\/12\/aiuto-collaborazione.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/chiave-volta-tutela-infanzia-calabria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Affido &amp; Accoglienza Familiare","item":"https:\/\/www.aibi.it\/ita\/category\/affido\/"},{"@type":"ListItem","position":3,"name":"Ai.Bi. e La Chiave di Volta: insieme per la tutela dell\u2019infanzia in Calabria"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:13:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=234952"}],"version-history":[{"count":2,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234952\/revisions"}],"predecessor-version":[{"id":234955,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/234952\/revisions\/234955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/234953"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=234952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=234952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=234952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}