﻿


{"id":235582,"date":"2026-01-29T07:30:50","date_gmt":"2026-01-29T06:30:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=235582"},"modified":"2026-01-29T11:15:35","modified_gmt":"2026-01-29T10:15:35","slug":"congo-jojo-progressi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/","title":{"rendered":"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo."},"content":{"rendered":"<h2>Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale<\/h2>\n<p><!--more--><\/p>\n<p>Jojo era un bambino con alle spalle molti problemi familiari, incapace di concentrarsi sulla scuola e perennemente a rischio, vivendo spesso in strada. L&#8217;aiuto dell&#8217;Adozione a Distanza e il\u00a0<strong>costante lavoro\u00a0dell\u2019assistente sociale e del team psicosociale<\/strong>\u00a0del centro SODAS, uno degli orfanotrofi con i quali collabora Amici dei Bambini in Repubblica Democratica del Congo, hanno cambiato drasticamente la situazione, dando a Jojo una\u00a0<strong>motivazione nuova<\/strong>\u00a0e una rinnovata fiducia in se stesso.<\/p>\n<h3>La scuola e la famiglia<\/h3>\n<p>In passato, la frequenza scolastica di Jojo era fortemente compromessa da una situazione familiare molto difficile. Ogni sera era costretto ad assistere alle\u00a0<strong>violente liti<\/strong>\u00a0tra il padre, spesso ubriaco, e la madre, che faceva il possibile per garantire la sopravvivenza della famiglia. Questo clima di instabilit\u00e0 lo portava a un rendimento scolastico scarso e a frequenti bocciature. Nell\u2019anno scolastico 2023-2024, vista la gravit\u00e0 della situazione, il team psicosociale ha richiesto l\u2019intervento dell\u2019avvocato di progetto per\u00a0<strong>sensibilizzare i genitori sulle loro responsabilit\u00e0<\/strong>\u00a0e sulle conseguenze dei loro comportamenti. Il\u00a0<strong>lavoro sinergico<\/strong> ha portato a un graduale miglioramento del contesto familiare: i bambini hanno smesso di passare il tempo in strada e hanno iniziato a sentirsi pi\u00f9 sicuri e fiduciosi all\u2019interno della famiglia.<\/p>\n<h3>L&#8217;intervento dell&#8217;assistente sociale<\/h3>\n<p>Nell\u2019anno scolastico 2024-2025, dopo la bocciatura in quarta elementare, Jojo \u00e8 stato trasferito in una scuola pi\u00f9 vicina a casa, frequentata anche da altri bambini del Centro SODAS e riconosciuta per la buona qualit\u00e0 dell\u2019insegnamento. Nonostante ci\u00f2, inizialmente sono riemersi comportamenti problematici. Per questo, fin dall\u2019inizio dell\u2019anno, l\u2019assistente sociale ha pianificato azioni mirate in collaborazione con la scuola: sono state individuate le lacune, assegnati compiti supplementari e creati\u00a0<strong>momenti di incoraggiamento durante le lezioni<\/strong>. Inoltre, Jojo ha iniziato a recarsi ogni giorno al\u00a0<strong>Centro SODAS<\/strong>\u00a0dopo la scuola per svolgere i compiti insieme agli altri bambini.<\/p>\n<h3>I risultati non hanno tardato ad arrivare<\/h3>\n<p>La proclamazione degli esiti del primo trimestre \u00e8 stata per Jojo un momento di grande gioia: con orgoglio, accompagnato dalla mamma, ha mostrato i suoi voti al coordinatore del Centro SODAS, dichiarando entusiasta: \u201cHo preso il 71,3%\u201d. Un gesto spontaneo che testimonia il suo impegno e il suo<strong>\u00a0rinnovato interesse per lo studio<\/strong>.<br \/>\nIl progetto di adozione a distanza ha contribuito in modo determinante a rafforzare l\u2019autostima di Jojo, permettendogli di credere nelle proprie capacit\u00e0 e di essere fiero dei risultati raggiunti, frutto di uno sforzo condiviso e di un sostegno costante.<\/p>\n<h3>Come partecipare al progetto \u201cSostieni a distanza i bambini di un orfanotrofio in Congo\u201d?<\/h3>\n<p>Nonostante la situazione difficilissima dovuta agli scontri che non si placano, Ai.Bi. Amici dei Bambini, continua a portare aiuto alle bambine e ai bambini vittime di abbandono, grazie al sostegno garantito dal progetto\u00a0\u201cSostieni a distanza i bambini di un orfanotrofio\u201d.<br \/>\nSe vuoi aiutare anche tu i 137 bambini degli orfanotrofi FED e SODAS di GOMA, puoi aderire al progetto. Riceverai periodiche informazioni su di loro e potrai seguire tutte le attivit\u00e0 che Ai.Bi. porta avanti per i bambini vittime di abbandono in Congo.<\/p>\n\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adotta-a-distanza-25\/?paese=Congo\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza ORA<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n\n<p><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Per richiedere informazioni sull\u2019Adozione a Distanza <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\" href=\"https:\/\/zimbra.teleposta.it\/#infosad\"><strong>clicca qui<\/strong><\/a><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">.<\/span><\/p>\n<p>E ricorda: come ogni donazione, anche le<strong>\u00a0Adozioni a Distanza di Ai.Bi.\u00a0<\/strong>godono delle seguenti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/images\/AGEVOLAZIONI_FISCALI.pdf\"><strong>agevolazioni fiscali<\/strong><\/a>.<br \/>\nAnche questo progetto fa parte della campagna\u00a0<strong>Emergenza Abbandono in Africa<\/strong>. Puoi fare\u00a0una donazione cliccando\u00a0<strong><a href=\"https:\/\/dona.aibi.it\/emergenza-congo\/\">qui<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grazie al sostegno garantito dal progetto&nbsp;&ldquo;Adotta a distanza i bambini di un orfanotrofio&rdquo;, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale<\/p>\n","protected":false},"author":133,"featured_media":235583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209],"tags":[671],"class_list":["post-235582","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-a-distanza","tag-sodas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.<\/title>\n<meta name=\"description\" content=\"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.\" \/>\n<meta property=\"og:description\" content=\"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-29T06:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T10:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antonio.rubinetti@aibi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antonio.rubinetti@aibi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/\"},\"author\":{\"name\":\"antonio.rubinetti@aibi.it\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\"},\"headline\":\"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.\",\"datePublished\":\"2026-01-29T06:30:50+00:00\",\"dateModified\":\"2026-01-29T10:15:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/\"},\"wordCount\":608,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/01\\\/rdc-sodas.jpg\",\"keywords\":[\"Sodas\"],\"articleSection\":[\"Adozione a Distanza\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/\",\"name\":\"Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/01\\\/rdc-sodas.jpg\",\"datePublished\":\"2026-01-29T06:30:50+00:00\",\"dateModified\":\"2026-01-29T10:15:35+00:00\",\"description\":\"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/01\\\/rdc-sodas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/01\\\/rdc-sodas.jpg\",\"width\":1200,\"height\":630,\"caption\":\"I bambini del centro Sodas in Congo, aiutati dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-jojo-progressi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/e921da992c7d79c8874aa1e558f181f2\",\"name\":\"antonio.rubinetti@aibi.it\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/antonio-rubinettiaibi-it\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.","description":"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/","og_locale":"it_IT","og_type":"article","og_title":"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.","og_description":"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale","og_url":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2026-01-29T06:30:50+00:00","article_modified_time":"2026-01-29T10:15:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg","type":"image\/jpeg"}],"author":"antonio.rubinetti@aibi.it","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"antonio.rubinetti@aibi.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/"},"author":{"name":"antonio.rubinetti@aibi.it","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2"},"headline":"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.","datePublished":"2026-01-29T06:30:50+00:00","dateModified":"2026-01-29T10:15:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/"},"wordCount":608,"commentCount":0,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg","keywords":["Sodas"],"articleSection":["Adozione a Distanza"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/","url":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/","name":"Congo. Dalla strada alla scuola: gli importanti progressi di Jojo.","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg","datePublished":"2026-01-29T06:30:50+00:00","dateModified":"2026-01-29T10:15:35+00:00","description":"Grazie al sostegno garantito dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d, Jojo sta vivendo un percorso di crescita significativo, soprattutto sul piano scolastico e personale","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/01\/rdc-sodas.jpg","width":1200,"height":630,"caption":"I bambini del centro Sodas in Congo, aiutati dal progetto\u00a0\u201cAdotta a distanza i bambini di un orfanotrofio\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-jojo-progressi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Repubblica Democratica del Congo. Dalla strada alla scuola: gli importanti progressi di Jojo."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/e921da992c7d79c8874aa1e558f181f2","name":"antonio.rubinetti@aibi.it","url":"https:\/\/www.aibi.it\/ita\/author\/antonio-rubinettiaibi-it\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:45:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/235582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=235582"}],"version-history":[{"count":2,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/235582\/revisions"}],"predecessor-version":[{"id":235587,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/235582\/revisions\/235587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/235583"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=235582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=235582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=235582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}