﻿


{"id":236266,"date":"2026-03-14T08:00:34","date_gmt":"2026-03-14T07:00:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=236266"},"modified":"2026-03-13T15:05:52","modified_gmt":"2026-03-13T14:05:52","slug":"aprirsi-accoglienza-proposte-aibi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/","title":{"rendered":"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini"},"content":{"rendered":"<h2>Nelle ultime due settimane di marzo Ai.Bi. Amici dei Bambini e la sua scuola di relazioni famialiri Faris propongono sette appuntamenti per conoscere l\u2019Adozione Internazionale, l\u2019Affido e per parlare di accoglienza di minori<\/h2>\n<p><!--more--><\/p>\n<h3>Marted\u00ec 17 marzo<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nIl primo incontro con l\u2019Affido familiare<br \/>\nOn Line<br \/>\nOre 21.00 \u2013 23.00<br \/>\nGratuito<br \/>\n<\/strong>Un incontro informativo per single, coppie o famiglie con figli interessati a conoscere e approfondire il tema dell\u2019affido familiare.<br \/>\nQuando una famiglia attraversa un momento di difficolt\u00e0 e non riesce a prendersi momentaneamente cura dei figli, i minori possono essere accolti per un periodo di tempo determinato in un\u2019altra famiglia, la famiglia accogliente. Chi pu\u00f2 fare affido? Che et\u00e0 bisogna avere? Quanto pu\u00f2 durare un affido? E che tipologie di affido esistono? Come funziona tutto il procedimento?<br \/>\nL\u2019incontro informativo \u00e8 condotto da una famiglia affidataria di Amici dei Bambini.<br \/>\nMaggiori informazioni <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-il-primo-incontro-con-laffido-familiare\/\">QUI<\/a><\/p>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nCORSO online di preidoneit\u00e0 all\u2019Adozione Internazionale<br \/>\nOn Line<br \/>\nOre 21.00 \u2013 23.00<br \/>\nGratuito<br \/>\n<\/strong>Il corso risponde all\u2019esigenza di preparare nel migliore dei modi gli aspiranti genitori adottivi all\u2019incontro con i loro figli. \u00c8 specificatamente pensato per coppie o single in procinto di depositare o che abbiano appena depositato la disponibilit\u00e0 all\u2019Adozione Internazionale presso il proprio Tribunale per i Minorenni di riferimento.<br \/>\nIl corso permetter\u00e0 alle persone, interessate ad adottare uno o pi\u00f9 minori stranieri, di approfondire i motivi per cui quelli che saranno i loro figli sono stati abbandonati una prima volta, dove vivono, quanti anni hanno, quali sono le loro patologie e come avviene un abbinamento. I nostri operatori, inoltre, ascolteranno le storie e il sogno che gli aspiranti genitori hanno sul \u201cloro\u201d bambino, accompagnandoli verso l\u2019incontro con lui attraverso la realt\u00e0 dell\u2019Adozione Internazionale.<br \/>\nIl corso si sviluppa in 5 moduli<br \/>\nMaggiori informazioni <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/corso-online-di-preidoneita-alladozione-internazionale\/\">QUI<\/a><\/p>\n<h3><strong>Mercoled\u00ec 18 marzo<\/strong><\/h3>\n<p><strong>Ai.Bi. sede di Bolzano<br \/>\nL\u2019incontro con l\u2019Adozione Internazionale (primo incontro informativo)<br \/>\nOn Line<br \/>\nOre 17.00<\/strong><br \/>\nAmici dei Bambini organizza incontri informativi di gruppo gratuiti, per le coppie che desiderano approfondire la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Gli incontri hanno una durata di 4 ore, sono condotti da un operatore di Ai.Bi. e prevedono la testimonianza di una famiglia adottiva. La partecipazione all\u2019incontro di entrambi i coniugi \u00e8 obbligatoria per le coppie che intendono conferire mandato ad Amici dei Bambini. Sono aperti alle coppie che hanno concluso il percorso con i Servizi o gi\u00e0 in possesso del decreto di idoneit\u00e0.<br \/>\nPer informazioni e iscrizioni: <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>QUI<\/strong><\/a>.<\/p>\n<h3>Sabato 21 marzo<\/h3>\n<p><strong>Progetto C.A.S.A.<br \/>\nOpen Day sull\u2019Accoglienza Familiare: Adozione e Affido<br \/>\nVia Cesare Battisti, 179 \u2013 Terni<br \/>\nOre 15.00<br \/>\n<\/strong>Un pomeriggio dedicato alla scoperta del mondo dell\u2019accoglienza familiare; un\u2019occasione per avvicinarsi all\u2019adozione e all\u2019affido scoprendo cosa vuol dire accogliere un bambino o un ragazzo all\u2019interno della propria vita e nel proprio percorso di crescita.<br \/>\nDurante l\u2019incontro verranno illustrate le principali differenze tra adozione e affido, i bisogni dei bambini, il ruolo delle famiglie e quello dei servizi che accompagnano questi percorsi. Sono previsti anche momenti esperienziali con attivit\u00e0 e laboratori pensati per riflettere su emozioni, timori e risorse di chi sceglie di accogliere.<br \/>\nL\u2019incontro sar\u00e0 tenuto da un\u2019esperta di Adozione Internazionale di Amici dei Bambini, con la partecipazione di una famiglia accogliente che porter\u00e0 la propria testimonianza.<\/p>\n<h3>Luned\u00ec 23 marzo<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nBambini da accogliere, chi e come? Aprirsi all\u2019accoglienza<br \/>\nOn Line<br \/>\nOre 18.00 \u2013 20.00<br \/>\nCosto: 10 euro<\/strong><br \/>\nUna serata per capire meglio chi sono i bambini in difficolt\u00e0 familiare oggi, nel mondo e in Italia.<br \/>\nIl webinar informativo vuole offrire uno squarcio sul mondo dei minori che vivono la necessit\u00e0 di essere accolti e, a seconda di diverse situazioni e bisogni, un approfondimento rispetto alle differenti modalit\u00e0 di accoglienza attraverso le quali \u00e8 possibile diventare riferimento per un bambino o una bambina.<br \/>\nAffido, Adozione nazionale, Adozione internazionale, sicuramente le modalit\u00e0 pi\u00f9 conosciute ma non solo, si pu\u00f2 diventare anche tutori per Minori Stranieri Non Accompagnati.<br \/>\nMaggiori informazioni <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-bambini-da-accogliere-chi-e-come-aprirsi-allaccoglienza\/\">QUI<\/a><\/p>\n<h3>Marted\u00ec 24 marzo<\/h3>\n<p><strong>FARIS \u2013 Family Relationship International School<br \/>\nPrimi passi nel mondo dell\u2019Adozione Internazionale<br \/>\nOn Line<br \/>\nOre 10.00<br \/>\nCosto: 20 euro<\/strong><br \/>\nIl webinar risponde all\u2019esigenza di dare alle coppie coniugate e i single che intendono avvicinarsi per la prima volta al mondo dell\u2019adozione internazionale le nozioni base sulla normativa di riferimento e le procedure da espletare, nonch\u00e9 sul significato stesso dell\u2019adozione.<br \/>\nL\u2019obiettivo \u00e8 dare ai partecipanti gli strumenti per presentare domanda di idoneit\u00e0 per diventare genitori adottivi sia a livello nazionale sia a livello internazionale.<br \/>\nIl webinar, partendo da un approfondimento della normativa di riferimento per l\u2019adozione, far\u00e0 conoscere \u00a0le procedure da espletare passo dopo passo, affrontando anche il ruolo degli enti autorizzati all\u2019adozione internazionale.<br \/>\nPer informazioni e iscrizioni: <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-primi-passi-nel-mondo-delladozione-internazionale-2\/\"><strong>QUI<\/strong><\/a>.<\/p>\n<h3>Mercoled\u00ec 25 marzo<\/h3>\n<p><strong>Ai.Bi. sede di Cagliari<br \/>\nL\u2019incontro con l\u2019Adozione Internazionale (primo incontro informativo)<br \/>\nOn Line<br \/>\nOre 20.00<\/strong><br \/>\nAmici dei Bambini organizza incontri informativi di gruppo gratuiti, per le coppie che desiderano approfondire la conoscenza dell\u2019adozione internazionale, dell\u2019associazione e delle procedure di adozione. Gli incontri hanno una durata di 4 ore, sono condotti da un operatore di Ai.Bi. e prevedono la testimonianza di una famiglia adottiva. La partecipazione all\u2019incontro di entrambi i coniugi \u00e8 obbligatoria per le coppie che intendono conferire mandato ad Amici dei Bambini.<br \/>\nQuesto incontro \u00e8 aperto solo a chi \u00e8 gi\u00e0 in possesso del decreto di idoneit\u00e0<br \/>\nPer informazioni e iscrizioni: <a href=\"https:\/\/www.fondazioneaibi.it\/faris\/prodotto\/webinar-informativo-su-come-aprire-una-casa-famiglia-per-minori\/\"><strong>QUI<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle ultime due settimane di marzo Ai.Bi. Amici dei Bambini e la sua scuola di relazioni famialiri Faris propongono sette appuntamenti per conoscere l&rsquo;Adozione Internazionale, l&rsquo;Affido e per parlare di accoglienza di minori<\/p>\n","protected":false},"author":102,"featured_media":236708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[764],"tags":[781,776,1011],"class_list":["post-236266","post","type-post","status-publish","format-standard","has-post-thumbnail","category-progetti-in-italia","tag-aibiweek","tag-faris","tag-progetti-in-italia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprirsi alla accoglienza. Ecco le proposte di Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini\" \/>\n<meta property=\"og:description\" content=\"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-14T07:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini\",\"datePublished\":\"2026-03-14T07:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/\"},\"wordCount\":902,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/03\\\/aibiweek-Adozione-e-affido-fine-marzo.jpg\",\"keywords\":[\"AIBIweek\",\"FARIS\",\"progetti in italia\"],\"articleSection\":[\"Progetti in Italia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/\",\"name\":\"Aprirsi alla accoglienza. Ecco le proposte di Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/03\\\/aibiweek-Adozione-e-affido-fine-marzo.jpg\",\"datePublished\":\"2026-03-14T07:00:34+00:00\",\"description\":\"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/03\\\/aibiweek-Adozione-e-affido-fine-marzo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/03\\\/aibiweek-Adozione-e-affido-fine-marzo.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/aprirsi-accoglienza-proposte-aibi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti in Italia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/progetti-in-italia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprirsi alla accoglienza. Ecco le proposte di Amici dei Bambini","description":"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/","og_locale":"it_IT","og_type":"article","og_title":"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini","og_description":"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido","og_url":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2026-03-14T07:00:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini","datePublished":"2026-03-14T07:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/"},"wordCount":902,"commentCount":0,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg","keywords":["AIBIweek","FARIS","progetti in italia"],"articleSection":["Progetti in Italia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/","url":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/","name":"Aprirsi alla accoglienza. Ecco le proposte di Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg","datePublished":"2026-03-14T07:00:34+00:00","description":"Nelle ultime settimane di marzo Ai.Bi. e Faris propongono diversi appuntamenti per informare coloro che vogliono aprirsi alla accoglienza con adozione e affido","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/aibiweek-Adozione-e-affido-fine-marzo.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/aprirsi-accoglienza-proposte-aibi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Progetti in Italia","item":"https:\/\/www.aibi.it\/ita\/category\/progetti-in-italia\/"},{"@type":"ListItem","position":3,"name":"AibiWeek. Come aprirsi alla accoglienza? Ecco 7 proposte di Amici dei Bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:40:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/236266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=236266"}],"version-history":[{"count":2,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/236266\/revisions"}],"predecessor-version":[{"id":236716,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/236266\/revisions\/236716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/236708"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=236266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=236266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=236266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}