﻿


{"id":237792,"date":"2026-05-13T08:00:59","date_gmt":"2026-05-13T06:00:59","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=237792"},"modified":"2026-05-12T19:25:22","modified_gmt":"2026-05-12T17:25:22","slug":"progetto-ghana-aibi-tutela-minori-reinserimento-familiare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/","title":{"rendered":"Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare"},"content":{"rendered":"<h2><strong>Finanziato dalla CAI (Commissione per le Adozioni Internazionali), il programma di cooperazione punta a contrastare l\u2019istituzionalizzazione e a supportare oltre 8.500 beneficiari attraverso il rafforzamento delle famiglie e delle reti di protezione sociale<\/strong><\/h2>\n<p><!--more--><\/p>\n<p>Ai.Bi. Amici dei Bambini ETS annuncia l&#8217;avvio in Ghana del progetto di cooperazione internazionale \u201cUn sistema che si prende cura: rafforzare l\u2019infanzia tra istituzioni e famiglie\u201d. L&#8217;iniziativa, finanziata dalla <strong>Commissione per le Adozioni Internazionali<\/strong> (CAI), nasce con il duplice obiettivo di promuovere il processo di de-istituzionalizzazione dei minori e di consolidare un sistema di protezione dell\u2019infanzia che metta al centro il ruolo fondamentale della famiglia.<br \/>\nIl progetto avr\u00e0 una durata di 18 mesi e si concentrer\u00e0 nelle aree sensibili della Greater Accra e della Regione Centrale. L&#8217;intervento vede<strong> Ai.Bi.<\/strong> nel ruolo di capofila, supportata da un solido partenariato con C.I.F.A. Centro Internazionale per l\u2019Infanzia e la Famiglia ETS e OAfrica.<\/p>\n<h3>Contrastare le cause dell&#8217;allontanamento minorile<\/h3>\n<p>Nonostante i recenti passi avanti del Ghana sul fronte dei diritti dell&#8217;infanzia, permangono gravi criticit\u00e0 sociali. Povert\u00e0 multidimensionale, lavoro minorile e disgregazione familiare continuano ad alimentare il fenomeno dell&#8217;istituzionalizzazione dei bambini, spesso legata a cause prevenibili come lo stigma o la disabilit\u00e0. In piena sinergia con il processo di riforma promosso dal governo ghanese, il <strong>progetto di Ai.Bi.<\/strong> mira a fornire soluzioni alternative, sostenendo la transizione verso un modello di cura familiare, capace di garantire ai minori un ambiente di sviluppo sicuro e stabile.<\/p>\n<h3>Le attivit\u00e0 previste<\/h3>\n<p>La strategia d&#8217;intervento si articola su pi\u00f9 livelli, coinvolgendo in modo diretto sia le istituzioni pubbliche che le famiglie e le strutture di accoglienza locali. Le attivit\u00e0 principali includono<\/p>\n<ul>\n<li><strong>Capacity building istituzionale:<\/strong>\u00a0formazione e aggiornamento tecnico per il Dipartimento per l\u2019Assistenza Sociale (DSW) e il Ministero per il Genere, i Bambini e la Protezione Sociale (MoGCSP).<\/li>\n<li><strong>Sostegno al reinserimento familiare:<\/strong>\u00a0fornitura di assistenza psico-sociale, legale e supporto pratico alle famiglie vulnerabili per agevolare il ritorno a casa dei minori.<\/li>\n<li><strong>Empowerment economico:<\/strong>\u00a0avvio di attivit\u00e0 generatrici di reddito e percorsi di mentoring per garantire l&#8217;autonomia finanziaria delle famiglie a rischio.<\/li>\n<li><strong>Riqualificazione dell&#8217;assistenza:<\/strong>\u00a0innalzamento degli standard qualitativi nelle strutture residenziali ancora operative.<\/li>\n<li><strong>Sensibilizzazione nazionale:<\/strong>\u00a0lancio di campagne mirate per promuovere l&#8217;affido familiare e prevenire l&#8217;abbandono.<\/li>\n<\/ul>\n<h3>Oltre 8.500 beneficiari per il diritto a crescere in famiglia<\/h3>\n<p>L&#8217;impatto atteso del progetto \u00e8 significativo, con oltre <strong>8.500 beneficiari diretti<\/strong> tra minori istituzionalizzati, genitori, caregiver, funzionari pubblici e operatori sociali. Il programma porter\u00e0 benefici concreti ai bambini vulnerabili attualmente ospitati in istituti come la Royal Seed Home, la Osu Children Home, la Accra High School e la Nyamedua Children\u2019s Home, prestando particolare attenzione ai minori con disabilit\u00e0.<br \/>\nAttraverso il potenziamento delle competenze tecniche e il miglioramento del coordinamento inter-istituzionale, Ai.Bi. e i partner di progetto si prefiggono di rafforzare l&#8217;intero sistema pubblico ghanese nella gestione dei casi di tutela minorile e nell&#8217;adozione nazionale. L&#8217;obiettivo finale \u00e8 garantire che ogni bambino veda rispettato il proprio diritto fondamentale: crescere all&#8217;interno di una famiglia accogliente e adeguata, superando definitivamente la logica dell&#8217;istituzionalizzazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finanziato dalla CAI (Commissione per le Adozioni Internazionali), il programma di cooperazione punta a contrastare l&rsquo;istituzionalizzazione e a supportare oltre 8.500 beneficiari attraverso il rafforzamento delle famiglie e delle reti di protezione sociale<\/p>\n","protected":false},"author":102,"featured_media":237797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[433,551,511],"class_list":["post-237792","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cooperazione-internazionale","tag-cai","tag-cooperazione-internazionale","tag-ghana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuovo progetto in Ghana di AiBi per la tutela dei minori e il reinserimento familiare<\/title>\n<meta name=\"description\" content=\"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo progetto Ai.Bi. in Ghana: al via l&#039;iniziativa per la tutela dei minori e il reinserimento familiare\" \/>\n<meta property=\"og:description\" content=\"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T06:00:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\"},\"headline\":\"Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare\",\"datePublished\":\"2026-05-13T06:00:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/\"},\"wordCount\":531,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/05\\\/progetto-in-Ghana-Aibi-CAI.jpg\",\"keywords\":[\"CAI\",\"cooperazione internazionale\",\"Ghana\"],\"articleSection\":[\"Cooperazione Internazionale\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/\",\"name\":\"Nuovo progetto in Ghana di AiBi per la tutela dei minori e il reinserimento familiare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/05\\\/progetto-in-Ghana-Aibi-CAI.jpg\",\"datePublished\":\"2026-05-13T06:00:59+00:00\",\"description\":\"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/05\\\/progetto-in-Ghana-Aibi-CAI.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2026\\\/05\\\/progetto-in-Ghana-Aibi-CAI.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/cooperazione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/26d3bda6f6e9386101a441c3040318c5\",\"name\":\"francescoE\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/francescoe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuovo progetto in Ghana di AiBi per la tutela dei minori e il reinserimento familiare","description":"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo progetto Ai.Bi. in Ghana: al via l'iniziativa per la tutela dei minori e il reinserimento familiare","og_description":"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie","og_url":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2026-05-13T06:00:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5"},"headline":"Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare","datePublished":"2026-05-13T06:00:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/"},"wordCount":531,"commentCount":0,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg","keywords":["CAI","cooperazione internazionale","Ghana"],"articleSection":["Cooperazione Internazionale"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/","url":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/","name":"Nuovo progetto in Ghana di AiBi per la tutela dei minori e il reinserimento familiare","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg","datePublished":"2026-05-13T06:00:59+00:00","description":"Ai.Bi. avvia un nuovo progetto in Ghana di cooperazione finanziato dalla CAI per la tutela dei minori, la de-istituzionalizzazione e il sostegno alle famiglie","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Cooperazione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/cooperazione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/26d3bda6f6e9386101a441c3040318c5","name":"francescoE","url":"https:\/\/www.aibi.it\/ita\/author\/francescoe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:56:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/237792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=237792"}],"version-history":[{"count":2,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/237792\/revisions"}],"predecessor-version":[{"id":237796,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/237792\/revisions\/237796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/237797"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=237792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=237792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=237792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}