﻿


{"id":24903,"date":"2011-08-29T16:59:05","date_gmt":"2011-08-29T15:59:05","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=24903"},"modified":"2011-08-29T17:00:49","modified_gmt":"2011-08-29T16:00:49","slug":"bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/","title":{"rendered":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi."},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-24904\" style=\"margin: 5px;\" title=\"bilancio 2010\" src=\"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/bilancio-2010-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>La redazione del bilancio di sostenibilit\u00e0 sta sempre pi\u00f9 diventando, almeno per le organizzazioni profit e non profit medie e grandi, un appuntamento annuale consueto.<\/p>\n<p><strong><strong>Amici dei Bambini da cinque anni a questa parte redige un bilancio di sostenibilit\u00e0 e di missione nel quale si rendiconta delle attivit\u00e0 svolte sull\u2019ambiente circostante e del perseguimento della missione. <\/strong><\/strong><\/p>\n<p>Il bilancio di sostenibilit\u00e0, infatti, d\u00e0 conto dei risultati economici, sociali e ambientali prodotti dall\u2019attivit\u00e0 dell\u2019organizzazione nell\u2019anno.<\/p>\n<p><strong><strong>Nel report 2010 abbiamo cercato di riportare il focus sui paesi in cui siamo presenti e sui progetti che l\u00ec realizziamo<\/strong><\/strong>, perch\u00e9 \u00e8 a nostro avviso fondamentale rendere conto dell\u2019impatto che i nostri progetti hanno sulle politiche per l\u2019infanzia in questi paesi. Proprio per questo motivo, tutti i nostri interventi vanno a comporsi <strong><strong>in un progetto paese complessivo. <\/strong><\/strong><\/p>\n<p><strong><strong>La parte relativa agli indicatori di performance \u00e8 cos\u00ec imperniata su schede paese<\/strong><\/strong>, ognuna delle quali \u00e8 composta da una relazione descrittiva degli interventi in corso e dei risultati ottenuti e dagli indicatori relativi al paese. Due schede sono poi dedicate ai progetti <strong>culturale e di advocacy<\/strong>, che sono per loro natura transnazionali.<\/p>\n<p><strong><strong>Dal punto di vista sociale, gli indicatori utilizzati valutano la capacit\u00e0 di assicurare una famiglia ai bambini che ne sono privi<\/strong><\/strong> <strong><strong>attraverso progetti di cooperazione<\/strong><\/strong> che assicurino l\u2019ingresso negli istituti, la collaborazione con le istituzioni locali, il ritorno in famiglia, biologica o adottiva, dei minori abbandonati nel modo pi\u00f9 certo e rapido possibile e un accompagnamento reale alla maggiore et\u00e0 per quelli non pi\u00f9 adottabili.<\/p>\n<p>Nella nostra esperienza, occupa un posto privilegiato in questo ambito <strong><strong>l\u2019adozione internazionale, che risulta quasi sempre la cartina di tornasole della reale volont\u00e0<\/strong><\/strong><\/p>\n<p><strong><strong>delle istituzioni pubbliche di combattere l\u2019abbandono. <\/strong><\/strong><\/p>\n<p>All\u2019interno del Bilancio di Sostenibilit\u00e0 ampio spazio \u00e8 stato dedicato anche alle aziende che nel corso del 2010 hanno sostenuto i progetti di Ai.Bi. e collaborato alla realizzazione di eventi.<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/ita\/chi-siamo\/bilancio\/\">Clicca qui <\/a>\u00a0per scaricare il file Pdf del Bilancio di Sostenibilit\u00e0 2010.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amici dei Bambini da cinque anni a questa parte redige <strong>un bilancio di sostenibilit\u00e0 e di missione<\/strong> nel quale si rendiconta delle attivit\u00e0 svolte <strong>sull\u2019ambiente circostante e del perseguimento della missione<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-24903","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"Amici dei Bambini da cinque anni a questa parte redige un bilancio di sostenibilit\u00e0 e di missione nel quale si rendiconta delle attivit\u00e0 svolte sull\u2019ambiente circostante e del perseguimento della missione. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-29T15:59:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-29T16:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.\",\"datePublished\":\"2011-08-29T15:59:05+00:00\",\"dateModified\":\"2011-08-29T16:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bilancio-2010.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/\",\"name\":\"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bilancio-2010.jpg\",\"datePublished\":\"2011-08-29T15:59:05+00:00\",\"dateModified\":\"2011-08-29T16:00:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bilancio-2010.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bilancio-2010.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/","og_locale":"it_IT","og_type":"article","og_title":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.","og_description":"Amici dei Bambini da cinque anni a questa parte redige un bilancio di sostenibilit\u00e0 e di missione nel quale si rendiconta delle attivit\u00e0 svolte sull\u2019ambiente circostante e del perseguimento della missione. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-08-29T15:59:05+00:00","article_modified_time":"2011-08-29T16:00:49+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi.","datePublished":"2011-08-29T15:59:05+00:00","dateModified":"2011-08-29T16:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/"},"wordCount":337,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/","url":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/","name":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg","datePublished":"2011-08-29T15:59:05+00:00","dateModified":"2011-08-29T16:00:49+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bilancio-2010.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bilancio-di-sostenibilita-2010-on-line-i-progetti-e-le-attivita-di-ai-bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Bilancio di Sostenibilit\u00e0 2010: on line i progetti e le attivit\u00e0 di Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:40:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/24903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=24903"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/24903\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=24903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=24903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=24903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}