﻿


{"id":24939,"date":"2011-08-31T13:41:29","date_gmt":"2011-08-31T12:41:29","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=24939"},"modified":"2011-08-31T13:48:44","modified_gmt":"2011-08-31T12:48:44","slug":"ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/","title":{"rendered":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-24421\" style=\"margin: 5px;\" title=\"cooperazione\" src=\"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/cooperazione4-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Ai.Bi., grazie all\u2019esperienza maturata in tanti anni di lavoro nella gestione dell\u2019accoglienza dei nuclei familiari con bambini, ha iniziato il suo sostegno a favore dei profughi provenienti dal nord Africa<\/strong> portando avanti un impegno, non solo di ospitalit\u00e0 ma di accoglienza, per garantire loro <strong>un\u2019educazione biculturale<\/strong> necessaria per crescere liberamente in un contesto lontano dalla propria terra d\u2019origine.<\/p>\n<p>Amici dei Bambini in collaborazione con l\u2019Azienda Sociale Sud Est Milano (A.S.S.E.M.I.), ha messo a loro disposizione delle vere proprie case in grado di offrire il calore di un ambiente familiare.<\/p>\n<p>Al momento sono quattro i nuclei familiari accolti, due di questi con minori, provenienti da Ghana, Eritrea, Sudan e Nigeria.<\/p>\n<p>A supporto delle famiglie, Ai.Bi. e gli altri Enti coinvolti, forniranno i seguenti beni e servizi: vestiario, prodotti per l\u2019igiene personale, generi di conforto. Inoltre, saranno disponibili nei prossimi mesi alcuni <strong>servizi di informazione e consulenza sulla normativa concernente l\u2019immigrazione e la condizione giuridica dello straniero per garantire un orientamento sulla procedura di riconoscimento della protezione internazionale in Italia, corsi di insegnamento della lingua italiana e servizi di mediazione linguistica &#8211; culturale per assicurare la corretta fruizione di tutti i servizi da parte dei beneficiari.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Ai.Bi., grazie all\u2019esperienza maturata in tanti anni di lavoro nella gestione dell\u2019accoglienza dei nuclei familiari con bambini, ha iniziato il suo sostegno a favore dei profughi provenienti dal nord Africa.<\/strong> <strong><a href=\"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%E2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-24939","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l\u2019accoglienza-delle-famiglie-profughe-dal-nord-africa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa\" \/>\n<meta property=\"og:description\" content=\"Ai.Bi., grazie all\u2019esperienza maturata in tanti anni di lavoro nella gestione dell\u2019accoglienza dei nuclei familiari con bambini, ha iniziato il suo sostegno a favore dei profughi provenienti dal nord Africa. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l\u2019accoglienza-delle-famiglie-profughe-dal-nord-africa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-31T12:41:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-31T12:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa\",\"datePublished\":\"2011-08-31T12:41:29+00:00\",\"dateModified\":\"2011-08-31T12:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cooperazione4.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/\",\"name\":\"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cooperazione4.jpg\",\"datePublished\":\"2011-08-31T12:41:29+00:00\",\"dateModified\":\"2011-08-31T12:48:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cooperazione4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/cooperazione4.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l\u2019accoglienza-delle-famiglie-profughe-dal-nord-africa\/","og_locale":"it_IT","og_type":"article","og_title":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa","og_description":"Ai.Bi., grazie all\u2019esperienza maturata in tanti anni di lavoro nella gestione dell\u2019accoglienza dei nuclei familiari con bambini, ha iniziato il suo sostegno a favore dei profughi provenienti dal nord Africa. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l\u2019accoglienza-delle-famiglie-profughe-dal-nord-africa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-08-31T12:41:29+00:00","article_modified_time":"2011-08-31T12:48:44+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa","datePublished":"2011-08-31T12:41:29+00:00","dateModified":"2011-08-31T12:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/"},"wordCount":222,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/","url":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/","name":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg","datePublished":"2011-08-31T12:41:29+00:00","dateModified":"2011-08-31T12:48:44+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/cooperazione4.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ai-bi-in-prima-linea-per-l%e2%80%99accoglienza-delle-famiglie-profughe-dal-nord-africa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Ai.Bi.: in prima linea per l\u2019accoglienza delle famiglie profughe dal nord Africa"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:40:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/24939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=24939"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/24939\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=24939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=24939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=24939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}