﻿


{"id":25047,"date":"2011-09-07T16:21:30","date_gmt":"2011-09-07T15:21:30","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=25047"},"modified":"2011-09-07T16:21:54","modified_gmt":"2011-09-07T15:21:54","slug":"bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/","title":{"rendered":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-24897\" style=\"margin: 5px;\" title=\"Adozioni bambini\" src=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Per la prima volta in Bielorussia \u00e8 stata recepita una sentenza italiana di adozione di un maggiorenne.<\/p>\n<p>In base alla sentenza un ragazzo bielorusso adottato da una famiglia Italiana ha ottenuto un nuovo atto di nascita, che gli permette di conservare la sua nazionalit\u00e0 bielorussa ma di avere contemporaneamente il cognome e dei genitori italiani.<\/p>\n<p>Lo ha reso noto l&#8217;Adoc, Associazione per i diritti degli utenti e consumatori,che ha seguito il caso.<\/p>\n<p><strong><em>&#8220;<\/em><\/strong><strong><em>Dal punto di vista del diritto internazionale privato<\/em><\/strong><em> <\/em>&#8211; ha spiegato l&#8217;avvocato Isabella Cusanno, legale Adoc,-<em> <\/em><strong><em>il recepimento della sentenza italiana da parte della Bielorussia ha permesso un&#8217;integrazione tra le normative dei due Paesi, che d\u00e0 la possibilit\u00e0 al ragazzo maggiorenne adottato di avere un cognome e dei genitori italiani, pur mantenendo la cittadinanza bielorussa, quindi di poter esercitare dei diritti su due nazioni con piena facolt\u00e0.<\/em><\/strong><\/p>\n<p><strong><em>E&#8217; stato raggiunto un risultato importante<\/em><\/strong><em> <\/em>&#8211; ha continuato Cusanno &#8211; i<strong><em>n quanto in Bielorussia per molto tempo \u00e8 stato negato il recepimento della normativa italiana,non permettendo \u00a0ai ragazzi maggiorenni adottati la possibilit\u00e0 di godere della titolarit\u00e0 dei diritti.<\/em><\/strong><\/p>\n<p><strong><em>Alla base di questa negazione vi era un equivoco di fondo-<\/em><\/strong> ha precisato il legale Adoc &#8211;\u00a0<strong><em>secondo cui un Paese che non ha una legislazione simile a quella italiana, vale a dire l&#8217;adozione a maggiorenni,non poteva adeguarsi alla nostra normativa. Una considerazione sbagliata in quanto il diritto internazionale prevede che il cittadino italiano agisca in base alle proprie leggi e non a quelle bielorusse, mentre il cittadino bielorusso pu\u00f2 accettare nell&#8217;ambito del diritto privato di essere tutelato da leggi diverse dalla sua se lo ritiene opportuno, quindi-<\/em><\/strong><em> <\/em>ha concluso Cusanno &#8211;\u00a0<strong><em>un&#8217;adozione a maggiorenne era pienamente lecita<\/em><\/strong>.&#8221;<\/p>\n<p>(<a title=\"blocked::http:\/\/www.justicetv.it\/index.php\/news\/838-bielorussiaadozioni-maggiorenni1-recepimento-sentenza-italiana\" href=\"http:\/\/www.justicetv.it\/index.php\/news\/838-bielorussiaadozioni-maggiorenni1-recepimento-sentenza-italiana\">http:\/\/www.justicetv.it\/index.php\/news\/838-bielorussiaadozioni-maggiorenni1-recepimento-sentenza-italiana<\/a>)<\/p>\n<p><strong> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la prima volta in Bielorussia \u00e8 stata recepita una sentenza italiana di adozione di un maggiorenne.\u00a0In base alla sentenza un ragazzo bielorusso adottato da una famiglia Italiana ha ottenuto un nuovo atto di nascita, che gli permette di conservare la sua nazionalit\u00e0 bielorussa ma di avere contemporaneamente il cognome e dei genitori italiani. <strong><a href=\"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%E2%80%99adozione-di-maggiorenni\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-25047","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l\u2019adozione-di-maggiorenni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni\" \/>\n<meta property=\"og:description\" content=\"Per la prima volta in Bielorussia \u00e8 stata recepita una sentenza italiana di adozione di un maggiorenne.\u00a0In base alla sentenza un ragazzo bielorusso adottato da una famiglia Italiana ha ottenuto un nuovo atto di nascita, che gli permette di conservare la sua nazionalit\u00e0 bielorussa ma di avere contemporaneamente il cognome e dei genitori italiani. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l\u2019adozione-di-maggiorenni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-07T15:21:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-09-07T15:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni\",\"datePublished\":\"2011-09-07T15:21:30+00:00\",\"dateModified\":\"2011-09-07T15:21:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-bambini1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/\",\"name\":\"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-bambini1.jpg\",\"datePublished\":\"2011-09-07T15:21:30+00:00\",\"dateModified\":\"2011-09-07T15:21:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-bambini1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-bambini1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l\u2019adozione-di-maggiorenni\/","og_locale":"it_IT","og_type":"article","og_title":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni","og_description":"Per la prima volta in Bielorussia \u00e8 stata recepita una sentenza italiana di adozione di un maggiorenne.\u00a0In base alla sentenza un ragazzo bielorusso adottato da una famiglia Italiana ha ottenuto un nuovo atto di nascita, che gli permette di conservare la sua nazionalit\u00e0 bielorussa ma di avere contemporaneamente il cognome e dei genitori italiani. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l\u2019adozione-di-maggiorenni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-09-07T15:21:30+00:00","article_modified_time":"2011-09-07T15:21:54+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni","datePublished":"2011-09-07T15:21:30+00:00","dateModified":"2011-09-07T15:21:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/"},"wordCount":305,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/","url":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/","name":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg","datePublished":"2011-09-07T15:21:30+00:00","dateModified":"2011-09-07T15:21:54+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-bambini1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bielorussia-primo-recepimento-della-sentenza-italiana-per-l%e2%80%99adozione-di-maggiorenni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Bielorussia: primo recepimento della sentenza italiana per l\u2019adozione di maggiorenni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:44:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/25047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=25047"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/25047\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=25047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=25047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=25047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}