﻿


{"id":25064,"date":"2011-09-08T14:23:12","date_gmt":"2011-09-08T13:23:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=25064"},"modified":"2011-09-09T09:54:36","modified_gmt":"2011-09-09T08:54:36","slug":"nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/","title":{"rendered":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-22464\" style=\"margin: 5px;\" title=\"nepal100x100\" src=\"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Un primo passo \u00e8 stato fatto per sbloccare la situazione delle adozioni dei bambini nepalesi: <strong>il Ministero delle Donne, dell&#8217;Infanzia e della Previdenza Sociale, l\u2019autorit\u00e0 centrale per le Adozioni Internazionali in Nepal, ha, infatti, pubblicato una lista di enti accreditati alla gestione delle pratiche di adozione.<\/strong><\/p>\n<p>Le Adozioni Internazionali in Nepal sono state bloccate a fine giugno 2010,  a causa di alcune violazioni dei diritti dei bambini e del non corretto adeguamento delle norme in materia di adozioni a quanto stabilito dalla Conferenza dell\u2019Aja. Sono invece ancora in corso gli iter adottivi depositati prima della sospensione.<\/p>\n<p>A seguito degli inviti rivolti dal Permament Bureau della Conferenza dell\u2019Aja, il Governo ha per\u00f2 cominciato a elaborare le necessarie modifiche alle leggi riguardanti la tutela dei bambini nel Paese\u00a0al fine di favorire l\u2019adozione internazionale dei bambini nepalesi. Tali modifiche sono state fatte\u00a0tenendo in considerazione le conclusioni emerse durante l\u2019incontro che si \u00e8 svolto il 31 marzo e 1\u00b0aprile a Roma\u00a0tra i rappresentanti di alcuni stati europei, gli Stati Uniti, il Canada, il Segretariato dell\u2019Aja e i rappresentanti del governo del Nepal. Durante l\u2019incontro, i Paesi di accoglienza\u00a0hanno assicurato al Ministero nepalese la volont\u00e0 di valutare interventi di supporto; <strong>\u00e8 stata comunque confermata la decisione di mantenere la sospensione del deposito di nuovi fascicoli,\u00a0finch\u00e9 il Nepal non avr\u00e0 raggiunto standard normativi\u00a0e operativi conformi al \u201csistema Aja\u201d.<\/strong><\/p>\n<p>La pubblicazione da parte del Ministero di una lista di enti accreditati \u00e8 dunque un incoraggiante primo passo verso la riapertura delle adozioni internazionali. Gli enti che hanno ricevuto l\u2019autorizzazione ad operare in Nepal sono in tutto 36, di cui otto italiani: Ai.Bi., AIPA Erga Pueros, International Adoption Net, Associazione Ariete Onlus, Associazioni Amici Trentini, L\u2019Airone Onlus, NAA, AMPAS Associazione Nazionale Pubbliche assistenze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un primo passo \u00e8 stato fatto per sbloccare la situazione delle adozioni dei bambini nepalesi:\u00a0<strong>il Ministero delle Donne, dell&#8217;Infanzia e della Previdenza Sociale, l\u2019autorit\u00e0 centrale per le Adozioni Internazionali in Nepal, ha, infatti, pubblicato una lista di enti accreditati alla gestione delle pratiche di adozione. <a href=\"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-25064","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nepal: primo passo verso la riapertura delle Adozioni Internazionali - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nepal: primo passo verso la riapertura delle Adozioni Internazionali\" \/>\n<meta property=\"og:description\" content=\"Un primo passo \u00e8 stato fatto per sbloccare la situazione delle adozioni dei bambini nepalesi:\u00a0il Ministero delle Donne, dell&#039;Infanzia e della Previdenza Sociale, l\u2019autorit\u00e0 centrale per le Adozioni Internazionali in Nepal, ha, infatti, pubblicato una lista di enti accreditati alla gestione delle pratiche di adozione. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-08T13:23:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-09-09T08:54:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Nepal: primo passo verso la riapertura delle Adozioni Internazionali\",\"datePublished\":\"2011-09-08T13:23:12+00:00\",\"dateModified\":\"2011-09-09T08:54:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/\"},\"wordCount\":304,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal100x1005.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/\",\"name\":\"Nepal: primo passo verso la riapertura delle Adozioni Internazionali - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal100x1005.jpg\",\"datePublished\":\"2011-09-08T13:23:12+00:00\",\"dateModified\":\"2011-09-09T08:54:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal100x1005.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/nepal100x1005.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nepal: primo passo verso la riapertura delle Adozioni Internazionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/","og_locale":"it_IT","og_type":"article","og_title":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali","og_description":"Un primo passo \u00e8 stato fatto per sbloccare la situazione delle adozioni dei bambini nepalesi:\u00a0il Ministero delle Donne, dell'Infanzia e della Previdenza Sociale, l\u2019autorit\u00e0 centrale per le Adozioni Internazionali in Nepal, ha, infatti, pubblicato una lista di enti accreditati alla gestione delle pratiche di adozione. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-09-08T13:23:12+00:00","article_modified_time":"2011-09-09T08:54:36+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali","datePublished":"2011-09-08T13:23:12+00:00","dateModified":"2011-09-09T08:54:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/"},"wordCount":304,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/","url":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/","name":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg","datePublished":"2011-09-08T13:23:12+00:00","dateModified":"2011-09-09T08:54:36+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/nepal100x1005.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/nepal-primo-passo-verso-la-riapertura-delle-adozioni-internazionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Nepal: primo passo verso la riapertura delle Adozioni Internazionali"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:43:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/25064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=25064"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/25064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=25064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=25064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=25064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}