﻿


{"id":27422,"date":"2011-11-25T11:05:39","date_gmt":"2011-11-25T10:05:39","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=27422"},"modified":"2011-11-25T11:10:55","modified_gmt":"2011-11-25T10:10:55","slug":"roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/","title":{"rendered":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-27425\" style=\"margin: 5px;\" title=\"Convegno Familiaris Consortio\" src=\"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Da un percorso condiviso tra l\u2019<strong>Ufficio<\/strong> <strong>Nazionale della CEI per la Pastorale Familiare<\/strong>, il <strong>Pontificio Istituto Giovanni Paolo II<\/strong> e il <strong>Forum delle Associazioni Familiari<\/strong>, \u00e8 nato il Convegno di studi che <strong>a Roma<\/strong>,<strong> da oggi a domenica 27 novembre<\/strong> presso la Domus Pacis, apre i lavori di ricerca sulla famiglia e sull\u2019analisi degli strumenti adatti a sostenerla &#8211; sia nel suo ruolo di educatrice e testimone del valore-uomo, sia nella sua soggettivit\u00e0 ecclesiale -, in vista di approfondire gli orientamenti pastorali della CEI nel prossimo decennio.<\/p>\n<p style=\"text-align: justify;\"><strong>Un evento di primaria importanza<\/strong>, nel panorama della pastorale familiare: confortato inoltre dalla celebrazione del 30mo anniversario dell\u2019<strong>esortazione<\/strong> <strong>apostolica<\/strong> <strong><em>Familiaris Consortio<\/em><\/strong>, uno dei pi\u00f9 importanti documenti voluti da Giovanni Paolo II durante gli anni del suo mandato, a edificazione e a nutrimento degli studi sulla famiglia.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>L\u2019avvenire dell\u2019umanit\u00e0 passa attraverso la famiglia<\/em>\u00bb: \u00e8 proprio la figura di <strong>Karol<\/strong> <strong>Woytila<\/strong>, ancora forte della sua pregnanza di guida spirituale, a ispirare la prima giornata di lavori nel segno de <strong><em>La fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI<\/em><\/strong>. Per le 14:30 di oggi pomeriggio \u00e8 previsto l\u2019arrivo dei partecipanti; di seguito, \u00e8 attesa l\u2019inaugurazione dei lavori alle 15:30 e la lettura del messaggio di Benedetto XVI, con l\u2019avvio di una prima sessione di interventi su <strong><em>Identit\u00e0 e differenza: teologia del corpo e teologia dell\u2019amore, linee di complementarit\u00e0<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\">Domani, <strong>sabato 26 novembre<\/strong>, dalle 8:30 alle 19:30 i lavori proseguiranno sotto la presidenza di S.E. Mons. Enrico <strong>Solmi<\/strong>. \u00c8 previsto l\u2019intervento, per le 15:00, dei coniugi\u00a0<strong>Maria Teresa e Sergio Bertoldo<\/strong>, membri di\u00a0Ai.Bi.\u00a0Amici dei Bambini\u00a0e de\u00a0La Pietra Scartata, l\u2019associazione di famiglie che custodisce il carisma dell&#8217;accoglienza adottiva e affidataria e propone una spiritualit\u00e0 dell&#8217;accoglienza familiare. La famiglia Bertoldo proporr\u00e0 un intervento sul tema \u00ab<strong>La fecondit\u00e0 oltre la sterilit\u00e0: percorsi di accoglienza<\/strong>\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Domenica 27<\/strong> il Convegno culminer\u00e0 con il tema <strong><em>La famiglia, anima della societ\u00e0: per uno sviluppo sostenibile<\/em><\/strong>. Alle 12:00, l\u2019Eucarestia celebrata da S.E. Mons. Mariano Crociata chiuder\u00e0 la tre-giorni di incontro.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Da un percorso condiviso tra l\u2019<strong>Ufficio<\/strong> <strong>Nazionale della CEI per la Pastorale Familiare<\/strong>, il <strong>Pontificio Istituto Giovanni Paolo II<\/strong> e il <strong>Forum delle Associazioni Familiari<\/strong>, \u00e8 nato il Convegno di studi che <strong>a Roma<\/strong>,<strong> da oggi a domenica 27 novembre<\/strong> presso la Domus Pacis, apre i lavori di ricerca sulla famiglia, in vista di approfondire gli orientamenti pastorali della CEI nel prossimo decennio. <strong><a href=\"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-27422","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/roma-\u00abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi\u00bb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb\" \/>\n<meta property=\"og:description\" content=\"Da un percorso condiviso tra l\u2019Ufficio Nazionale della CEI per la Pastorale Familiare, il Pontificio Istituto Giovanni Paolo II e il Forum delle Associazioni Familiari, \u00e8 nato il Convegno di studi che a Roma, da oggi a domenica 27 novembre presso la Domus Pacis, apre i lavori di ricerca sulla famiglia, in vista di approfondire gli orientamenti pastorali della CEI nel prossimo decennio. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/roma-\u00abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi\u00bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-25T10:05:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-11-25T10:10:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb\",\"datePublished\":\"2011-11-25T10:05:39+00:00\",\"dateModified\":\"2011-11-25T10:10:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/\"},\"wordCount\":348,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Convegno-Familiaris-Consortio.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/\",\"name\":\"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Convegno-Familiaris-Consortio.jpg\",\"datePublished\":\"2011-11-25T10:05:39+00:00\",\"dateModified\":\"2011-11-25T10:10:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Convegno-Familiaris-Consortio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Convegno-Familiaris-Consortio.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/roma-\u00abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi\u00bb\/","og_locale":"it_IT","og_type":"article","og_title":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb","og_description":"Da un percorso condiviso tra l\u2019Ufficio Nazionale della CEI per la Pastorale Familiare, il Pontificio Istituto Giovanni Paolo II e il Forum delle Associazioni Familiari, \u00e8 nato il Convegno di studi che a Roma, da oggi a domenica 27 novembre presso la Domus Pacis, apre i lavori di ricerca sulla famiglia, in vista di approfondire gli orientamenti pastorali della CEI nel prossimo decennio. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/roma-\u00abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi\u00bb\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-11-25T10:05:39+00:00","article_modified_time":"2011-11-25T10:10:55+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb","datePublished":"2011-11-25T10:05:39+00:00","dateModified":"2011-11-25T10:10:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/"},"wordCount":348,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/","url":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/","name":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg","datePublished":"2011-11-25T10:05:39+00:00","dateModified":"2011-11-25T10:10:55+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Convegno-Familiaris-Consortio.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/roma-%c2%abla-fecondita-di-familiaris-consortio-da-giovanni-paolo-ii-a-benedetto-xvi%c2%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Roma: \u00abLa fecondit\u00e0 di Familiaris Consortio: da Giovanni Paolo II a Benedetto XVI\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:12:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/27422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=27422"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/27422\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=27422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=27422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=27422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}