﻿


{"id":27978,"date":"2011-12-12T14:50:04","date_gmt":"2011-12-12T13:50:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=27978"},"modified":"2011-12-12T17:04:04","modified_gmt":"2011-12-12T16:04:04","slug":"adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/","title":{"rendered":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-27986\" style=\"margin: 5px;\" title=\"Adozioni in Bielorussia\" src=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Riceviamo e volentieri pubblichiamo una Lettera, contenente l\u2019appello alla riapertura delle adozioni in Bielorussia. <\/strong>\u00abSe condividete lo spirito della lettera &#8211; scrive il Coordinamento delle Famiglie Adottanti in Bielorussia -,\u00a0Vi invitiamo ad inviare al mondo politico e al Governo l\u2019invito a continuare su quella strada di dialogo con le istituzioni bielorusse che, in questi anni, ha portato tanti frutti alla causa a noi comune, al fine di individuare nel pieno rispetto del minore nuove forme di solidariet\u00e0 tra popoli\u00bb.<\/p>\n<blockquote>\n<h3 style=\"text-align: justify;\">Lettera alle Istituzioni su adozioni e permessi studio, 23 novembre 2011<\/h3>\n<p style=\"text-align: justify;\"><strong>Al Presidente del Consiglio<br \/>\n<\/strong>Prof. Mario Monti<\/p>\n<p style=\"text-align: justify;\"><strong>Al Ministro degli Esteri<br \/>\n<\/strong>Giulio Terzi di Sant&#8217;Agata<\/p>\n<p style=\"text-align: justify;\"><strong>Al Ministro della Cooperazione<br \/>\n<\/strong>Andrea Riccardi<\/p>\n<p style=\"text-align: justify;\">A tutti i Senatori<br \/>\nA tutti i Deputati<\/p>\n<p style=\"text-align: justify;\">Chi Le scrive \u00e8 una famiglia, legata a vario titolo all\u2019esperienza di accoglienza dei minori bielorussi.<\/p>\n<p style=\"text-align: justify;\">Il fenomeno umanitario delle accoglienze di bambini bielorussi &#8211; di cui sono motore famiglie italiane, di qualsiasi estrazione sociale e colore politico &#8211; \u00e8 unico al mondo, ed \u00e8 ben sotto gli occhi e i riflettori dell\u2019opinione pubblica italiana.<\/p>\n<p style=\"text-align: justify;\">L\u2019azione di cooperazione delle famiglie italiane \u00e8 diffusa capillarmente nel paese e molti altri cittadini italiani vengono, ogni anno, a contatto con questi bambini e \u201cragazzi di Chernobyl\u201d, perfettamente integrati nella realt\u00e0 italiana.<\/p>\n<p style=\"text-align: justify;\"><strong>Questo \u00e8 un momento cruciale per il destino di moltissimi bambini bielorussi, che attendono, spesso da molti anni, di sentirsi chiamare finalmente figli: perch\u00e9 la Bielorussia ha dimostrato nei fatti &#8211; con il riesame, a partire dal 2010, di oltre 500 pratiche adottive in sospeso &#8211; la sua volont\u00e0 di riaprire le adozioni. Tant\u2019\u00e8 che gi\u00e0 nel 2010 (da statistiche CAI) sono stati adottati 99 minori, e altrettante adozioni sono state completate nei primi sei mesi del 2011. <\/strong>Questo dato non pu\u00f2 essere ignorato dalla Commissione Adozioni Internazionali, che, invece (come da comunicato del 22 marzo 2011), ritiene ancora di bloccare il deposito delle nuove domande di adozione.<\/p>\n<p style=\"text-align: justify;\">Anche per i bambini non adottabili registriamo un traguardo importantissimo, con la firma del protocollo d\u2019intesa sui permessi studio, risalente al 10 giugno 2011, e che attende solo i decreti attuativi, per permettere a minori bielorussi di almeno 14 anni l\u2019accesso alla scuola italiana. Sappiamo che le nostre istituzioni stanno lavorando molto in questa direzione, gettando le basi per solidi scambi culturali, economici non solo con la Bielorussia, ma con tutti i paesi di lingua russa, e speriamo che l\u2019attenzione su questo tema non venga mai a mancare, perch\u00e9 la vicenda delle adozioni, delle accoglienze e quello dei permessi studio nei confronti dell\u2019infanzia Bielorussa dimostra che un paese non pu\u00f2 prescindere, anche nei momenti di crisi, dagli aspetti umanitari.<\/p>\n<p style=\"text-align: justify;\">Il rispetto di consolidati rapporti umanitari rappresenta la cartina di tornasole della seriet\u00e0 di un paese, su cui costruire serie basi della cooperazione sociale e della collaborazione economica tra due stati.<\/p>\n<p style=\"text-align: justify;\">Per questo, intendiamo con la presente supportare le proposte del Coordinamento delle Famiglie Adottanti in Bielorussia (<a title=\"blocked::http:\/\/www.adozionibielorussia.org\/\" href=\"http:\/\/www.adozionibielorussia.org\/\">www.adozionibielorussia.org<\/a>), movimento di famiglie non solo adottanti, che ha registrato un\u2019incredibile partecipazione di persone che, a vario titolo, sono legate alle vicende bielorusse.<\/p>\n<p style=\"text-align: justify;\">In questi ultimi anni, in questa vicenda si \u00e8 evidenziato un problema di fondo della politica internazionale del nostro paese, poco attenta alle adozioni internazionali, nonostante \u201cil boom\u201d delle\u00a0 stesse, registrato dalla Commissione Adozioni Internazionali, sostanziandosi di fatto nella negazione all\u2019avviare pratiche di adozione per decine di migliaia di famiglie italiane, con decreto di idoneit\u00e0 gi\u00e0 ottenuto e in attesa di aprire la propria famiglia all\u2019affetto di un minore.<\/p>\n<p style=\"text-align: justify;\"><strong>La riforma, avviata nella passata legislatura dal Governo Italiano, non \u00e8 completa, per due ordini di motivi<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>La politica delle adozioni internazionali deve in primo luogo essere supportata dalle nostre ambasciate e consolati nel mondo<\/strong> e non vissuta come un problema e con superficiale sufficienza.<\/p>\n<p style=\"text-align: justify;\">A tal fine \u00e8 auspicabile la migrazione della Commissione delle Adozioni Internazionali, sotto l\u2019egida del Ministero degli Affari Esteri, piuttosto che in una posizione di ripiego, laddove il ministro o\u00a0 sottosegretario di turno si occupa \u201ca tempo perso\u201d della questione.<\/p>\n<p style=\"text-align: justify;\">Riteniamo inoltre auspicabile una profonda riforma della Commissione delle Adozioni Internazionali, volta non solo a rappresentare un mero organo di controllo degli Enti per le adozioni internazionali, ma anche a sostenere il processo di espansione delle adozioni, viste le sempre maggiori richieste di adozione da parte di coppie italiane. Tale azione raggiungerebbe il duplice obiettivo di efficacia ed efficienza, derivante dal porre sotto la medesima guida del Ministro degli Esteri sia la CAI sia il braccio operativo delle ambasciate, rappresentanti dello Stato Italiano nel mondo.<\/p>\n<p style=\"text-align: justify;\">La preparazione e soprattutto il coinvolgimento del personale del Ministero degli Esteri diventa drammaticamente importante, soprattutto in paesi quali la Bielorussia, dove l\u2019avvicinamento all\u2019Unione Europea evolve grazie anche all\u2019incontro delle nuove generazioni con la nostra cultura.<\/p>\n<p style=\"text-align: justify;\">L\u2019iniziativa di promozione deve essere frutto non solo del Governo Italiano a livello centrale ma anche attraverso i propri ambasciatori. \u00c8 forse anche grazie a venti anni di rapporti tra le famiglie italiane e la societ\u00e0 bielorussa, che la politica italiana ha potuto far muovere i primi passi verso l\u2019Europa alle autorit\u00e0 di quel Paese.<\/p>\n<p style=\"text-align: justify;\">Il supporto delle Ambasciate \u00e8 ancora pi\u00f9 importante nei paesi con i quali si stringono rapporti di cooperazione basati sull\u2019accoglienza, non per scavalcare il meccanismo internazionale dell\u2019adozione internazionale, ma quanto per garantire \u201cil supremo interesse del minore\u201d ad avere una famiglia propria.<\/p>\n<p style=\"text-align: justify;\"><strong>Il secondo aspetto<\/strong> \u00e8 quello legato ai diritti dei minori in difficolt\u00e0, che, attraverso i soggiorni di risanamento, hanno la possibilit\u00e0 di incontrare l\u2019affetto e l\u2019amore che ci contraddistingue come popolo accogliente.<\/p>\n<p style=\"text-align: justify;\">Le esperienze si evolvono e gli stati e le leggi devono disciplinare e contemplare le evoluzioni della realt\u00e0, soprattutto in un contesto cos\u00ec delicato quale quello della tutela dei minori, come nel caso dei permessi studio<strong>. Per questo chiediamo di giungere rapidamente ad una attuazione dell\u2019accordo firmato dal ministro Frattini, in data 10 giugno 2011.<\/strong><\/p>\n<p style=\"text-align: justify;\">Il boom delle adozioni dimostra la grande disponibilit\u00e0 delle coppie italiane all\u2019adozione, che, in numero ben superiore alla media di 4000 unit\u00e0, attendono 4-5 anni per giungere all\u2019adozione di un minore.\u00a0 Tra quelle in attesa, ci sono le famiglie adottanti in Bielorussia, che hanno un legame ben identificato con un minore che, il pi\u00f9 delle volte, ha espresso la volont\u00e0 chiara di essere adottato da una famiglia identificata.<\/p>\n<p style=\"text-align: justify;\">Vi rivolgiamo pertanto un appello, affinch\u00e9 si prosegua senza esitazioni lungo la strada gi\u00e0 aperta dal ministro Frattini e dal sottosegretario Gianni Letta in questi ultimi anni, volta a non considerare un nemico la parte bielorussa. In questo ambito troverete l\u2019appoggio e il consenso di tantissime famiglie italiane.<\/p>\n<p style=\"text-align: justify;\"><strong>Infine, intendiamo sottoporre all\u2019attenzione del mondo politico e del Governo<\/strong> <strong>la richiesta di rivedere la legislazione in materia di diritto di cittadinanza per i maggiorenni adottati da famiglie italiane<\/strong>, consentendone l\u2019acquisizione contestuale alla sentenza di adozione. Senza dilungarsi in tecnicismi riassumibili con estrema difficolt\u00e0, allo stato attuale le conseguenze giuridiche producono effetti paradossali, sia per quanto riguarda l\u2019acquisizione del cognome italiano da parte del maggiorenne extracomunitario, che per quanto riguarda l\u2019acquisizione di diritti prettamente limitati alla sfera patrimoniale.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Invitiamo a prendere visione del sito <a title=\"blocked::http:\/\/www.adozionibielorussia.org\/index.html\" href=\"http:\/\/www.adozionibielorussia.org\/index.html\">Adozioni in Bielorussia<\/a>. Visitando <a title=\"blocked::http:\/\/www.adozionibielorussia.org\/documenti\/208letteraappelloadozioni19112011.htm\" href=\"http:\/\/www.adozionibielorussia.org\/documenti\/208letteraappelloadozioni19112011.htm\">la pagina dedicata all\u2019appello<\/a>, \u00e8 possibile seguire le istruzioni per firmare la lettera e contribuire allo sblocco della situazione.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\"><strong>Pubblichiamo una Lettera<\/strong>, contenente l\u2019appello alla riapertura delle adozioni internazionali dalla Bielorussia. \u00abSe condividete lo spirito della lettera &#8211; scrive il Coordinamento delle Famiglie Adottanti in Bielorussia -,\u00a0vi invitiamo ad inviare\u00a0al Governo l\u2019invito a continuare su quella strada di dialogo con le istituzioni bielorusse, al fine di <strong>individuare nuove forme di solidariet\u00e0 tra popoli<\/strong>\u00bb. <strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-27978","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi\" \/>\n<meta property=\"og:description\" content=\"Pubblichiamo una Lettera, contenente l\u2019appello alla riapertura delle adozioni internazionali dalla Bielorussia. \u00abSe condividete lo spirito della lettera - scrive il Coordinamento delle Famiglie Adottanti in Bielorussia -,\u00a0vi invitiamo ad inviare\u00a0al Governo l\u2019invito a continuare su quella strada di dialogo con le istituzioni bielorusse, al fine di individuare nuove forme di solidariet\u00e0 tra popoli\u00bb. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-12T13:50:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-12T16:04:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi\",\"datePublished\":\"2011-12-12T13:50:04+00:00\",\"dateModified\":\"2011-12-12T16:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/\"},\"wordCount\":1202,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-in-Bielorussia.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/\",\"name\":\"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-in-Bielorussia.jpg\",\"datePublished\":\"2011-12-12T13:50:04+00:00\",\"dateModified\":\"2011-12-12T16:04:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-in-Bielorussia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozioni-in-Bielorussia.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi","og_description":"Pubblichiamo una Lettera, contenente l\u2019appello alla riapertura delle adozioni internazionali dalla Bielorussia. \u00abSe condividete lo spirito della lettera - scrive il Coordinamento delle Famiglie Adottanti in Bielorussia -,\u00a0vi invitiamo ad inviare\u00a0al Governo l\u2019invito a continuare su quella strada di dialogo con le istituzioni bielorusse, al fine di individuare nuove forme di solidariet\u00e0 tra popoli\u00bb. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-12-12T13:50:04+00:00","article_modified_time":"2011-12-12T16:04:04+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi","datePublished":"2011-12-12T13:50:04+00:00","dateModified":"2011-12-12T16:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/"},"wordCount":1202,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/","name":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg","datePublished":"2011-12-12T13:50:04+00:00","dateModified":"2011-12-12T16:04:04+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozioni-in-Bielorussia.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-sblocchiamo-il-destino-dei-bambini-bielorussi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Internazionali: sblocchiamo il destino dei bambini bielorussi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:14:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/27978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=27978"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/27978\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=27978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=27978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=27978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}