﻿


{"id":28065,"date":"2011-12-27T15:13:51","date_gmt":"2011-12-27T14:13:51","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=28065"},"modified":"2011-12-27T16:15:11","modified_gmt":"2011-12-27T15:15:11","slug":"reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/","title":{"rendered":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28416\" style=\"margin: 5px;\" title=\"Brasile non solo spiagge e samba\" src=\"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>BAHIA \u2013 \u00ab<strong>Caldo, aria secca, 40 gradi all\u2019ombra, il pulmino si ferma in una piazza semideserta, c&#8217;\u00e8 solo il rumore del vento, ma dove cavolo siamo?<\/strong>\u00bb.<\/p>\n<p style=\"text-align: justify;\">In Brasile, con i giovani occhi della solidariet\u00e0. L\u2019incipit tra virgolette \u00e8 di Letizia, 26 enne di Torino. \u00c8 partita con altri nove giovani il 16 novembre scorso, alla volta di Salvador de Bahia, per addestrarsi in un progetto di solidariet\u00e0 e cooperazione tra Italia e Brasile. Ecco come prosegue il reportage della loro avventura formativa.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Jacun\u00e0, regione Sertaneja di Bahia, ore 10<\/strong>. Le porte della chiesa, unico edificio riconoscibile nella piazza, si aprono ed eccoli l\u00ec, <strong><strong>tutti i bambini del paese venuti ad accoglierci<\/strong><\/strong>. Il benvenuto ce lo danno a suon di canzoni e ballate, un repertorio che va dall&#8217;inno del Brasile alla struggente melodia del Titanic (un <em><em>evergreen<\/em><\/em>): di fronte a tale manifestazione non vogliamo certo essere da meno, improvvisiamo quindi &#8220;Bella Ciao&#8221; che, da qui in poi, sar\u00e0 il nostro biglietto da visita.<\/p>\n<p style=\"text-align: justify;\">\u00abSolo qualche ora dopo, gi\u00e0 gironzoliamo nella comunit\u00e0 di Jacun\u00e0; c&#8217;\u00e8 chi tenta di pescare nello stagno dietro casa, chi prova (ma non riesce) a cavalcare un asino, chi cerca disperatamente una chitarra e chi si orienta tra le strade sterrate, lo sterco, le mandrie di mucche, tutti noi rigorosamente seguiti da sciami di bambine e bambini incuriositi e affettuosi.<\/p>\n<p style=\"text-align: justify;\">\u00abQui il tempo \u00e8 scandito dall\u2019attivit\u00e0 nei campi, dalla pioggia (rara) e dal <strong><strong>meticoloso intreccio della paglia<\/strong><\/strong>. In questa terra arida infatti, un tempo ricoperta di campi di paglia, la vita delle famiglie e delle comunit\u00e0 locali girava intorno ad essa: dal raccolto (attivit\u00e0 <strong>per gli<\/strong> <strong><strong>uomini<\/strong><\/strong>), alla seccatura al sole, alla lavorazione per farne principalmente cappelli, tappeti e scope, ma anche borse e altri oggetti.<\/p>\n<p style=\"text-align: justify;\">\u00abIncontriamo un <strong><strong>gruppo di donne<\/strong><\/strong> \u201c<strong><strong>Associa\u00e7<\/strong><\/strong><strong>\u00e3<strong><strong>o de Artes<\/strong><\/strong>\u00e3<strong><strong>os de palha<\/strong><\/strong><\/strong>\u201d che sta cercando di valorizzare questa usanza comunitaria per costituirsi come <strong><strong>gruppo di economica solidale<\/strong><\/strong>, favorendo cos\u00ec la generazione di un reddito comune che possa essere equamente ridistribuito, migliorando in generale la condizione di vita di queste donne. Le giornate si sono susseguite veloci tra <strong><strong>visite alle varie comunit\u00e0 (Cazumba, Lage, Maria<\/strong><\/strong> <strong><strong>Preta)<\/strong><\/strong> della regione di Bomfim dove Ai. Bi, partner di <strong><strong>APAC (Associa\u00e7<\/strong><\/strong><strong>\u00e3<strong><strong>o Parceira das Crian\u00e7as),<\/strong><\/strong><\/strong> gestisce progetti ed attivit\u00e0 rivolti ai bambini e alle mamme: persone speciali, donne \u201cguerriere\u201d soprattutto, e luoghi che sembrano senza un dove e senza un tempo, che ci hanno accolto a braccia aperte nella loro nuda semplicit\u00e0, <strong><strong>posti dove davvero si vive con poco e si \u00e8 felici di poco<\/strong><\/strong>, l&#8217;uno per necessit\u00e0, l&#8217;altro per virt\u00f9. <strong><strong>Una realt\u00e0 molto lontana dal Brasile delle spiagge<\/strong><\/strong>, dell&#8217;Amazzonia, del samba, ma anche dalla povert\u00e0 delle favelas dei centri urbani: qui infatti quel che manca sono in assoluto i servizi (la scuola, l&#8217;ospedale, i trasporti, le comunicazioni), l&#8217;acqua corrente \u00e8 arrivata solo 10 anni fa\u00a0(prima la si prendeva negli stagni che si formavano durante la stagione delle piogge), le possibilit\u00e0 di lavoro e, agli occhi di noi giovani italiani, <strong><strong>mancano le opportunit\u00e0 per i giovani di Jacun\u00e0 <\/strong><\/strong><strong>di\u00a0oggi e di domani<\/strong>. <strong>Quale futuro si riserva per loro?<\/strong> \u00bb.<strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Intervistiamo Facica<\/strong>, 23 anni, iscritta a Milano al corso di Consulenza pedagogica, partita il 16 con i suoi compagni: \u00ab<strong>Quest\u2019esperienza ha ribaltato la mia visione del mondo<\/strong> \u2013 risponde alla nostra intervista \u2013. Questa gente mi ha insegnato a vivere l\u2019importanza di ogni pi\u00f9 piccolo gesto. Comunicare, lavorare e stare in mezzo a loro, cambia il modo di approcciarsi alle persone, mente qui, in Italia, si fatica a guardare in faccia gli altri, e a fare in modo che sia piacevole\u00bb. Ne parliamo con <strong>Letizia<\/strong>, l\u2019autrice del reportage. \u00abLa voglia \u00e8 ripartire in Brasile per fare la tesi l\u00ec\u00bb. Letizia infatti studia Scienze sociali a Torino. \u00abL\u2019ultimo giorno abbiamo viaggiato verso Campo Formoso, citt\u00e0 dello Stato di Bahia estesa su un raggio di 200 km, la mia esperienza pi\u00f9 interessante. Ho conosciuto Monalisa D., la coordinatrice di CREA, un Centro di assistenza specialistica \u2013 un\u2019assistenza sociale di secondo livello \u2013 che accoglie e sostiene minorenni in gravidanza precoce, bambini, uomini con alle spalle storie di violenza. Monalisa \u00e8 un avvocato con propensione sociale, \u00e8 lei che <strong>mi ha aperto gli occhi dalla macro alla micro-politica<\/strong>. Grazie a lei abbiamo conosciuto <strong>Eddie, un ragazzino di 10 anni<\/strong>, reinserito nella famiglia di origine. Proviene da un Istituto locale, dove la direttrice faceva subire maltrattamenti ai piccoli ospiti; la mamma era minorenne e i nonni non volevano che subentrasse un neonato in famiglia. L\u2019Istituto, per interessamento delle autorit\u00e0 locali, \u00e8 stato fortunatamente chiuso. \u00c8 stato recuperato il rapporto di Eddie con sua madre. <strong>Oggi Eddie dice che vuole fare l\u2019avvocato, racconta la sua storia con un realismo e una lucidit\u00e0 di coscienza che ti fa sentire piccolo-piccolo\u2026<\/strong> Molto, molto bella l\u2019occasione di fare begli incontri con belle donne. Molto bella l\u2019esperienza con i volontari espatriati che abbiamo incontrato, che sanno comportarsi senza invadenza, da fomentatori di energie gi\u00e0 presenti sul territorio. Ancora pi\u00f9 voglia di stare in Brasile\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">BAHIA \u2013 \u00ab<strong>Eddie, un ragazzino di 10 anni<\/strong>, reinserito nella famiglia di origine, proviene da un Istituto locale <strong>dove la direttrice faceva subire maltrattamenti<\/strong> ai piccoli ospiti.\u00a0Oggi Eddie dice che <strong>vuole fare l\u2019avvocato, racconta la sua storia con un realismo e una lucidit\u00e0 di coscienza che ti fa sentire piccolo-piccolo\u2026<\/strong>\u00bb <strong><a href=\"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-28065","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-\u00abnon-solo-spiagge-e-samba\u00bb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb\" \/>\n<meta property=\"og:description\" content=\"BAHIA \u2013 \u00abEddie, un ragazzino di 10 anni, reinserito nella famiglia di origine, proviene da un Istituto locale dove la direttrice faceva subire maltrattamenti ai piccoli ospiti.\u00a0Oggi Eddie dice che vuole fare l\u2019avvocato, racconta la sua storia con un realismo e una lucidit\u00e0 di coscienza che ti fa sentire piccolo-piccolo\u2026\u00bb LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-\u00abnon-solo-spiagge-e-samba\u00bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-27T14:13:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-27T15:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb\",\"datePublished\":\"2011-12-27T14:13:51+00:00\",\"dateModified\":\"2011-12-27T15:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/\"},\"wordCount\":831,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Brasile-non-solo-spiagge-e-samba.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/\",\"name\":\"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Brasile-non-solo-spiagge-e-samba.jpg\",\"datePublished\":\"2011-12-27T14:13:51+00:00\",\"dateModified\":\"2011-12-27T15:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Brasile-non-solo-spiagge-e-samba.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Brasile-non-solo-spiagge-e-samba.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-\u00abnon-solo-spiagge-e-samba\u00bb\/","og_locale":"it_IT","og_type":"article","og_title":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb","og_description":"BAHIA \u2013 \u00abEddie, un ragazzino di 10 anni, reinserito nella famiglia di origine, proviene da un Istituto locale dove la direttrice faceva subire maltrattamenti ai piccoli ospiti.\u00a0Oggi Eddie dice che vuole fare l\u2019avvocato, racconta la sua storia con un realismo e una lucidit\u00e0 di coscienza che ti fa sentire piccolo-piccolo\u2026\u00bb LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-\u00abnon-solo-spiagge-e-samba\u00bb\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-12-27T14:13:51+00:00","article_modified_time":"2011-12-27T15:15:11+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb","datePublished":"2011-12-27T14:13:51+00:00","dateModified":"2011-12-27T15:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/"},"wordCount":831,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/","url":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/","name":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg","datePublished":"2011-12-27T14:13:51+00:00","dateModified":"2011-12-27T15:15:11+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Brasile-non-solo-spiagge-e-samba.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/reportage-dal-brasile-%c2%abnon-solo-spiagge-e-samba%c2%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Reportage dal Brasile: \u00abNon solo spiagge e samba\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=28065"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28065\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=28065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=28065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=28065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}