﻿


{"id":28281,"date":"2011-12-20T18:30:44","date_gmt":"2011-12-20T17:30:44","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=28281"},"modified":"2011-12-20T18:31:09","modified_gmt":"2011-12-20T17:31:09","slug":"il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/","title":{"rendered":"Il lusso dell&#8217;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28284\" style=\"margin: 5px;\" title=\"Abbattere i costi drastica riduzione degli enti autorizzati\" src=\"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>MILANO \u2013 Il quotidiano <em>Il Giornale<\/em> pubblica, il 17 dicembre, le dichiarazioni di Attilio Gugiatti, ricercatore presso l\u2019Universit\u00e0 Bocconi, rilasciate a proposito dei sempre pi\u00f9 alti costi economici dell\u2019adozione internazionale. L\u2019articolo \u00e8 <em>Se l\u2019adozione all\u2019estero diventa un lusso<\/em>. \u00abSforbiciare i troppi Enti Autorizzati all\u2019adozione internazionale e creare un organismo pubblico, che operi sull\u2019intero territorio nazionale, sul modello dell\u2019AFA francese\u00bb, \u00e8 la duplice proposta di Gugiatti, membro del CERGAS, Centro di Ricerche sulla Gestione dell\u2019Assistenza Sanitaria Sociale.<\/p>\n<p style=\"text-align: justify;\"><strong>Se la prima proposta \u00e8 assolutamente condivisibile, l\u2019Ente pubblico non \u00e8 una soluzione<\/strong>. Per due motivi: con la creazione di un Ente pubblico nazionale, le adozioni internazionali <strong>verrebbero a costare di pi\u00f9<\/strong> allo Stato e conseguentemente ai cittadini. Lo dimostrano i bilanci dell\u2019ARAI, l\u2019Ente Regionale piemontese per le adozioni di minori stranieri. In secondo luogo, un Ente pubblico finirebbe per determinare il <strong>notevole rallentamento delle adozioni internazionali<\/strong>, con una decrescita del numero di minori accolti e di nuove famiglie adottive. A dimostrarlo \u00e8 l\u2019esperienza dell\u2019Autorit\u00e0 Francese per le adozioni internazionali: le coppie che si rivolgono ad essa sono la minima parte del totale di aspiranti. In Italia, lo dimostra poi l\u2019esperienza pubblica dell\u2019affidamento di minori, da anni in situazione di stallo.<\/p>\n<p style=\"text-align: justify;\">Semmai, la soluzione alla deriva economica \u00e8 nel <strong>ridurre drasticamente, fino a un massimo di 20-25, il numero di Enti Autorizzati<\/strong>.<strong> <\/strong>Un numero ragionevole di grandi enti, capaci di superare le 200 adozioni l\u2019anno, potrebbero infatti sia offrire un servizio strutturato e qualitativamente adeguato su tutto il territorio nazionale, sia frenare l\u2019aumento dei costi per le aspiranti coppie adottive, grazie alle economie di scala, che naturalmente si svilupperebbero.<\/p>\n<p style=\"text-align: justify;\">\u00c8 poi convinzione di Ai.Bi. Amici dei Bambini, da anni, che lo strumento principale di razionalizzazione dei costi \u00e8 nel <strong>semplificare l\u2019iter procedurale<\/strong>, cui oggi sono obbligate le coppie aspiranti. L\u2019attuale composizione dell\u2019iter incastra le coppie aspiranti in una serie onerosa di colloqui, il cui numero \u00e8 sostanzialmente imprevedibile: pu\u00f2 raggiungere il numero di 15, distribuiti sostanzialmente in tre percorsi paralleli e ripetitivi: presso i Servizi Sociali, il Tribunale per i Minorenni e gli Enti Autorizzati.<\/p>\n<p style=\"text-align: justify;\"><strong>Il primo passo per la creazione di risparmi sulla spesa adottiva \u00e8 l\u2019abolizione del ruolo del giudice presso il Tribunale presso i Minorenni<\/strong>. \u00abSiamo arrivati a questi alti costi per gli errori dei Governi passati, che hanno autorizzato un eccessivo numero di Enti \u2013 dichiara il presidente di Amici dei Bambini, Marco Griffini \u2013. <strong>L\u2019eliminazione dei costi superflui dipende dalla fine del coinvolgimento del giudice nell\u2019emissione dei decreti d\u2019Idoneit\u00e0<\/strong>. <strong>Lo Stato liberi totalmente l\u2019adozione dai costi <\/strong><strong>inutili che la soffocano<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">MILANO \u2013 <strong>Un&#8217;economia di scala, a contrasto dei costi dell&#8217;adozione<\/strong>. Il quotidiano <em>Il Giornale<\/em> pubblica, il 17 dicembre, le dichiarazioni di Attilio Gugiatti, ricercatore presso l\u2019Universit\u00e0 Bocconi, rilasciate a proposito dei sempre pi\u00f9 alti costi economici dell\u2019adozione internazionale.\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-28281","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il lusso dell&#039;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l\u2019ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il lusso dell&#039;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati\" \/>\n<meta property=\"og:description\" content=\"MILANO \u2013 Un&#039;economia di scala, a contrasto dei costi dell&#039;adozione. Il quotidiano Il Giornale pubblica, il 17 dicembre, le dichiarazioni di Attilio Gugiatti, ricercatore presso l\u2019Universit\u00e0 Bocconi, rilasciate a proposito dei sempre pi\u00f9 alti costi economici dell\u2019adozione internazionale.\u00a0LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l\u2019ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-20T17:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-20T17:31:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Il lusso dell&#8217;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati\",\"datePublished\":\"2011-12-20T17:30:44+00:00\",\"dateModified\":\"2011-12-20T17:31:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/\"},\"wordCount\":451,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/\",\"name\":\"Il lusso dell'adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\",\"datePublished\":\"2011-12-20T17:30:44+00:00\",\"dateModified\":\"2011-12-20T17:31:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il lusso dell&#8217;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il lusso dell'adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l\u2019ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/","og_locale":"it_IT","og_type":"article","og_title":"Il lusso dell'adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati","og_description":"MILANO \u2013 Un'economia di scala, a contrasto dei costi dell'adozione. Il quotidiano Il Giornale pubblica, il 17 dicembre, le dichiarazioni di Attilio Gugiatti, ricercatore presso l\u2019Universit\u00e0 Bocconi, rilasciate a proposito dei sempre pi\u00f9 alti costi economici dell\u2019adozione internazionale.\u00a0LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l\u2019ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-12-20T17:30:44+00:00","article_modified_time":"2011-12-20T17:31:09+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Il lusso dell&#8217;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati","datePublished":"2011-12-20T17:30:44+00:00","dateModified":"2011-12-20T17:31:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/"},"wordCount":451,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/","url":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/","name":"Il lusso dell'adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg","datePublished":"2011-12-20T17:30:44+00:00","dateModified":"2011-12-20T17:31:09+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Abbattere-i-costi-drastica-riduzione-degli-enti-autorizzati.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-lusso-delladozione-internazionale-la-soluzione-non-e-l%e2%80%99ente-pubblico-nazionale-ma-una-drastica-riduzione-degli-enti-autorizzati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Il lusso dell&#8217;adozione internazionale: la soluzione non \u00e8 l\u2019Ente pubblico nazionale, ma una drastica riduzione degli Enti autorizzati"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:12:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=28281"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28281\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=28281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=28281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=28281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}