﻿


{"id":28361,"date":"2011-12-22T16:08:54","date_gmt":"2011-12-22T15:08:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=28361"},"modified":"2011-12-22T16:13:54","modified_gmt":"2011-12-22T15:13:54","slug":"marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/","title":{"rendered":"Marcus, 9 anni: \u00ab&#8230; e una sera ci disse, &#8220;Adesso vi racconto la storia della mia vita!&#8221;\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28363\" style=\"margin: 5px;\" title=\"Street child from Brazil\" src=\"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a><\/strong>TORINO \u2013 \u00ab<strong>Era pieno di rabbia nei confronti della vita<\/strong>. Era scontroso, si comportava male, voleva sempre giocare alla lotta e si teneva a distanza dall\u2019elemento materno. Arrivati a casa si \u00e8 trasformato\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Un bambino speciale, unico, \u00abspettacolare\u00bb<\/strong>, dice sua madre Lucia al telefono, ferma al margine della strada di un paesino del torinese. La nostra chiamata la trova in automobile insieme a Marcus, lo chiameremo con questo nome, il figlio che l\u2019ha conquistata, sciogliendole anima e cuore in un pianto rinnovatore. Acqua dagli occhi: il battesimo dell\u2019accoglienza, per un nuovo figlio dell\u2019abbandono.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>\u00c8 qui con lo sportello aperto, che ascolta Michael Jackson a manetta<\/strong>\u00bb, \u00a0ride di gusto Lucia. Una maniera di attirare l\u2019attenzione materna? \u00abAll\u2019inizio, quando era con noi in Brasile, pieno di rabbia contro il mondo, non c\u2019era giorno che non facesse i capricci. La sua \u00e8 la storia di un bambino ripetutamente abbandonato e forse aveva buone ragioni per essere cos\u00ec. Ha quasi 9 anni e sicuramente \u00e8 cresciuto prima di altri bambini. Qui a casa si \u00e8 trasformato. Ogni mattina si sveglia e mi chiede di guardare la neve. Ora la gente, quando ci vede insieme a lui, non fa che notare la sua grande dolcezza\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Lucia e Salvatore, coppia di 46enni partiti per il Brasile e tornati a casa il 3 dicembre, con un giuramento: <em>famiglia per sempre<\/em><\/strong>. Niente rose e fiori, all\u2019inizio. Marcus &#8211; che i lettori hanno conosciuto attraverso una lettera, pubblicata le settimane scorse sul sito di Ai.Bi. &#8211; per una reazione che risale dal suo passato, non voleva saperne della madre, dandosi completamente all\u2019adorazione del pap\u00e0. Tutto normale, dicevano gli psicologi; ma la cosa \u00e8 di non poco conto per una mamma. \u00abDiciamo che lui non ne voleva sapere &#8211; commenta Lucia -. <strong>Il cambiamento \u00e8 avvenuto una sera che siamo tornati dal mare<\/strong>. Eravamo in Brasile, ci siamo allontanati per qualche tempo e la sera, tornati da Marcus, lo abbiamo trovato come al solito stizzoso. Poi si \u00e8 creata un\u2019occasione per stare insieme. Marcus ha iniziato ad aprirsi: \u201cAdesso vi racconto la storia della mia vita\u201d, ha detto. Ha tirato fuori il suo passato, i suoi abbandoni. Io, da questo suo racconto, sono scoppiata a piangere. Sono scappata nell\u2019altra stanza in lacrime. E il fatto che io piangessi lo ha colpito. Mi ha abbracciata, piangeva con me, non mi mollava pi\u00f9. Finalmente si faceva accarezzare la testa\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Salvatore, il pap\u00e0, lo troviamo nel bel mezzo dell\u2019autostrada<\/strong>. Guida e parla in vivavoce, la comunicazione viene e va, \u00e8 un turbine di emozione. \u00ab<strong>Sono felice<\/strong>\u00bb, \u00e8 la sua dichiarazione. \u00abCome bimbo, spesso mi stupisce. Nonostante la sua et\u00e0, 9 anni appena, dimostra una maturit\u00e0 mostruosa su certi argomenti di vita quotidiana. Poi capita di giocare assieme e lui mostra di ricordare tante cose imparate da me. Di certo dovr\u00e0 tirare fuori ancora molto del suo vissuto, ma trover\u00e0 sfogo in qualcosa, sono fiducioso. Oggi posso dire che sono contento di essere il pap\u00e0 di Marcus. Abbiamo incontrato tanti ostacoli: una lunga attesa, poi le resistenze e la rabbia di Marcus che si trasformava in aggressivit\u00e0: abbiamo imparato a mettere il bambino al centro, a far diventare il nostro desiderio di essere genitori <strong>un desiderio di dare una famiglia a nostro figlio<\/strong>. Bisogna avere il coraggio di abbattere gli ostacoli: mai stare da soli, e mai abbassare la guardia dell\u2019amore. S\u00ec, il nostro motto era: famiglia per sempre. <strong>E Marcus lo ripete tutti i giorni<\/strong>\u00bb, conclude Salvatore, ormai commosso, cacciando indietro, eroicamente, le prime lacrime di padre della sua vita.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">TORINO \u2013 \u00ab<strong>Era pieno di rabbia nei confronti della vita<\/strong>. Era scontroso, si comportava male, voleva sempre giocare alla lotta e si teneva a distanza dall\u2019elemento materno. Arrivati a casa si \u00e8 trasformato\u00bb. <strong>Un bambino speciale, unico, \u00abspettacolare\u00bb<\/strong>, dice sua madre Lucia al telefono, ferma al margine della strada. <strong><a href=\"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-28361","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marcus, 9 anni: \u00ab... e una sera ci disse, &quot;Adesso vi racconto la storia della mia vita!&quot;\u00bb - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/marcus-9-anni-\u00ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita\u00bb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marcus, 9 anni: \u00ab... e una sera ci disse, &quot;Adesso vi racconto la storia della mia vita!&quot;\u00bb\" \/>\n<meta property=\"og:description\" content=\"TORINO \u2013 \u00abEra pieno di rabbia nei confronti della vita. Era scontroso, si comportava male, voleva sempre giocare alla lotta e si teneva a distanza dall\u2019elemento materno. Arrivati a casa si \u00e8 trasformato\u00bb. Un bambino speciale, unico, \u00abspettacolare\u00bb, dice sua madre Lucia al telefono, ferma al margine della strada. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/marcus-9-anni-\u00ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita\u00bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-22T15:08:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-22T15:13:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Marcus, 9 anni: \u00ab&#8230; e una sera ci disse, &#8220;Adesso vi racconto la storia della mia vita!&#8221;\u00bb\",\"datePublished\":\"2011-12-22T15:08:54+00:00\",\"dateModified\":\"2011-12-22T15:13:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/\"},\"wordCount\":602,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Street-child-from-Brazil.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/\",\"name\":\"Marcus, 9 anni: \u00ab... e una sera ci disse, \\\"Adesso vi racconto la storia della mia vita!\\\"\u00bb - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Street-child-from-Brazil.jpg\",\"datePublished\":\"2011-12-22T15:08:54+00:00\",\"dateModified\":\"2011-12-22T15:13:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Street-child-from-Brazil.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Street-child-from-Brazil.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marcus, 9 anni: \u00ab&#8230; e una sera ci disse, &#8220;Adesso vi racconto la storia della mia vita!&#8221;\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marcus, 9 anni: \u00ab... e una sera ci disse, \"Adesso vi racconto la storia della mia vita!\"\u00bb - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-\u00ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita\u00bb\/","og_locale":"it_IT","og_type":"article","og_title":"Marcus, 9 anni: \u00ab... e una sera ci disse, \"Adesso vi racconto la storia della mia vita!\"\u00bb","og_description":"TORINO \u2013 \u00abEra pieno di rabbia nei confronti della vita. Era scontroso, si comportava male, voleva sempre giocare alla lotta e si teneva a distanza dall\u2019elemento materno. Arrivati a casa si \u00e8 trasformato\u00bb. Un bambino speciale, unico, \u00abspettacolare\u00bb, dice sua madre Lucia al telefono, ferma al margine della strada. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-\u00ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita\u00bb\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2011-12-22T15:08:54+00:00","article_modified_time":"2011-12-22T15:13:54+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Marcus, 9 anni: \u00ab&#8230; e una sera ci disse, &#8220;Adesso vi racconto la storia della mia vita!&#8221;\u00bb","datePublished":"2011-12-22T15:08:54+00:00","dateModified":"2011-12-22T15:13:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/"},"wordCount":602,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/","url":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/","name":"Marcus, 9 anni: \u00ab... e una sera ci disse, \"Adesso vi racconto la storia della mia vita!\"\u00bb - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg","datePublished":"2011-12-22T15:08:54+00:00","dateModified":"2011-12-22T15:13:54+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Street-child-from-Brazil.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/marcus-9-anni-%c2%ab-e-una-sera-ci-disse-adesso-vi-racconto-la-storia-della-mia-vita%c2%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Marcus, 9 anni: \u00ab&#8230; e una sera ci disse, &#8220;Adesso vi racconto la storia della mia vita!&#8221;\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:39:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=28361"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28361\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=28361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=28361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=28361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}