﻿


{"id":28570,"date":"2012-01-02T16:21:14","date_gmt":"2012-01-02T15:21:14","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=28570"},"modified":"2012-01-02T16:21:51","modified_gmt":"2012-01-02T15:21:51","slug":"adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/","title":{"rendered":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-27876\" style=\"margin: 5px;\" title=\"Adozione\" src=\"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/Adozione-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Chi aspira a un&#8217;adozione  internazionale non pu\u00f2 e non deve avere riserve sull&#8217;etnia del bambino o  esprimere timori sulle tare genetiche. Con l\u2019<strong>ordinanza n. 29424 del 28 dicembre 2011<\/strong> la  Corte di Cassazione ha ribadito ancora una volta che chi aspira a un&#8217;adozione internazionale non pu\u00f2 avere  riserve sul bambino da accogliere.<\/p>\n<p style=\"text-align: justify;\">Sia il Tribunale per i Minorenni  dell\u2019Emilia Romagna che la Corte d\u2019Appello di Bologna hanno ritenuto <strong>non idonea<\/strong> una coppia aspirante  all\u2019adozione che aveva dichiarato quanto segue: \u201c<em>no a religione di origine diversa da quella  cattolica; no a bambini figli di pazienti psichiatrici; no ad un bambino di  origine rom per le difficolt\u00e0 di carattere che renderebbero difficile imporsi e  assumere posizioni diverse, perplessit\u00e0 rispetto a un bambino di  colore<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Che la disponibilit\u00e0 di  accoglienza delle coppie non possa essere condizionata n\u00e9 limitata in funzione  delle caratteristiche del minore adottando \u00e8 una questione che sembrava da tempo  risolta perch\u00e9 gi\u00e0 chiarita dalla Cassazione nella sentenza dell\u20191 giugno 2010,  dove si spiegava chiaramente che l\u2019adozione internazionale \u00e8 uno <strong>strumento di solidariet\u00e0<\/strong> (Cass. S.U.  13332\/2010).<\/p>\n<p style=\"text-align: justify;\">Nonostante quell\u2019autorevole  sentenza, e anzi all\u2019indomani della stessa, il Procuratore Generale presso la  Corte d\u2019Appello di Bologna ha inspiegabilmente proposto ricorso in Cassazione  contestando il fatto che alla coppia fosse stata negata  l\u2019idoneit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>La Cassazione ha confermato la decisione della Corte  d\u2019Appello<\/strong> che, convalidando a sua volta la decisione del Tribunale,  aveva concluso per l\u2019inidoneit\u00e0 del nucleo familiare degli adottanti proprio  sulla base delle preclusioni da loro manifestate su determinate caratteristiche  del minore da adottare.<\/p>\n<p style=\"text-align: justify;\">Speriamo che questa ennesima  conferma possa essere di riflessione per alcuni Tribunali per i Minorenni, come  ad esempio quello di <strong>Roma<\/strong>, perch\u00e9  finalmente decidano di porsi dalla parte dei minori abbandonati senza alcuna  distinzione di sorta, et\u00e0 inclusa!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi aspira a un&#8217;adozione internazionale non pu\u00f2 e non deve avere riserve sull&#8217;etnia del bambino o esprimere timori sulle tare genetiche. Con l\u2019<strong>ordinanza n. 29424 del 28 dicembre 2011<\/strong> la Corte di Cassazione ha ribadito ancora una volta che chi aspira a un&#8217;adozione internazionale non pu\u00f2 avere riserve sul bambino da accogliere.<a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/\"> <strong>LEGGI TUTTO&#8230;<\/strong><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-28570","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati\" \/>\n<meta property=\"og:description\" content=\"Chi aspira a un&#039;adozione internazionale non pu\u00f2 e non deve avere riserve sull&#039;etnia del bambino o esprimere timori sulle tare genetiche. Con l\u2019ordinanza n. 29424 del 28 dicembre 2011 la Corte di Cassazione ha ribadito ancora una volta che chi aspira a un&#039;adozione internazionale non pu\u00f2 avere riserve sul bambino da accogliere. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-02T15:21:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-02T15:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati\",\"datePublished\":\"2012-01-02T15:21:14+00:00\",\"dateModified\":\"2012-01-02T15:21:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/\",\"name\":\"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione.jpg\",\"datePublished\":\"2012-01-02T15:21:14+00:00\",\"dateModified\":\"2012-01-02T15:21:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati","og_description":"Chi aspira a un'adozione internazionale non pu\u00f2 e non deve avere riserve sull'etnia del bambino o esprimere timori sulle tare genetiche. Con l\u2019ordinanza n. 29424 del 28 dicembre 2011 la Corte di Cassazione ha ribadito ancora una volta che chi aspira a un'adozione internazionale non pu\u00f2 avere riserve sul bambino da accogliere. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-01-02T15:21:14+00:00","article_modified_time":"2012-01-02T15:21:51+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati","datePublished":"2012-01-02T15:21:14+00:00","dateModified":"2012-01-02T15:21:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/"},"wordCount":306,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/","name":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg","datePublished":"2012-01-02T15:21:14+00:00","dateModified":"2012-01-02T15:21:51+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-cassazione-ribadisce-un-deciso-no-ai-decreti-vincolati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni Internazionali: Cassazione ribadisce un deciso no ai decreti vincolati"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:14:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=28570"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28570\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=28570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=28570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=28570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}