﻿


{"id":28933,"date":"2012-01-12T16:29:27","date_gmt":"2012-01-12T15:29:27","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=28933"},"modified":"2012-01-12T16:42:43","modified_gmt":"2012-01-12T15:42:43","slug":"georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/","title":{"rendered":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-28936\" style=\"margin: 5px;\" title=\"Bambini a Tbilisi\" src=\"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>TBILISI \u2013 A partire dal 2012 in Georgia tutti gli Istituti del paese che ospitano minori fino ai 6 anni d\u2019et\u00e0 \u2013 46 in totale \u2013 saranno chiusi dietro ordinanza del Presidente della Georgia Mikhail Saaka\u0161vili. Il fatto fa scalpore perch\u00e9 accade dopo <strong>le scoperte di un\u2019inchiesta<\/strong>, pubblicata in un report dell\u2019Ufficio del Difensore Civico. Ecco l\u2019approfondimento di questa notizia sul Georgia Times, nella traduzione esclusiva di Ai.Bi.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Gli orfani georgiani sotto la scure della riforma<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">In Georgia chiudono gli orfanotrofi. Scrivono che non sono pi\u00f9 necessari. Questo non significa che nel paese siano scomparsi gli orfani. Semplicemente Mikhail Saakashvili e i suoi ministri non vogliono alzare un dito per difenderli: quindi i bambini vivono in condizioni spaventose. Gli orfanotrofi, che fino a poco tempo fa in Georgia erano 46, davvero facevano una brutta impressione. Ora li liquidano in fretta distribuendo i bambini, come merce in negozio, presso famiglie affidatarie.<em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Ma i bambini non sono<\/strong><strong> pietre<\/strong>. Hanno una mente fine e la confusione che si crea con il cambio dei genitori affidatari e delle Case per bambini ha su di essi effetti molto negativi. Gli attivisti dei diritti umani avvertono che la riforma fatta in fretta non far\u00e0 che peggiorare la situazione dei bambini svantaggiati. Esempi ce ne sono gi\u00e0. A Digomi, sobborgo di Tbilisi, una casa per bambini \u00e8 stata riformata a tempo di record. Al suo posto \u00e8 stato <strong>creato un centro di addestramento militare, ed \u00e8 per questo in realt\u00e0 che c\u2019era fretta di liquidarla<\/strong>.<\/p>\n<p style=\"text-align: justify;\">I 57 bambini che vivevano nell\u2019orfanotrofio di Digomi o sono tornati dai loro genitori biologici, o sono stati collocati in famiglie affidatarie o inviati ad altre istituzioni per orfani. Per molti di loro \u00e8 stato un trauma psicologico, ritengono Natia Partskhaladze, esperto di famiglia e bambini dell&#8217;UNICEF, e Jaba Nachkebia, capo dell\u2019ONG locale &#8220;Bambini della Georgia&#8221;, che rilevano come lo Stato non aiuti le famiglie e gli educatori degli orfanotrofi, n\u00e9 moralmente n\u00e9 materialmente, a prepararsi al cambio di vita.<\/p>\n<p style=\"text-align: justify;\">La stessa sorte \u00e8 gi\u00e0 toccata ad altri 28 orfanotrofi in Georgia. Qualcuno ha accolto i bambini solo per 450 lari al mese (la valuta locale), pagati dal governo. Rispetto al salario minimo, si tratta di un importo considerevole. Ma per soddisfare tutte le condizioni del contratto con lo Stato sul mantenimento dell\u2019affidato (vestirlo, alimentarlo completamente, condurlo agli studi) con 450 lari \u00e8 <strong>impossibile<\/strong>. E poich\u00e9 il contratto di affido si fa <strong>per tre mesi<\/strong>, alcune delle famiglie sicuramente <strong>ridaranno<\/strong><strong> indietro i bambini<\/strong>. Ma l&#8217;orfanotrofio non ci sar\u00e0 pi\u00f9. Dovranno stare in rifugi temporanei e poi andare in una nuova famiglia, magari una volta ogni tre mesi.<\/p>\n<p style=\"text-align: justify;\">Lo psicologo Ketevan Pkhakadze ritiene <strong>che il<\/strong><strong> cambiamento permanente<\/strong> di residenza e di genitori affidatari <strong>pu\u00f2 danneggiare la salute<\/strong><strong> mentale del bambino<\/strong>. Inoltre, nel cos\u00ec breve periodo in cui Saakashvili ha ordinato di compiere la riforma, <strong>non \u00e8 possibile selezionare buoni candidati<\/strong><strong> all\u2019affido<\/strong> e preparare loro e i bambini ad un nuovo stile di vita. Questo aumenta il rischio di cessazione del contratto.<\/p>\n<p style=\"text-align: justify;\">Un altro problema riguarda <strong>i bambini<\/strong><strong> malati terminali<\/strong>, che si \u00e8 sempre riluttanti ad adottare. E sebbene lo Stato paga per loro un po\u2019 di pi\u00f9 &#8211; 600 lari &#8211; \u00e8 ingenuo sperare che anche tutti loro vengano tolti dagli orfanotrofi.<\/p>\n<p style=\"text-align: justify;\"><strong>La maggior parte<\/strong><strong> degli orfani in Georgia sono orfani sociali<\/strong> che vivono con i genitori. In tale situazione lo Stato dovrebbe pensare alle ragioni della comparsa di bambini rifiutati. Se i 450 lari non fossero pagati a persone sconosciute, che sottoscrivono un contratto e si prendono temporaneamente dei figli, ma ai loro genitori biologici, l&#8217;effetto della riforma sarebbe molto pi\u00f9 alto. <strong>Ma ora il<\/strong><strong> governo non prevede assegni famigliari per i genitori biologici. Solo le famiglie con otto figli sono considerate famiglie numerose e prendono per i loro figli l\u2019equivalente del gelato<\/strong>.<\/p>\n<p style=\"text-align: justify;\">A volte i genitori mandano i bambini negli orfanotrofi e nei collegi, <strong>perch\u00e9 nei loro<\/strong><strong> villaggi vicini non c&#8217;\u00e8 la scuola. Durante il periodo di governo di<\/strong> Saakashvili il numero di scuole pubbliche gratuite <strong>\u00e8 diminuito di<\/strong><strong> quasi due volte<\/strong> &#8211; fino a mille e rotti. Pertanto, <strong>le madri si strappano i figli dal cuore, purch\u00e9 possano studiare<\/strong>. Ora quei bambini rischiano un amaro destino?<\/p>\n<p style=\"text-align: justify;\"><strong>In Georgia le strade sono piene, oltre che di vigilanza statale<\/strong><strong> che si occupa di orfani, anche di bambini di strada<\/strong>. Non vanno a scuola e principalmente chiedono elemosina. In presenza di masse di bambini che necessitano di cure dello Stato, risulta totalmente irrazionale sbarazzarsi dei grandi orfanotrofi. Ma la Georgia davvero <strong>vuole assomigliare sempre pi\u00f9 agli Stati Uniti<\/strong>, <strong>dove gli istituti <\/strong><strong>da tempo sono ormai scomparsi<\/strong>, anche se sono nati in questo paese prima che altrove \u2013 gi\u00e0 nel 19\u00b0 secolo.<\/p>\n<p style=\"text-align: justify;\">A tal proposito, parallelamente alla chiusura degli orfanotrofi il governo ha deciso di aprire collegi <strong>per ragazzi difficili<\/strong>. Ai genitori che si rifiutano di mandare i propri figli, segnalati dagli assistenti sociali, verranno imposte delle sanzioni pecuniarie.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, la risposta positiva dell\u2019<strong>UNICEF<\/strong> al governo di Saakashvili \u00e8 gi\u00e0 arrivata. Secondo l&#8217;UNICEF, qualsiasi bambino che nasce oggi in Georgia ha una migliore qualit\u00e0 di vita rispetto a un bambino che \u00e8 nato 10 anni fa. Si osserva che ora quasi tutti i neonati sono registrati, tutti i bambini, tranne gli zingari, frequentano la scuola, e la mortalit\u00e0 dei bambini al di sotto dei 5 anni \u00e8 diminuita.<\/p>\n<p style=\"text-align: justify;\">Ma allo stesso tempo, rispetto ad altri paesi dell\u2019 ex-Unione Sovietica e dell\u2019 Europa, la Georgia \u00e8 il peggiore in termini di spesa sociale. <strong>Pi\u00f9 di un<\/strong><strong> quarto dei bambini vive in miseria<\/strong>. La quantit\u00e0 dei decessi tra i pi\u00f9 piccoli in ogni caso riguarda il loro livello di salute, nonostante quello che il presidente Mikhail Saakashvili dichiari sui livelli di salute del popolo georgiano, quindi insomma la Georgia pu\u00f2 ancora essere considerato un Paese selvaggio.<\/p>\n<p style=\"text-align: justify;\">&#8220;In Europa, su 1000 bambini ne muoiono tre o quattro, da noi invece fino a 20 bambini&#8221; &#8211; ha detto il leader del &#8220;Tetrebi&#8221; Temur Shashiashvili. In aggiunta a ci\u00f2 c\u2019\u00e8 un numero sempre pi\u00f9 crescente di aborti. Aumenta anche l\u2019emigrazione, aumenta la minaccia dei naziskin.\u00a0 Ma Saakashvili, come \u00e8 evidente, \u00e8 di questa idea: <strong>meglio pochi ma buoni<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Autrice: Salom\u00e8 Batianin<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">TBILISI &#8211; <strong>I bambini non sono pietre<\/strong>.\u00a0La confusione che si crea con il cambio dei genitori affidatari e delle Case per bambini ha su di essi effetti molto negativi.\u00a0A Digomi, sobborgo di Tbilisi, una casa per bambini \u00e8 stata riformata a tempo di record. Al suo posto \u00e8 stato <strong>creato un centro di addestramento militare, ed \u00e8 per questo in realt\u00e0 che c\u2019era fretta di liquidarla<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-28933","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni\" \/>\n<meta property=\"og:description\" content=\"TBILISI - I bambini non sono pietre.\u00a0La confusione che si crea con il cambio dei genitori affidatari e delle Case per bambini ha su di essi effetti molto negativi.\u00a0A Digomi, sobborgo di Tbilisi, una casa per bambini \u00e8 stata riformata a tempo di record. Al suo posto \u00e8 stato creato un centro di addestramento militare, ed \u00e8 per questo in realt\u00e0 che c\u2019era fretta di liquidarla. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-12T15:29:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-12T15:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni\",\"datePublished\":\"2012-01-12T15:29:27+00:00\",\"dateModified\":\"2012-01-12T15:42:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/\"},\"wordCount\":1017,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Bambini-a-Tbilisi.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/\",\"name\":\"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Bambini-a-Tbilisi.jpg\",\"datePublished\":\"2012-01-12T15:29:27+00:00\",\"dateModified\":\"2012-01-12T15:42:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Bambini-a-Tbilisi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Bambini-a-Tbilisi.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/","og_locale":"it_IT","og_type":"article","og_title":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni","og_description":"TBILISI - I bambini non sono pietre.\u00a0La confusione che si crea con il cambio dei genitori affidatari e delle Case per bambini ha su di essi effetti molto negativi.\u00a0A Digomi, sobborgo di Tbilisi, una casa per bambini \u00e8 stata riformata a tempo di record. Al suo posto \u00e8 stato creato un centro di addestramento militare, ed \u00e8 per questo in realt\u00e0 che c\u2019era fretta di liquidarla. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-01-12T15:29:27+00:00","article_modified_time":"2012-01-12T15:42:43+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni","datePublished":"2012-01-12T15:29:27+00:00","dateModified":"2012-01-12T15:42:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/"},"wordCount":1017,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/","url":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/","name":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg","datePublished":"2012-01-12T15:29:27+00:00","dateModified":"2012-01-12T15:42:43+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Bambini-a-Tbilisi.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/georgia-chiudono-in-massa-gli-istituti-per-i-minori-fino-ai-6-anni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Georgia, chiudono in massa gli Istituti per i minori fino ai 6 anni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=28933"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/28933\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=28933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=28933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=28933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}