﻿


{"id":29664,"date":"2012-02-01T18:08:37","date_gmt":"2012-02-01T17:08:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=29664"},"modified":"2012-02-01T20:45:54","modified_gmt":"2012-02-01T19:45:54","slug":"la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/","title":{"rendered":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-29668\" style=\"margin: 5px;\" title=\"Adozione a Milano, 3 coppie aspiranti su 10 non sono idonee\" src=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Nel 2011 in Lombardia<strong> 3 coppie su 10<\/strong> sono state dichiarate <strong>non idonee<\/strong> ad adottare o hanno rinunciato a proseguire. Sono i dati pubblicati a Milano dal Tribunale per i Minorenni, gli stessi dati che parlano di una flessione nel numero di domande con cui le coppie lombarde si sono candidate ad adottare un bambino.<\/p>\n<p style=\"text-align: justify;\">\u00abNel 2011 si \u00e8 assistito ad <strong>un deciso calo nelle domande di adozione internazionale<\/strong>\u00bb, dichiara la nota emessa dal Tribunale dei Minori di Milano, \u00abcon inversione di tendenza rispetto al trend di leggero aumento delle domande registrato nel 2009, dopo alcuni anni di costante calo\u00bb. Sono state <strong>588<\/strong> le domande presentate dalle coppie nel 2011. Di esse, sono state dichiarata <strong>idonee all\u2019adozione<\/strong> <strong>410 domande<\/strong>.<strong> <\/strong>Le<strong> <\/strong>coppie invece <strong>non idonee sono state 134<\/strong>. Le rinunce ammontano a quota 44.<\/p>\n<p style=\"text-align: justify;\">Nel 2010 le coppie idonee erano 535. I decreti di idoneit\u00e0 emessi a Milano sono calati dunque del <strong>23,3%<\/strong>. Da una lettura critica del fenomeno si rileva come il numero di aspiranti coppie adottive in Lombardia tra il 2010 e il 2011 \u00e8 sceso del 23,5%: due anni fa le coppie che hanno presentato domanda erano 769. Ma l\u2019analisi non pu\u00f2 fare a meno di notare come, <strong>nell\u2019arco del biennio 2010-2011, ben 142 coppie sono state rigettate<\/strong> e dichiarate non idonee. Una lettura attenta del fenomeno dovrebbe sottolineare come, oltre alla crisi, l\u2019adozione in Italia sta attraversando una fase di <strong>spreco di preziose risorse demografiche<\/strong>,<strong> rappresentate dalle coppie<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Nel 2011 in Lombardia<strong> 3 coppie su 10<\/strong> sono state dichiarate <strong>non idonee<\/strong> ad adottare o hanno <strong>rinunciato<\/strong> a proseguire. Da una lettura critica del fenomeno si rileva come il numero di aspiranti coppie adottive in Lombardia tra il 2010 e il 2011 \u00e8 sceso del 23,5%. <strong><a href=\"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-29664","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/la-crisi-dell\u2019adozione-il-crollo-delle-idoneita-a-milano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano\" \/>\n<meta property=\"og:description\" content=\"Nel 2011 in Lombardia 3 coppie su 10 sono state dichiarate non idonee ad adottare o hanno rinunciato a proseguire. Da una lettura critica del fenomeno si rileva come il numero di aspiranti coppie adottive in Lombardia tra il 2010 e il 2011 \u00e8 sceso del 23,5%. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/la-crisi-dell\u2019adozione-il-crollo-delle-idoneita-a-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-01T17:08:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-01T19:45:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano\",\"datePublished\":\"2012-02-01T17:08:37+00:00\",\"dateModified\":\"2012-02-01T19:45:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/\",\"name\":\"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\",\"datePublished\":\"2012-02-01T17:08:37+00:00\",\"dateModified\":\"2012-02-01T19:45:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/la-crisi-dell\u2019adozione-il-crollo-delle-idoneita-a-milano\/","og_locale":"it_IT","og_type":"article","og_title":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano","og_description":"Nel 2011 in Lombardia 3 coppie su 10 sono state dichiarate non idonee ad adottare o hanno rinunciato a proseguire. Da una lettura critica del fenomeno si rileva come il numero di aspiranti coppie adottive in Lombardia tra il 2010 e il 2011 \u00e8 sceso del 23,5%. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/la-crisi-dell\u2019adozione-il-crollo-delle-idoneita-a-milano\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-02-01T17:08:37+00:00","article_modified_time":"2012-02-01T19:45:54+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano","datePublished":"2012-02-01T17:08:37+00:00","dateModified":"2012-02-01T19:45:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/"},"wordCount":235,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/","url":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/","name":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg","datePublished":"2012-02-01T17:08:37+00:00","dateModified":"2012-02-01T19:45:54+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Adozione-a-Milano-3-coppie-aspiranti-su-10-non-sono-idonee.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/la-crisi-dell%e2%80%99adozione-il-crollo-delle-idoneita-a-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"La crisi dell\u2019adozione: il crollo delle idoneit\u00e0 a Milano"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/29664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=29664"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/29664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=29664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=29664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=29664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}