﻿


{"id":30294,"date":"2012-02-15T15:18:25","date_gmt":"2012-02-15T14:18:25","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=30294"},"modified":"2012-02-15T15:29:09","modified_gmt":"2012-02-15T14:29:09","slug":"commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/","title":{"rendered":"ForumSad: fare una legge per il sostegno a distanza"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-29547\" style=\"margin: 5px;\" title=\"Il sostegno a distanza\" src=\"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Nell&#8217;audizione del 14 febbraio alla <strong>Commissione Parlamentare Infanzia<\/strong>, voluta dal ForumSad\u00a0(Forum per il Sostegno a Distanza)\u00a0\u00e8 arrivata la promessa del Presidente di Commissione, on. Alessandra Mussolini, di inserire il sostegno a distanza nelle materie in studio della commissione stessa.<\/p>\n<p style=\"text-align: justify;\">A conclusione dell&#8217;incontro il ForumSad, <strong>rete di 100 organizzazioni<\/strong> italiane che si occupano di sostegno a distanza, lancia un appello a difesa dell&#8217;Agenzia del Terzo settore, di cui si ventilava nei giorni scorsi una prossima chiusura.<\/p>\n<p style=\"text-align: justify;\"><strong><strong>Sono 2milioni <\/strong><\/strong><strong>le famiglie italiane<\/strong> che attraverso il sostegno a distanza danno aiuto ai bambini del cosiddetto &#8220;Sud del mondo&#8221;, garantendo istruzione, controlli medici e molti altri tipi di supporti. Per capire il peso dell&#8217;aiuto: solo le organizzazioni della rete del ForumSad, 100 delle 400 in Italia che si occupano di questo ambito, hanno all&#8217;attivo 1600 progetti di cooperazione allo sviluppo, in tutti i continenti.<\/p>\n<p style=\"text-align: justify;\">Il ForumSad non ha portato all&#8217;attenzione della Commissione solo i dati di un fenomeno che, con una cooperazione allo sviluppo ai minimi storici e fanalino di coda della UE, rappresenta <strong>un aiuto consistente<\/strong> e di natura privata. <strong>Aiutare a distanza infatti vuol dire avere degli effetti importanti anche nel nostro Paese<\/strong>: far conoscere agli alunni delle scuole italiane che si pu\u00f2 aiutare i bambini meno fortunati di loro; far crescere la consapevolezza di un mondo che \u00e8 in stretta connessione. Si pensi al fenomeno dell&#8217;immigrazione. Aiutare i bambini, futuri uomini e donne, a crescere l\u00ec dove sono nati, \u00e8 prima di tutto un&#8217;azione di <strong>giustizia sociale<\/strong> e secondo poi pu\u00f2 avere <strong>effetti sui flussi migratori<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Il ForumSad chiede <strong>che si riveda la legge sulla cooperazione<\/strong>, ormai approvata 40 anni fa. Rivederla includendo e quindi valorizzando il Sostegno a distanza. Cos\u00ec da non risultare pi\u00f9 un&#8217;azione di aiuto di serie B ma gli venga riconosciuta la rilevanza. A conclusione l\u2019On. Mussolini ha richiamato le due materie di studio (indagini) che la Commissione sta portando avanti, <strong>una sui minori stranieri e l&#8217;altra su adozioni e affido<\/strong>. \u00c8 nell&#8217;ambito di quest&#8217;ultima indagine che potr\u00e0 trovare <strong>spazio uno studio sul Sostegno a distanza in Italia<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Infine ForumSad ha ribadito l&#8217;appello a <strong>non smantellare l&#8217;Agenzia del Terzo Settore<\/strong>. Organo che, all&#8217;interno l&#8217;Osservatorio del sostegno a distanza, ha prodotto <strong>per la prima volta delle linee guida del sad<\/strong> e che rappresentata un organo di trasparenza e correttezza. Da tenere ben presente la funzione di raccordo tra istituzioni, <strong>l&#8217;Agenzia \u00e8 infatti emanazione della Presidenza del Consiglio<\/strong>, e il mondo degli aiuti che vengono dal privato.<\/p>\n<p><em>(Da Vita.it, 14 febbraio 2012)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Il ForumSad chiede <strong>che si riveda la legge sulla cooperazione<\/strong>, ormai approvata 40 anni fa: rivederla includendo, e quindi valorizzando, il Sostegno a distanza. La Commissione sta portando avanti, <strong>una sui minori stranieri e l&#8217;altra su adozioni e affido<\/strong>. \u00c8 nell&#8217;ambito di quest&#8217;ultima indagine che potr\u00e0 trovare <strong>spazio uno studio sul Sostegno a distanza in Italia<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-30294","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ForumSad: fare una legge per il sostegno a distanza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-\u00abil-sostegno-a-distanza-sara-studiato\u00bb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ForumSad: fare una legge per il sostegno a distanza\" \/>\n<meta property=\"og:description\" content=\"Il ForumSad chiede che si riveda la legge sulla cooperazione, ormai approvata 40 anni fa: rivederla includendo, e quindi valorizzando, il Sostegno a distanza. La Commissione sta portando avanti, una sui minori stranieri e l&#039;altra su adozioni e affido. \u00c8 nell&#039;ambito di quest&#039;ultima indagine che potr\u00e0 trovare spazio uno studio sul Sostegno a distanza in Italia. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-\u00abil-sostegno-a-distanza-sara-studiato\u00bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-15T14:18:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-15T14:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"ForumSad: fare una legge per il sostegno a distanza\",\"datePublished\":\"2012-02-15T14:18:25+00:00\",\"dateModified\":\"2012-02-15T14:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Il-sostegno-a-distanza.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/\",\"name\":\"ForumSad: fare una legge per il sostegno a distanza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Il-sostegno-a-distanza.jpg\",\"datePublished\":\"2012-02-15T14:18:25+00:00\",\"dateModified\":\"2012-02-15T14:29:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Il-sostegno-a-distanza.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Il-sostegno-a-distanza.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ForumSad: fare una legge per il sostegno a distanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ForumSad: fare una legge per il sostegno a distanza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-\u00abil-sostegno-a-distanza-sara-studiato\u00bb\/","og_locale":"it_IT","og_type":"article","og_title":"ForumSad: fare una legge per il sostegno a distanza","og_description":"Il ForumSad chiede che si riveda la legge sulla cooperazione, ormai approvata 40 anni fa: rivederla includendo, e quindi valorizzando, il Sostegno a distanza. La Commissione sta portando avanti, una sui minori stranieri e l'altra su adozioni e affido. \u00c8 nell'ambito di quest'ultima indagine che potr\u00e0 trovare spazio uno studio sul Sostegno a distanza in Italia. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-\u00abil-sostegno-a-distanza-sara-studiato\u00bb\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-02-15T14:18:25+00:00","article_modified_time":"2012-02-15T14:29:09+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"ForumSad: fare una legge per il sostegno a distanza","datePublished":"2012-02-15T14:18:25+00:00","dateModified":"2012-02-15T14:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/"},"wordCount":430,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/","url":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/","name":"ForumSad: fare una legge per il sostegno a distanza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg","datePublished":"2012-02-15T14:18:25+00:00","dateModified":"2012-02-15T14:29:09+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Il-sostegno-a-distanza.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/commissione-parlamentare-infanzia-%c2%abil-sostegno-a-distanza-sara-studiato%c2%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"ForumSad: fare una legge per il sostegno a distanza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:45:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=30294"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30294\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=30294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=30294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=30294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}