﻿


{"id":30798,"date":"2012-02-27T16:16:54","date_gmt":"2012-02-27T15:16:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=30798"},"modified":"2012-02-27T16:17:18","modified_gmt":"2012-02-27T15:17:18","slug":"regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/","title":{"rendered":"Regione Lombardia: a che serve nominare il Garante dell&#8217;Infanzia?"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-30809\" style=\"margin: 5px;\" title=\"Minori fuori famiglia\" src=\"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Il Coordinamento Per I Diritti Dell\u2019Infanzia e dell\u2019Adolescenza in Italia e nel mondo (<strong>PIDIDA<\/strong>) apprende con viva preoccupazione <strong>l\u2019intenzione da parte della Giunta regionale della Lombardia di cancellare la figura del Garante<\/strong> dei Diritti dell\u2019Infanzia e dell\u2019Adolescenza.<\/p>\n<p style=\"text-align: justify;\">Prevista dalla <strong>Legge Regionale n. 6 del 2009<\/strong> che istituisce in Lombardia la figura del Garante dell\u2019Infanzia e dell\u2019Adolescenza, la nomina del Garante regionale <strong>\u00e8 obbligatoria<\/strong>. Soltanto Veneto, Emilia-Romagna, Toscana, Lazio, Marche, Molise, Puglia, Calabria e la provincia di Bolzano hanno effettivamente nominato un Garante regionale o un Pubblico Tutore dei diritti dell\u2019Infanzia.<\/p>\n<p style=\"text-align: justify;\">Al fine di assicurare e dare priorit\u00e0 alla piena attuazione dei diritti dell\u2019infanzia e dell\u2019adolescenza, <strong>il Garante deve svolgere la propria attivit\u00e0 in piena autonomia<\/strong>. Per questo, anche al fine di evitare possibili conflitti di interesse, si afferma la necessit\u00e0 di <strong>istituire una figura indipendente ed esclusivamente dedicata<\/strong> a cui affidare la promozione, la tutela dei diritti e il coordinamento e la valorizzazione degli organi e degli enti che si occupano di infanzia.<\/p>\n<p style=\"text-align: justify;\">Per questi motivi il PIDIDA <strong>denuncia non soltanto la proposta di abolizione della norma<\/strong>, ma anche <strong>la mancata approvazione del regolamento attuativo<\/strong> che avrebbe dovuto portare alla nomina del Garante stesso, in ottemperanza alla legge Regionale 6\/2009 e al Commento Generale n. 2 del Comitato ONU per i Diritti dell\u2019Infanzia che presuppone l\u2019istituzione del Garante Nazionale e dei Garanti Regionali.<\/p>\n<p style=\"text-align: justify;\">Aderiscono all\u2019appello <strong>le associazioni del PIDIDA Lombardia<\/strong>: ABCitt\u00e0, Ai.Bi. Associazione Amici dei Bambini, L\u2019Albero della Vita, Ambiente Acqua Onlus, ANFAA, Arciragazzi, Associazione Valeria Onlus, Celim Milano, CIAI, CNCA Lombardia \u2013 Coordinamento Nazionale delle Comunit\u00e0 d\u2019Accoglienza, Fratelli dell\u2019Uomo, Legambiente, Save the Children Italia, SOS Villaggi dei Bambini, UNICEF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Prevista dalla <strong>Legge Regionale n. 6 del 2009<\/strong> che istituisce in Lombardia la figura del Garante dell\u2019Infanzia e dell\u2019Adolescenza, la nomina del Garante regionale <strong>\u00e8 obbligatoria<\/strong>. Soltanto Veneto, Emilia-Romagna, Toscana, Lazio, Marche, Molise, Puglia, Calabria e la provincia di Bolzano hanno effettivamente nominato un Garante regionale o un Pubblico Tutore dei diritti dell\u2019Infanzia. <a href=\"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/\"><strong>LEGGI TUTTO<\/strong>&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-30798","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Regione Lombardia: a che serve nominare il Garante dell&#039;Infanzia? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regione Lombardia: a che serve nominare il Garante dell&#039;Infanzia?\" \/>\n<meta property=\"og:description\" content=\"Prevista dalla Legge Regionale n. 6 del 2009 che istituisce in Lombardia la figura del Garante dell\u2019Infanzia e dell\u2019Adolescenza, la nomina del Garante regionale \u00e8 obbligatoria. Soltanto Veneto, Emilia-Romagna, Toscana, Lazio, Marche, Molise, Puglia, Calabria e la provincia di Bolzano hanno effettivamente nominato un Garante regionale o un Pubblico Tutore dei diritti dell\u2019Infanzia. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-27T15:16:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-27T15:17:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Regione Lombardia: a che serve nominare il Garante dell&#8217;Infanzia?\",\"datePublished\":\"2012-02-27T15:16:54+00:00\",\"dateModified\":\"2012-02-27T15:17:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Minori-fuori-famiglia1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/\",\"name\":\"Regione Lombardia: a che serve nominare il Garante dell'Infanzia? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Minori-fuori-famiglia1.jpg\",\"datePublished\":\"2012-02-27T15:16:54+00:00\",\"dateModified\":\"2012-02-27T15:17:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Minori-fuori-famiglia1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Minori-fuori-famiglia1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regione Lombardia: a che serve nominare il Garante dell&#8217;Infanzia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regione Lombardia: a che serve nominare il Garante dell'Infanzia? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/","og_locale":"it_IT","og_type":"article","og_title":"Regione Lombardia: a che serve nominare il Garante dell'Infanzia?","og_description":"Prevista dalla Legge Regionale n. 6 del 2009 che istituisce in Lombardia la figura del Garante dell\u2019Infanzia e dell\u2019Adolescenza, la nomina del Garante regionale \u00e8 obbligatoria. Soltanto Veneto, Emilia-Romagna, Toscana, Lazio, Marche, Molise, Puglia, Calabria e la provincia di Bolzano hanno effettivamente nominato un Garante regionale o un Pubblico Tutore dei diritti dell\u2019Infanzia. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-02-27T15:16:54+00:00","article_modified_time":"2012-02-27T15:17:18+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Regione Lombardia: a che serve nominare il Garante dell&#8217;Infanzia?","datePublished":"2012-02-27T15:16:54+00:00","dateModified":"2012-02-27T15:17:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/"},"wordCount":291,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/","url":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/","name":"Regione Lombardia: a che serve nominare il Garante dell'Infanzia? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg","datePublished":"2012-02-27T15:16:54+00:00","dateModified":"2012-02-27T15:17:18+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Minori-fuori-famiglia1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/regione-lombardia-a-che-serve-nominare-il-garante-dellinfanzia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Regione Lombardia: a che serve nominare il Garante dell&#8217;Infanzia?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=30798"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30798\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=30798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=30798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=30798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}