﻿


{"id":30929,"date":"2012-02-29T17:18:55","date_gmt":"2012-02-29T16:18:55","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=30929"},"modified":"2012-02-29T17:31:34","modified_gmt":"2012-02-29T16:31:34","slug":"agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/","title":{"rendered":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-30712\" style=\"margin: 5px;\" title=\"Governo Monti, chiusa l'Agenzia Terzo Settore\" src=\"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Il Consiglio dei Ministri ha deciso venerd\u00ec la soppressione dell\u2019Agenzia per il Terzo settore, affidandone, per il futuro, <strong>le competenze al Ministero del lavoro e delle politiche sociali<\/strong>. Con l\u2019obiettivo di \u2018contenere\u2019 la spesa pubblica, si perde dunque uno strumento di promozione, ma anche di vigilanza e controllo, fondamentale per il terzo settore.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Siamo fortemente contrari<\/strong>\u00a0&#8211; dichiara il Portavoce del Forum, <strong>Andrea Olivero<\/strong>\u00a0&#8211; a questa decisione presa dal Governo, peraltro in totale contraddizione con i segnali di attenzione che finora ci aveva mostrato. L\u2019Agenzia per il Terzo settore, seppur ente di emanazione governativa, ha svolto un importante ruolo di <strong>\u2018terziet\u00e0\u2019 tra organizzazioni non profit e istituzioni<\/strong>, ruolo che le ha permesso di essere autorevole strumento di controllo, trasparenza e promozione del terzo settore in modo autonomo e non immediatamente legato all\u2019azione di governo. Sopprimere l\u2019Agenzia \u2013 prosegue il Portavoce \u2013 per risparmi del tutto inconsistenti, \u00e8 quindi una scelta miope, foriera di gravi conseguenze per tutto il terzo settore, che ne va a minare la sua articolazione organizzativa e soprattutto la \u00a0sua autonomia\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abChiudere l\u2019Agenzia \u2013 prosegue il Portavoce \u2013 e affidarne le competenze al Ministero del Lavoro e delle politiche sociali \u00e8 <strong>un brutto segnale politico<\/strong>; <strong>significa infatti ridurre il terzo settore al solo ambito del welfare<\/strong>, non riconoscerne la multiformit\u00e0 delle iniziative e il ruolo fondamentale di leva per la crescita del Paese. \u00c8 un\u2019iniziativa che <strong>va a sommarsi ad altri brutti segnali che il Governo ha dato nell\u2019ultimo periodo<\/strong>, <strong>come le contraddittorie dichiarazioni sul 5&#215;1000, l\u2019estensione dell\u2019Ici e dell\u2019Imu, e l\u2019ulteriore inasprimento dei controlli fiscali sul terzo settore<\/strong>\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abInfine \u2013 conclude il Portavoce \u2013 la decisione \u00e8 tanto pi\u00f9 grave quanto il fatto che sia stata <strong>presa senza alcuna interlocuzione con il nostro mondo<\/strong>. Da parte nostra ci siamo sempre posti in un ottica di dialogo con il Governo e da sempre abbiamo rappresentato <strong>un soggetto vocato a rappresentare il bene comune<\/strong>, non certo una lobby di interessi. Non ascoltare le nostre istanze \u00e8 una grave scorrettezza e manifesta un\u2019assoluta mancanza di sensibilit\u00e0. Ci aspettiamo che, alle prese di posizione avverse a questa risoluzione, arrivate da parte di numerosi esponenti di tutte le forze politiche, ne seguano ulteriori e <strong>che il provvedimento venga modificato dal Parlamento.<\/strong> A sostegno di questa nostra richiesta <strong>attiveremo da subito azioni di sensibilizzazione e mobilitazione tra tutte le nostre associazioni e nel territorio<\/strong>. Al Governo chiediamo che mostri segnali di attenzione verso il terzo settore, in coerenza con quel senso di responsabilit\u00e0 e partecipazione che da sempre sosteniamo\u00bb.<\/p>\n<p style=\"text-align: justify;\">(Dal Forum nazionale del terzo Settore, 27 febbraio 2012)<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">\u00ab<strong>Siamo fortemente contrari<\/strong> &#8211; dichiara il Portavoce del Forum, <strong>Andrea Olivero<\/strong> \u2013 a questa decisione presa dal Governo, peraltro in totale contraddizione con i segnali di attenzione che finora ci aveva mostrato. L\u2019Agenzia per il Terzo settore, seppur ente di emanazione governativa, ha svolto un importante ruolo di <strong>\u2018terziet\u00e0\u2019 tra organizzazioni non profit e istituzioni\u00bb<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-30929","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura\" \/>\n<meta property=\"og:description\" content=\"\u00abSiamo fortemente contrari - dichiara il Portavoce del Forum, Andrea Olivero \u2013 a questa decisione presa dal Governo, peraltro in totale contraddizione con i segnali di attenzione che finora ci aveva mostrato. L\u2019Agenzia per il Terzo settore, seppur ente di emanazione governativa, ha svolto un importante ruolo di \u2018terziet\u00e0\u2019 tra organizzazioni non profit e istituzioni\u00bb. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-29T16:18:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-29T16:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura\",\"datePublished\":\"2012-02-29T16:18:55+00:00\",\"dateModified\":\"2012-02-29T16:31:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/\"},\"wordCount\":436,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/\",\"name\":\"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\",\"datePublished\":\"2012-02-29T16:18:55+00:00\",\"dateModified\":\"2012-02-29T16:31:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/","og_locale":"it_IT","og_type":"article","og_title":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura","og_description":"\u00abSiamo fortemente contrari - dichiara il Portavoce del Forum, Andrea Olivero \u2013 a questa decisione presa dal Governo, peraltro in totale contraddizione con i segnali di attenzione che finora ci aveva mostrato. L\u2019Agenzia per il Terzo settore, seppur ente di emanazione governativa, ha svolto un importante ruolo di \u2018terziet\u00e0\u2019 tra organizzazioni non profit e istituzioni\u00bb. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-02-29T16:18:55+00:00","article_modified_time":"2012-02-29T16:31:34+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura","datePublished":"2012-02-29T16:18:55+00:00","dateModified":"2012-02-29T16:31:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/"},"wordCount":436,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/","url":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/","name":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg","datePublished":"2012-02-29T16:18:55+00:00","dateModified":"2012-02-29T16:31:34+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Governo-Monti-la-ratifica-della-Convenzione-dellAja1.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/agenzia-del-terzo-settore-dal-governo-e-ordine-di-chiusura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Agenzia del Terzo Settore, dal Governo \u00e8 ordine di chiusura"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:47:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=30929"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/30929\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=30929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=30929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=30929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}