﻿


{"id":31783,"date":"2012-03-22T17:23:28","date_gmt":"2012-03-22T16:23:28","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=31783"},"modified":"2012-03-22T17:25:12","modified_gmt":"2012-03-22T16:25:12","slug":"toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/","title":{"rendered":"Toscana: chiss\u00e0 se arriveranno i contributi per l&#8217;adozione internazionale"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg\"><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-29226\" style=\"margin: 5px;\" title=\"Regione Toscana\" src=\"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/regione-Toscana-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/em><\/a>L\u2019assessore toscano al Welfare, Salvatore Allocca, ha risposto a un\u2019interrogazione del consigliere regionale <strong>Paolo Bambagioni<\/strong>, che voleva verificare lo stato di attuazione della legge regionale del novembre 2009. Il consigliere aveva presentato un\u2019interrogazione sugli interventi di sostegno messi in campo dalla Regione Toscana <strong>a favore delle coppie impegnate in adozioni internazionali<\/strong>.<\/p>\n<p style=\"text-align: justify;\">L\u2019interrogazione originava dalla volont\u00e0 di conoscere lo stato delle cose. La legge che prevede azioni di sostegno in questo campo risale al novembre 2009 ed <strong>ancora non sono stati erogati i contributi previsti<\/strong>. \u00abIl mio intento era verificare l\u2019attuazione della legge che prevede la concessione di contributi alle coppie che scelgono di fare delle adozioni internazionali e al tempo stesso, dopo aver conosciuto i motivi dei ritardi, sollecitare la Giunta regionale a procedere sulla strada indicata dalla normativa\u00bb, ha affermato Bambagioni. Che ha detto di avere ascoltato con \u00abattenzione ed interesse quanto affermato dall\u2019assessore competente\u00bb.<\/p>\n<p style=\"text-align: justify;\">L\u2019assessore Allocca, da parte sua, ha assicurato che l<strong>a Regione<\/strong><strong> ha utilizzato i due anni ormai passati<\/strong>, oltre che per redigere il decreto attuativo della legge stessa, \u00ab<strong>per coinvolgere gli istituti bancari e le associazioni e gli enti che si occupano di adozione internazionale<\/strong>\u00bb. Tutto questo lavoro, ha assicurato Allocca, \u00absi concretizzer\u00e0 al pi\u00f9 presto in due bandi per fare in modo che chi ha i requisiti potr\u00e0 accedere ai contributi e ai prestiti\u00bb, fermo restando che \u00abi contributi potranno essere erogati solo a chi ha un imponibile inferiore a 75 mila euro annui\u00bb.<\/p>\n<p style=\"text-align: justify;\"><em>(Da Met Firenze, 21 marzo 2012)<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">L\u2019assessore toscano al Welfare, Salvatore Allocca, ha risposto a un\u2019interrogazione del consigliere regionale <strong>Paolo Bambagioni<\/strong>, che voleva verificare lo stato di attuazione della legge regionale del novembre 2009.\u00a0Osso della disputa, gli\u00a0interventi di sostegno messi in campo dalla Regione Toscana <strong>a favore delle coppie impegnate in adozioni internazionali<\/strong>. <strong><a href=\"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-31783","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Toscana: chiss\u00e0 se arriveranno i contributi per l&#039;adozione internazionale - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toscana: chiss\u00e0 se arriveranno i contributi per l&#039;adozione internazionale\" \/>\n<meta property=\"og:description\" content=\"L\u2019assessore toscano al Welfare, Salvatore Allocca, ha risposto a un\u2019interrogazione del consigliere regionale Paolo Bambagioni, che voleva verificare lo stato di attuazione della legge regionale del novembre 2009.\u00a0Osso della disputa, gli\u00a0interventi di sostegno messi in campo dalla Regione Toscana a favore delle coppie impegnate in adozioni internazionali. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-22T16:23:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-03-22T16:25:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Toscana: chiss\u00e0 se arriveranno i contributi per l&#8217;adozione internazionale\",\"datePublished\":\"2012-03-22T16:23:28+00:00\",\"dateModified\":\"2012-03-22T16:25:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/\"},\"wordCount\":258,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/regione-Toscana.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/\",\"name\":\"Toscana: chiss\u00e0 se arriveranno i contributi per l'adozione internazionale - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/regione-Toscana.jpg\",\"datePublished\":\"2012-03-22T16:23:28+00:00\",\"dateModified\":\"2012-03-22T16:25:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/regione-Toscana.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/regione-Toscana.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toscana: chiss\u00e0 se arriveranno i contributi per l&#8217;adozione internazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Toscana: chiss\u00e0 se arriveranno i contributi per l'adozione internazionale - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Toscana: chiss\u00e0 se arriveranno i contributi per l'adozione internazionale","og_description":"L\u2019assessore toscano al Welfare, Salvatore Allocca, ha risposto a un\u2019interrogazione del consigliere regionale Paolo Bambagioni, che voleva verificare lo stato di attuazione della legge regionale del novembre 2009.\u00a0Osso della disputa, gli\u00a0interventi di sostegno messi in campo dalla Regione Toscana a favore delle coppie impegnate in adozioni internazionali. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-03-22T16:23:28+00:00","article_modified_time":"2012-03-22T16:25:12+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Toscana: chiss\u00e0 se arriveranno i contributi per l&#8217;adozione internazionale","datePublished":"2012-03-22T16:23:28+00:00","dateModified":"2012-03-22T16:25:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/"},"wordCount":258,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/","name":"Toscana: chiss\u00e0 se arriveranno i contributi per l'adozione internazionale - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg","datePublished":"2012-03-22T16:23:28+00:00","dateModified":"2012-03-22T16:25:12+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/regione-Toscana.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/toscana-chissa-se-arriveranno-i-contributi-per-ladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Toscana: chiss\u00e0 se arriveranno i contributi per l&#8217;adozione internazionale"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:47:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/31783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=31783"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/31783\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=31783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=31783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=31783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}