﻿


{"id":31935,"date":"2012-03-27T14:36:49","date_gmt":"2012-03-27T12:36:49","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=31935"},"modified":"2012-06-06T18:00:27","modified_gmt":"2012-06-06T16:00:27","slug":"adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/","title":{"rendered":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-27398\" style=\"margin: 5px;\" title=\"AiBi, verso la riforma della legge sulle adozioni internazionali\" src=\"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Sul calo delle idoneit\u00e0<\/strong> non concede terreno (\u00abAuspicabile: ci vuole rigore\u00bb, ha detto) ma apre su quanto chiesto dalle famiglie durante uno degli ultimi sondaggi lanciati da AiBiNews. <strong>S\u00ec ai termini perentori di legge<\/strong> nell\u2019emissione dell\u2019idoneit\u00e0 alle coppie, \u00e8 la risposta di <strong>Pasquale Andria<\/strong>, presidente del Tribunale per i Minorenni di Salerno.<\/p>\n<p style=\"text-align: justify;\"><strong>Presidente Andria, le adozioni internazionali sono in crisi. Qual \u00e8 la sua interpretazione?<br \/>\n<\/strong>L\u2019Italia, che era tra i Paesi pi\u00f9 avanti nell\u2019adozione, seconda solo agli Stati Uniti, oggi \u00e8 un Paese in difficolt\u00e0. Credo che il dato potrebbe essere positivo solo se fosse corrispondente a una maggiore cooperazione con i Paesi esteri e a una pi\u00f9 adeguata applicazione del principio di sussidiariet\u00e0. Ma ritengo invece che non sia cos\u00ec, considerato che aumentano le condizioni di miseria in quei Paesi. Dunque il dato \u00e8 preoccupante.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali le cause, a suo giudizio?<br \/>\n<\/strong>Vi sono ragioni contingenti alla crisi delle adozioni internazionali: c\u2019\u00e8 scarsa disponibilit\u00e0 di coppie ad accogliere adolescenti, il cui numero \u00e8 in crescita. Vi sono coppie che, in una certa quantit\u00e0, si rivolgono all\u2019iter adottivo dopo essere passate per tentativi di fecondazione assistita, e questo fa s\u00ec che vi arrivino in et\u00e0 pi\u00f9 avanzata, quando \u00e8 difficile adottare.<\/p>\n<p style=\"text-align: justify;\"><strong>Un calo del 49% nell\u2019emissione dei decreti d\u2019idoneit\u00e0, a partire dal 2006. Non \u00e8 troppa, tutta questa severit\u00e0 da parte dei Tribunali?<br \/>\n<\/strong>La mia posizione \u00e8 che l\u2019idoneit\u00e0 debba essere rilasciata dai Tribunali con molta attenzione. La legge d\u00e0 al giudice il compito di valutare la domanda di disponibilit\u00e0 di una coppia all\u2019adozione internazionale \u2013 si badi: \u00e8 una domanda di disponibilit\u00e0, non una domanda di adozione \u2013. Non esiste un diritto delle coppie ad adottare, esiste il diritto del bambino a un\u2019adozione, e la migliore adozione possibile. In questo senso \u00e8 giusto che i Tribunali siano molto attenti nel rilasciare decreti. Mi sembra poco prudente tornare a cifre come quelle degli anni passati, quando si approvava quasi la totalit\u00e0 delle domande. Un\u2019adozione non riuscita crea sofferenze aggiuntive nel bambino.<\/p>\n<p style=\"text-align: justify;\"><strong>Questo<\/strong> <strong>calo del 49% \u00e8 un dato vistoso<\/strong> \u2013 non avevo presente che fosse cos\u00ec \u2013. Ma direi che \u00e8 auspicabile. Occorre rigore. Specie se il minore non \u00e8 piccolissimo.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cosa pensa se in Italia fosse introdotta l\u2019idoneit\u00e0 amministrativa, come accade in Europa?<br \/>\n<\/strong>Non sarei d\u2019accordo. Il ruolo del giudici in Italia \u00e8 un ruolo di terziet\u00e0 che garantisce maggior sicurezza.<\/p>\n<p style=\"text-align: justify;\"><strong>Non pensa che invece contribuisca ad allungare i tempi dell\u2019iter?<br \/>\n<\/strong>I tempi maggiori li impieghiamo nell\u2019attendere che ci rispondano i servizi sociali. Il problema non \u00e8 far presto, ma fare bene. Non tutti possono adottare, \u00e8 la mia posizione.<\/p>\n<p style=\"text-align: justify;\"><strong>Nel sondaggio di AiBiNews <em>Come abbreviare l\u2019iter?<\/em> le coppie votanti hanno espresso la preferenza di inserire termini perentori di idoneit\u00e0, per legge. \u00c8 dello stesso parere?<br \/>\n<\/strong><strong>Ecco, questa potrebbe essere una buona idea<\/strong>. I termini attuali sono di 6 mesi, ma ci sono criticit\u00e0 dovute alla disponibilit\u00e0 di risorse. Se fossero fornite pi\u00f9 risorse, io sarei d\u2019accordo con questa proposta.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\"><strong>Sul calo delle idoneit\u00e0<\/strong> non concede terreno (\u00abAuspicabile: ci vuole rigore\u00bb, ha detto) ma apre su quanto chiesto dalle famiglie durante uno degli ultimi sondaggi lanciati da AiBiNews. <strong>S\u00ec ai termini perentori di legge<\/strong> nell\u2019emissione dell\u2019idoneit\u00e0 alle coppie, \u00e8 la risposta di <strong>Pasquale Andria<\/strong>, presidente del Tribunale per i Minorenni di Salerno. <strong><a href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-31935","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-\u00absi-ai-termini-perentori-di-legge\u00bb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb\" \/>\n<meta property=\"og:description\" content=\"Sul calo delle idoneit\u00e0 non concede terreno (\u00abAuspicabile: ci vuole rigore\u00bb, ha detto) ma apre su quanto chiesto dalle famiglie durante uno degli ultimi sondaggi lanciati da AiBiNews. S\u00ec ai termini perentori di legge nell\u2019emissione dell\u2019idoneit\u00e0 alle coppie, \u00e8 la risposta di Pasquale Andria, presidente del Tribunale per i Minorenni di Salerno. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-\u00absi-ai-termini-perentori-di-legge\u00bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-27T12:36:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-06T16:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb\",\"datePublished\":\"2012-03-27T12:36:49+00:00\",\"dateModified\":\"2012-06-06T16:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/\"},\"wordCount\":496,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/\",\"name\":\"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\",\"datePublished\":\"2012-03-27T12:36:49+00:00\",\"dateModified\":\"2012-06-06T16:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-\u00absi-ai-termini-perentori-di-legge\u00bb\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb","og_description":"Sul calo delle idoneit\u00e0 non concede terreno (\u00abAuspicabile: ci vuole rigore\u00bb, ha detto) ma apre su quanto chiesto dalle famiglie durante uno degli ultimi sondaggi lanciati da AiBiNews. S\u00ec ai termini perentori di legge nell\u2019emissione dell\u2019idoneit\u00e0 alle coppie, \u00e8 la risposta di Pasquale Andria, presidente del Tribunale per i Minorenni di Salerno. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-\u00absi-ai-termini-perentori-di-legge\u00bb\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-03-27T12:36:49+00:00","article_modified_time":"2012-06-06T16:00:27+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb","datePublished":"2012-03-27T12:36:49+00:00","dateModified":"2012-06-06T16:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/"},"wordCount":496,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/","name":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg","datePublished":"2012-03-27T12:36:49+00:00","dateModified":"2012-06-06T16:00:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/AiBi-verso-la-riforma-della-legge-sulle-adozioni-internazionali.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-verso-la-nuova-legge-andria-%c2%absi-ai-termini-perentori-di-legge%c2%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali, verso la nuova legge. Andria: \u00abS\u00ec ai termini perentori di legge\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:51:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/31935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=31935"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/31935\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=31935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=31935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=31935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}