﻿


{"id":32520,"date":"2012-04-12T15:13:18","date_gmt":"2012-04-12T13:13:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=32520"},"modified":"2012-04-12T16:01:31","modified_gmt":"2012-04-12T14:01:31","slug":"verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/","title":{"rendered":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32526\" style=\"margin: 5px;\" title=\"Family2012100\" src=\"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/a>Una festa per la famiglia. Per riflettere, per dialogare, parlare di fatiche e speranze. <\/strong>Saranno tante le comunit\u00e0 che tra il 14 e il 15 Aprile si ritroveranno in preparazione al VII Incontro mondiale delle famiglie.\u00a0Come a<strong> Gerenzano (Va) <\/strong>dove la festa si svolger\u00e0 al Palazzetto dello Sport <strong>domenica 15 Aprile. <\/strong>\u201cL\u2019obiettivo di questa iniziativa \u00e8 quello di sensibilizzare e promuovere l\u2019accoglienza delle famiglie\u201d, spiega Sandro Imparato, Presidente del Centro Culturale San Pietro e Paolo di Gerenzano. Per l\u2019occasione ci sar\u00e0 un\u2019unica messa alle 10.30, un pic-nic insieme alle 12.30, io giochi alle 14.00 e, dopo la preghiera comunitaria, la merenda alle 16.30.<\/p>\n<p style=\"text-align: justify;\"><strong>Sabato 14<\/strong>, invece, dalle 10 alle 19 l\u2019appuntamento \u00e8 a <strong>Cesano Boscone (Mi<\/strong>). Per tutto l\u2019arco della giornata, le realt\u00e0 che si occupano di progetti per le famiglie saranno presenti stand con materiali informativi per presentare i loro servizi e le attivit\u00e0. Presso l\u2019oratorio San Giovanni Battista, sar\u00e0 possibile visitare la mostra a cura delle scuole e dei gruppi di catechismo che hanno partecipato al concorso diocesano \u201cRacconta Family\u201d. A partire dalle 11, sar\u00e0 allestito in Piazza San Giovanni Battista, un punto di ristoro per il pranzo con un men\u00f9 a misura di famiglia. Nel pomeriggio, dalle 14,\u00a0 ci sar\u00e0 l\u2019inizio delle attivit\u00e0 per i bambini a cui seguir\u00e0 la merenda alle 16.30. I genitori, mentre i bambini si divertono, potranno partecipare al Convegno delle 16.30 sul welfare familiare, presso la Sala delle Carrozze ( in Villa Marazzi) con Cesare Palombi, referente di Carovana per la Famiglia e Lilia di Giuseppe, Assessore ai servizi sociali e Vicesindaco di Cesano Boscone. Seguir\u00e0 nel cortile della villa, un aperitivo con intrattenimento musicale.<\/p>\n<p style=\"text-align: justify;\"><strong>A Busto Arsizio (Va), la festa si terr\u00e0 domenica 15.<\/strong> Dalle 15 alle 17.45 negli spazi del Museo Tessile in Via Volta 6\/8, si potr\u00e0 incontrare la Carovana per la famiglia, un progetto nato dall\u2019Associazione di solidariet\u00e0 familiare \u201cSpazio famiglia\u201d dell\u2019Azione Cattolica e delle Acli Lombardia, per diffondere sul territorio l\u2019idea che la famiglia \u00e8 una risorsa e un bene per la comunit\u00e0. Ci saranno poi giochi per tutti e uno spazio per i pi\u00f9 piccoli. Alle 18, il decano mons. Franco Agnesi, insieme ai sacerdoti della citt\u00e0, celebrer\u00e0 la Messa nella Chiesa di San Michele. Dopo la messa, la serata si concluder\u00e0 con un coro Gospel.<\/p>\n<p style=\"text-align: justify;\"><strong>A Paderno Dugnano e Varedo, inizier\u00e0 alle 20.45 di sabato 14 Aprile<\/strong> con un incontro nel Salone \u201cMonsignor Buzzi\u201d (via De Marchi a Paderno) sul tema \u201cUna scelta di vita\u201d su iniziativa dell\u2019Azione Cattolica decanale, e che vedr\u00e0 la partecipazione di Gianna Emanuela Molla, figlia di Santa Gianna Beretta Molla. Domenica 15 inoltre dalle 11 alle 18 presso il Parco Cava Nord di Paderno Dugnano ci saranno gli stand di alcune associazioni di volontariato e un Infopoint dedicato al \u201cFamily 2012\u201d. Alle 12 all\u2019anfiteatro la Santa Messa presieduta dal Vescovo Angelo Mascheroni. Seguir\u00e0 al termine, il pranzo al sacco e momenti di gioco; dalle 15.30 si esibiranno alcuni gruppi musicali.<\/p>\n<p style=\"text-align: justify;\">Anche <strong>Melegnano<\/strong>, Comune in Provincia di Milano, ha voluto partecipare all\u2019Incontro mondiale con un&#8217;esposizione dal nome <strong><em>La famiglia, anima del mondo<\/em><\/strong>, realizzata con il prezioso contributo del Centro Culturale San Benedetto di Milano e con il supporto delle Parrocchie di Melegnano e del vicino Comune di Vizzolo Predabissi, sul tema della famiglia, intesa come valore fondamentale per la societ\u00e0 e per la Chiesa. La mostra testimonia come la famiglia fosse una realt\u00e0 gi\u00e0 stimata <strong>nelle culture pre-cristiane<\/strong>; descrive inoltre lo stato attuale della famiglia in Italia e nel mondo con l&#8217;aiuto di tabelle statistiche e dei principali scritti di Magistero e di documenti quali la Costituzione Italiana e il Codice Civile. La mostra ha una seconda parte, dal titolo<em> Santa Gianna Beretta Molla. Una vita per la vita<\/em>: 16 pannelli curati dalla Fondazione omonima, che ricostruiscono attraverso testi e fotografie la vita di questa santa cos\u00ec attuale, moglie e madre eroica fino al dono della vita. La mostra rimarr\u00e0 esposta a ingresso libero fino al 15 aprile nella Sala dell\u2019Imperatore del Castello Mediceo di Melegnano, in piazza della Vittoria, dalle 9.30 alle 12 e dalle 16 alle 19. Info e prenotazioni: tel. 029834107, email <a href=\"mailto:family2012.melegnanovizzolo@gmail.com\">family2012.melegnanovizzolo@gmail.com<\/a>. Sar\u00e0 attivo un servizio bookshop per l&#8217;acquisto di testi e <strong>per le informazioni circa gli eventi del VII Incontro Mondiale delle Famiglie<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\"><strong>Una festa per la famiglia. Per riflettere, per dialogare, parlare di fatiche e speranze. <\/strong>Saranno tante le comunit\u00e0 che tra il 14 e il 15 Aprile si ritroveranno in preparazione al VII Incontro mondiale delle famiglie.\u00a0Come a<strong> Gerenzano<\/strong> (Va), dove la festa si svolger\u00e0 al Palazzetto dello Sport, domenica<strong> 15 Aprile. <a href=\"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/\">LEGGI TUTTO&#8230;<\/a><\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-32520","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano\" \/>\n<meta property=\"og:description\" content=\"Una festa per la famiglia. Per riflettere, per dialogare, parlare di fatiche e speranze. Saranno tante le comunit\u00e0 che tra il 14 e il 15 Aprile si ritroveranno in preparazione al VII Incontro mondiale delle famiglie.\u00a0Come a Gerenzano (Va), dove la festa si svolger\u00e0 al Palazzetto dello Sport, domenica 15 Aprile. LEGGI TUTTO...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-12T13:13:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-04-12T14:01:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano\",\"datePublished\":\"2012-04-12T13:13:18+00:00\",\"dateModified\":\"2012-04-12T14:01:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Family2012100.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/\",\"name\":\"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Family2012100.jpg\",\"datePublished\":\"2012-04-12T13:13:18+00:00\",\"dateModified\":\"2012-04-12T14:01:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Family2012100.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Family2012100.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/","og_locale":"it_IT","og_type":"article","og_title":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano","og_description":"Una festa per la famiglia. Per riflettere, per dialogare, parlare di fatiche e speranze. Saranno tante le comunit\u00e0 che tra il 14 e il 15 Aprile si ritroveranno in preparazione al VII Incontro mondiale delle famiglie.\u00a0Come a Gerenzano (Va), dove la festa si svolger\u00e0 al Palazzetto dello Sport, domenica 15 Aprile. LEGGI TUTTO...","og_url":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-04-12T13:13:18+00:00","article_modified_time":"2012-04-12T14:01:31+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano","datePublished":"2012-04-12T13:13:18+00:00","dateModified":"2012-04-12T14:01:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/"},"wordCount":707,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/","url":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/","name":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg","datePublished":"2012-04-12T13:13:18+00:00","dateModified":"2012-04-12T14:01:31+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Family2012100.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/verso-family-2012-le-feste-che-animano-gerenzano-cesano-boscone-busto-arsizio-paderno-dugnano-varedo-e-melegnano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Verso Family 2012: le feste che animano Gerenzano, Cesano Boscone, Busto Arsizio, Paderno Dugnano, Varedo e Melegnano"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:59:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/32520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=32520"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/32520\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=32520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=32520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=32520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}