﻿


{"id":34904,"date":"2012-06-05T19:34:26","date_gmt":"2012-06-05T17:34:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=34904"},"modified":"2012-06-06T17:57:08","modified_gmt":"2012-06-06T15:57:08","slug":"max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/","title":{"rendered":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-34906\" style=\"margin: 5px;\" title=\"Max Laudadio in conferenza stampa di Ai.Bi., il 31 maggio\" src=\"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-150x86.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-96x55.jpg 96w, https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019adesione popolare al Manifesto brucia le tappe anche grazie al servizio che <strong>Max Laudadio<\/strong> ha voluto dedicare su Striscia la Notizia. Laudadio \u00e8 tra i primi ad aver dato la sua firma. Lo intervistiamo.<\/p>\n<p style=\"text-align: justify;\"><strong>Max, perch\u00e9 hai firmato?<br \/>\n<\/strong>Perch\u00e9 c\u2019\u00e8 necessit\u00e0 di un\u2019urgente modifica della legge che regola l\u2019adozione internazionale. Attualmente il sistema complica le procedure anzich\u00e9 agevolarle: finch\u00e9 non cambieremo la normativa non riusciremo a<strong> chiudere gli orfanotrofi<\/strong>, cosa che deve essere il principale obiettivo di tutti noi che ci battiamo per i bambini abbandonati.<\/p>\n<p style=\"text-align: justify;\"><strong>Hai preso la questione molto a cuore e la stai affrontando di petto: c\u2019\u00e8 una ragione particolare per questo?<br \/>\n<\/strong>Ho avuto modo di confrontarmi in prima persona con il <strong>marasma<\/strong> e la <strong>follia<\/strong> che le coppie sono obbligate ad affrontare quando intraprendono il percorso adottivo. Mi ero gi\u00e0 avvicinato alla questione da un punto di vista tecnico e avevo avuto modo di vederne le difficolt\u00e0; ma, non appena sono stato direttamente coinvolto, mi sono reso conto che il problema \u00e8 molto pi\u00f9 grande di quanto immaginassi. Se si trova una coppia felice, che si ama, che ha figli e che vuole adottare, <strong>non capisco perch\u00e9<\/strong> vada incontro ad atteggiamenti volti a scoraggiarla e a scartarla!<\/p>\n<p style=\"text-align: justify;\"><strong>Si \u00e8 diffusa anche in Italia una certa opinione che i bambini abbandonati dovrebbero, per il loro bene, continuare a vivere nel loro Paese. Cosa ne pensi?<br \/>\n<\/strong>Sono chiacchiere! L\u2019Italia \u00e8 un Paese di facciata, nel quale i politici che tengono alla famiglia si contano sulla punta delle dita. Se i bambini abbandonati farebbero meglio a restare nel loro Paese? S\u00ec, <strong>ma con una famiglia<\/strong>! Quel che non si dice \u00e8 che alcuni Paesi li vendono, ci fanno business sopra. Finch\u00e9 sar\u00e0 cos\u00ec, non sar\u00e0 rispettato alcun interesse superiore del minore.<\/p>\n<p style=\"text-align: justify;\"><strong>Un incoraggiamento alle coppie aspiranti, o che hanno iniziato un cammino di adozione.<br \/>\n<\/strong>Continuate a testa bassa. Non arrendetevi e unitevi a noi: <strong>pi\u00f9 siamo, pi\u00f9 riusciremo a cambiare le cose<\/strong>. Io sono a disposizione perfino per andare in gruppo a Roma e a incatenarci davanti al palazzo del Governo. Nessuno deve permettersi di impedire a una famiglia di adottare un bambino!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>L\u2019adesione popolare al Manifesto brucia le tappe anche grazie al servizio che <strong>Max Laudadio<\/strong> ha voluto dedicare su Striscia la Notizia.\u00a0\u00abHo avuto modo di confrontarmi in prima persona con il <strong>marasma<\/strong> e la <strong>follia<\/strong> che le coppie sono obbligate ad affrontare quando intraprendono il percorso adottivo. Mi sono reso conto che il problema \u00e8 molto pi\u00f9 grande di quanto immaginassi\u00bb.<\/p>\n<p>Leggi il Manifesto e <a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/verso-una-nuova-legge-sulle-adozioni-internazionali\/\">dai la tua adesione<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-34904","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino\" \/>\n<meta property=\"og:description\" content=\"L\u2019adesione popolare al Manifesto brucia le tappe anche grazie al servizio che Max Laudadio ha voluto dedicare su Striscia la Notizia.\u00a0\u00abHo avuto modo di confrontarmi in prima persona con il marasma e la follia che le coppie sono obbligate ad affrontare quando intraprendono il percorso adottivo. Mi sono reso conto che il problema \u00e8 molto pi\u00f9 grande di quanto immaginassi\u00bb. Leggi il Manifesto e dai la tua adesione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-05T17:34:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-06T15:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino\",\"datePublished\":\"2012-06-05T17:34:26+00:00\",\"dateModified\":\"2012-06-06T15:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/\",\"name\":\"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\",\"datePublished\":\"2012-06-05T17:34:26+00:00\",\"dateModified\":\"2012-06-06T15:57:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/","og_locale":"it_IT","og_type":"article","og_title":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino","og_description":"L\u2019adesione popolare al Manifesto brucia le tappe anche grazie al servizio che Max Laudadio ha voluto dedicare su Striscia la Notizia.\u00a0\u00abHo avuto modo di confrontarmi in prima persona con il marasma e la follia che le coppie sono obbligate ad affrontare quando intraprendono il percorso adottivo. Mi sono reso conto che il problema \u00e8 molto pi\u00f9 grande di quanto immaginassi\u00bb. Leggi il Manifesto e dai la tua adesione","og_url":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-06-05T17:34:26+00:00","article_modified_time":"2012-06-06T15:57:08+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino","datePublished":"2012-06-05T17:34:26+00:00","dateModified":"2012-06-06T15:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/"},"wordCount":367,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/","url":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/","name":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg","datePublished":"2012-06-05T17:34:26+00:00","dateModified":"2012-06-06T15:57:08+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Max-Laudadio-in-conferenza-stampa-di-Ai.Bi_.-il-31-maggio-300x171.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/max-laudadio-nessuno-deve-permettersi-di-impedire-a-una-famiglia-di-adottare-un-bambino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Max Laudadio: nessuno deve permettersi di impedire a una famiglia di adottare un bambino"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:47:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/34904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=34904"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/34904\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=34904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=34904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=34904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}