﻿


{"id":34950,"date":"2012-06-06T18:03:56","date_gmt":"2012-06-06T16:03:56","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=34950"},"modified":"2012-06-06T21:49:53","modified_gmt":"2012-06-06T19:49:53","slug":"perche-monti-ha-paura-della-kafala","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/","title":{"rendered":"Perch\u00e9 il Governo Monti ha paura della &#8220;piccola&#8221; kafala?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35108\" title=\"VIGNETTA MONTATA 6 GIUGNO\" src=\"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg\" alt=\"\" width=\"550\" height=\"314\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg 550w, https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO-150x86.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO-300x171.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO-96x55.jpg 96w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nPu\u00f2 un bambino abbandonato<\/strong> proveniente da un Paese del Nordafrica <strong>far paura ad un Governo <\/strong>che si sta battendo con cos\u00ec tanta energia contro lo spread? Eppure \u00e8 quanto emerge dal dibattito tenuto il 30 maggio scorso alla Camera dei Deputati. Si \u00e8 riunita la Commissione parlamentare per gli affari esteri e comunitari per discutere il riconoscimento della <em>kafala<\/em> in Italia: parole di fuoco, invettive e accuse sono state lanciate contro il Governo Monti, con un messaggio chiaro e tagliente: \u00abState facendo <strong>ostruzionismo<\/strong>\u00bb. Pubblichiamo la notizia attingendo ai verbali della seduta.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Invito il Governo a un maggiore rispetto del Parlamento<\/strong>, che \u00e8 ben consapevole che l\u2019intollerabile e inaccettabile ostruzionismo burocratico alla Convenzione de L\u2019Aja 1996 <strong>\u00e8 motivato dalla questione della <em>kafala<\/em><\/strong>\u00bb ha tuonato l\u2019onorevole Francesco Tempestini, deputato del Partito Democratico. L\u2019accesa reazione di Tempestini \u00e8 seguita a una dichiarazione del presidente di Commissione, Stefano Stefani, che ha riferito di aver ricevuto una lettera dal presidente della Commissione Bilancio che comunicava la mancata presentazione da parte del Governo della relazione tecnica richiesta dalla Commissione stessa, segnalando l\u2019esigenza di configurare con maggiore precisione l\u2019Autorit\u00e0 centrale cui sarebbe delegata l\u2019attuazione della Convenzione de L\u2019Aja, individuando i relativi oneri e la corrispondente copertura finanziaria.<\/p>\n<p style=\"text-align: justify;\">Reazione furiosa e \u00abvivo sconcerto\u00bb da parte di Tempestini all\u2019udire la dichiarazione: \u00abLa ratifica della Convenzione de L\u2019Aja 1996 \u00e8 in ritardo di sedici anni \u2013 ha evidenziato l\u2019onorevole \u2013 nonostante riguardi aspetti umanitari rilevanti\u00bb, tra i quali l\u2019adeguamento della <em>kafala<\/em>, l\u2019istituto di origine coranica che permette al giudice islamico di affidare un bambino a una famiglia diversa da quella biologica.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Pretestuoso ed emulativo<\/strong> poi immaginare di questi tempi che i compiti previsti dall\u2019attuazione della Convenzione non possano essere svolti da strutture amministrative gi\u00e0 operanti\u00bb, ha concluso Tempestini. \u00ab<strong>Fior di giuristi<\/strong> hanno avanzato sulla <em>kafala<\/em> soluzioni assolutamente <strong>compatibili con il nostro ordinamento<\/strong>, che solo una miope percezione della vicenda ha sin qui impedito di valutare, portando al <strong>palleggiamento delle responsabilit\u00e0<\/strong> tra Ministero degli esteri, Ministero della giustizia ed ora Ministero dell\u2019economia! Si sollecita al pi\u00f9 presto il Governo a uscire da questa imbarazzante situazione presentando, come promesso, <strong>il disegno di legge di ratifica<\/strong>\u00bb.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Pu\u00f2 un bambino abbandonato\u00a0proveniente da un Paese del Nordafrica far paura ad un Governo\u00a0che si sta battendo con cos\u00ec tanta energia contro la crisi economica, incurante degli enormi ostacoli incontrati lungo il cammino? Eppure \u00e8 quanto emerge dal <strong>dibattito<\/strong><strong> <\/strong>tenuto alla Camera il<strong> <\/strong><strong>30 maggio<\/strong><strong>.<\/strong><strong> Parole di fuoco sono state lanciate contro il Governo Monti,\u00a0con u<\/strong><strong>n messaggio chiaro e tagliente:<\/strong><strong> <\/strong><strong>\u00ab<strong>State facendo\u00a0ostruzionismo<\/strong>\u00bb.<\/strong><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-34950","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perch\u00e9 il Governo Monti ha paura della &quot;piccola&quot; kafala? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 il Governo Monti ha paura della &quot;piccola&quot; kafala?\" \/>\n<meta property=\"og:description\" content=\"Pu\u00f2 un bambino abbandonato\u00a0proveniente da un Paese del Nordafrica far paura ad un Governo\u00a0che si sta battendo con cos\u00ec tanta energia contro la crisi economica, incurante degli enormi ostacoli incontrati lungo il cammino? Eppure \u00e8 quanto emerge dal dibattito tenuto alla Camera il 30 maggio. Parole di fuoco sono state lanciate contro il Governo Monti,\u00a0con un messaggio chiaro e tagliente: \u00abState facendo\u00a0ostruzionismo\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-06T16:03:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-06T19:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Perch\u00e9 il Governo Monti ha paura della &#8220;piccola&#8221; kafala?\",\"datePublished\":\"2012-06-06T16:03:56+00:00\",\"dateModified\":\"2012-06-06T19:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/\"},\"wordCount\":366,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/VIGNETTA-MONTATA-6-GIUGNO.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/\",\"name\":\"Perch\u00e9 il Governo Monti ha paura della \\\"piccola\\\" kafala? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/VIGNETTA-MONTATA-6-GIUGNO.jpg\",\"datePublished\":\"2012-06-06T16:03:56+00:00\",\"dateModified\":\"2012-06-06T19:49:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/VIGNETTA-MONTATA-6-GIUGNO.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/VIGNETTA-MONTATA-6-GIUGNO.jpg\",\"width\":550,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-monti-ha-paura-della-kafala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perch\u00e9 il Governo Monti ha paura della &#8220;piccola&#8221; kafala?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perch\u00e9 il Governo Monti ha paura della \"piccola\" kafala? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 il Governo Monti ha paura della \"piccola\" kafala?","og_description":"Pu\u00f2 un bambino abbandonato\u00a0proveniente da un Paese del Nordafrica far paura ad un Governo\u00a0che si sta battendo con cos\u00ec tanta energia contro la crisi economica, incurante degli enormi ostacoli incontrati lungo il cammino? Eppure \u00e8 quanto emerge dal dibattito tenuto alla Camera il 30 maggio. Parole di fuoco sono state lanciate contro il Governo Monti,\u00a0con un messaggio chiaro e tagliente: \u00abState facendo\u00a0ostruzionismo\u00bb.","og_url":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-06-06T16:03:56+00:00","article_modified_time":"2012-06-06T19:49:53+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Perch\u00e9 il Governo Monti ha paura della &#8220;piccola&#8221; kafala?","datePublished":"2012-06-06T16:03:56+00:00","dateModified":"2012-06-06T19:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/"},"wordCount":366,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/","url":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/","name":"Perch\u00e9 il Governo Monti ha paura della \"piccola\" kafala? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg","datePublished":"2012-06-06T16:03:56+00:00","dateModified":"2012-06-06T19:49:53+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/VIGNETTA-MONTATA-6-GIUGNO.jpg","width":550,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/perche-monti-ha-paura-della-kafala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Perch\u00e9 il Governo Monti ha paura della &#8220;piccola&#8221; kafala?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:48:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/34950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=34950"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/34950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=34950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=34950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=34950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}