﻿


{"id":35128,"date":"2012-06-07T14:42:01","date_gmt":"2012-06-07T12:42:01","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=35128"},"modified":"2012-06-07T15:32:04","modified_gmt":"2012-06-07T13:32:04","slug":"adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/","title":{"rendered":"Adozioni internazionali: le Isole Fiji diventano l&#8217;88mo Stato membro della Convenzione de L&#8217;Aja"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35150\" style=\"margin: 5px;\" title=\"Fiji\" src=\"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Fiji1-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Le Isole Fiji hanno depositato il mese scorso il proprio strumento di accesso alla Convenzione de L\u2019Aja del 1993 sulla protezione dei minori e sulla cooperazione in rispetto dell\u2019adozione internazionale. <strong>La Convenzione<\/strong><strong> entrer\u00e0 in vigore nel Paese il 1\u00b0 agosto 2012<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le Isole Fiji divengono ufficialmente l\u201988mo Paese partner della Convenzione, documento che disciplina la cooperazione fra le autorit\u00e0 competenti del Paese d\u2019origine del minore e quelle del Paese d\u2019accoglienza. Tra gli obiettivi della Convenzione vi \u00e8 quello di stabilire garanzie affinch\u00e9 le adozioni internazionali si facciano <strong>nell\u2019interesse del minore<\/strong> e quello di instaurare un sistema di cooperazione fra gli Stati contraenti, al fine di assicurare il rispetto di queste garanzie.<\/p>\n<p style=\"text-align: justify;\">\u00c8 infine di buon auspicio che i lavori di adeguamento da parte del nuovo Stato membro siano giunti a questo traguardo: tra i maggiori Paesi adottanti a livello mondiale <strong>soltanto gli Stati Uniti d\u2019America<\/strong>, negli ultimi anni, hanno portato a termine procedure di adozione dalle Fiji, vistando tra il 2005 e il 2011 l\u2019ingresso di 16 minori abbandonati, in prevalenza femmine (dati del Dipartimento di Stato USA, Bureau degli affari consolari).<\/p>\n<p style=\"text-align: justify;\"><em>(Fonte: sito ufficiale della Conferenza permanente de L\u2019Aja)<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Soltanto gli Stati Uniti d\u2019America<\/strong> hanno portato a termine procedure di adozione dalle Fiji, vistando, tra il 2005 e il 2011 l\u2019ingresso di 16 minori abbandonati.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-35128","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali: le Isole Fiji diventano l&#039;88mo Stato membro della Convenzione de L&#039;Aja - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali: le Isole Fiji diventano l&#039;88mo Stato membro della Convenzione de L&#039;Aja\" \/>\n<meta property=\"og:description\" content=\"Soltanto gli Stati Uniti d\u2019America hanno portato a termine procedure di adozione dalle Fiji, vistando, tra il 2005 e il 2011 l\u2019ingresso di 16 minori abbandonati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-07T12:42:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-07T13:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni internazionali: le Isole Fiji diventano l&#8217;88mo Stato membro della Convenzione de L&#8217;Aja\",\"datePublished\":\"2012-06-07T12:42:01+00:00\",\"dateModified\":\"2012-06-07T13:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fiji1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/\",\"name\":\"Adozioni internazionali: le Isole Fiji diventano l'88mo Stato membro della Convenzione de L'Aja - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fiji1.jpg\",\"datePublished\":\"2012-06-07T12:42:01+00:00\",\"dateModified\":\"2012-06-07T13:32:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fiji1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fiji1.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali: le Isole Fiji diventano l&#8217;88mo Stato membro della Convenzione de L&#8217;Aja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali: le Isole Fiji diventano l'88mo Stato membro della Convenzione de L'Aja - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali: le Isole Fiji diventano l'88mo Stato membro della Convenzione de L'Aja","og_description":"Soltanto gli Stati Uniti d\u2019America hanno portato a termine procedure di adozione dalle Fiji, vistando, tra il 2005 e il 2011 l\u2019ingresso di 16 minori abbandonati.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-06-07T12:42:01+00:00","article_modified_time":"2012-06-07T13:32:04+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni internazionali: le Isole Fiji diventano l&#8217;88mo Stato membro della Convenzione de L&#8217;Aja","datePublished":"2012-06-07T12:42:01+00:00","dateModified":"2012-06-07T13:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/"},"wordCount":206,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/","name":"Adozioni internazionali: le Isole Fiji diventano l'88mo Stato membro della Convenzione de L'Aja - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg","datePublished":"2012-06-07T12:42:01+00:00","dateModified":"2012-06-07T13:32:04+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Fiji1.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-le-isole-fiji-diventano-l88mo-stato-membro-della-convenzione-de-laja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali: le Isole Fiji diventano l&#8217;88mo Stato membro della Convenzione de L&#8217;Aja"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:46:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=35128"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35128\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=35128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=35128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=35128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}