﻿


{"id":35628,"date":"2012-06-19T12:42:27","date_gmt":"2012-06-19T10:42:27","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=35628"},"modified":"2012-06-19T12:42:27","modified_gmt":"2012-06-19T10:42:27","slug":"ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/","title":{"rendered":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35630\" style=\"margin: 5px;\" title=\"Lago Volta, bambini forzati al lavoro di pesca\" src=\"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Il lago Volta \u00e8 il pi\u00f9 grande lago artificiale del mondo. Si estende per 520 Km allungandosi dal sud del Paese, la regione del Volta appunto, fino al nord, passando per diverse regioni del Ghana.<\/p>\n<p style=\"text-align: justify;\">Il lago \u00e8 un\u2019importante risorsa economica per il Paese e per tutte le comunit\u00e0 che sorgono sulle sue sponde. La diga di Akosombo e l\u2019omonima centrale elettrica producono pi\u00f9 del 60% del fabbisogno di energia elettrica del Ghana. La pesca invece \u00e8 la fonte principale di nutrizione per la maggior parte della popolazione che vive lungo il lago. Il pesce pi\u00f9 pescato e\u2019 la famosa \u2018tilapia\u2019, divenuta piatto tipico che si pu\u00f2 trovare dappertutto e in tutte le salse.<\/p>\n<p style=\"text-align: justify;\">Il <strong>grande sviluppo della pesca<\/strong>, se da un lato ha positivamente contribuito alla nutrizione dell\u2019intera popolazione, dall\u2019altro ha creato <strong>un enorme problema di sfruttamento del lavoro minorile<\/strong>. Sono tantissimi infatti i bambini che vengono impiegati come aiutanti nella pratica della pesca, una piaga diffusa nel Paese, per combattere la quale molto poco \u00e8 stato fatto ad oggi.<\/p>\n<p style=\"text-align: justify;\">I piccoli pescatori spesso <strong>provengono da famiglie molto povere<\/strong> della zona, oppure <strong>addirittura vengono portati sulle sponde del lago da altre regioni del Ghana o paesi limitrofi<\/strong>. <strong>Lavorano di notte o la mattina molto presto e<\/strong> <strong>devono tuffarsi di continuo nell\u2019acqua fredda e profonda per districare le reti<\/strong> che si impigliano sul fondo del fiume. Lontani dalla loro famiglia <strong>perdono ben presto il diritto a un infanzia serena<\/strong>, rischiano la vita ogni giorno, non \u00e8 loro permesso di frequentare la scuola e, naturalmente, sono sottopagati.<\/p>\n<p style=\"text-align: justify;\">Il problema \u00e8 estremamente complesso e la sua soluzione richieder\u00e0 un lungo e difficile percorso di sensibilizzazione e supporto alle famiglie dei bambini e alle comunit\u00e0 al fine di far capire che i bambini non devono lavorare, ma vivere in famiglia la propria infanzia e andare a scuola.<\/p>\n<p style=\"text-align: justify;\">La difficile sfida \u00e8 quella di <strong>far capire che non sono i bambini a dover supportare la loro famiglia, ma il contrario!<\/strong> E per coloro che invece una famiglia a cui tornare non ce l\u2019hanno, e sono molti, si dovrebbe prevedere il <strong>reinserimento familiare<\/strong> principalmente tramite <strong>l\u2019adozione nazionale e internazionale<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Una situazione quindi drammatica che vogliamo portare all\u2019attenzione di tutti perch\u00e9 <strong>sempre pi\u00f9 voci si alzino per dire no allo sfruttamento dei bambini del Ghana e dell\u2019Africa tutta<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono\u00a0pescatori-bambini.\u00a0<strong>Lavorano di notte e<\/strong> <strong>devono tuffarsi di continuo nell\u2019acqua fredda e profonda per districare le reti<\/strong> che si impigliano sul fondo del fiume. Rischiano la vita ogni giorno.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-35628","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini\" \/>\n<meta property=\"og:description\" content=\"Sono\u00a0pescatori-bambini.\u00a0Lavorano di notte e devono tuffarsi di continuo nell\u2019acqua fredda e profonda per districare le reti che si impigliano sul fondo del fiume. Rischiano la vita ogni giorno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-19T10:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini\",\"datePublished\":\"2012-06-19T10:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/\",\"name\":\"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\",\"datePublished\":\"2012-06-19T10:42:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini","og_description":"Sono\u00a0pescatori-bambini.\u00a0Lavorano di notte e devono tuffarsi di continuo nell\u2019acqua fredda e profonda per districare le reti che si impigliano sul fondo del fiume. Rischiano la vita ogni giorno.","og_url":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-06-19T10:42:27+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini","datePublished":"2012-06-19T10:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/"},"wordCount":394,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/","url":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/","name":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg","datePublished":"2012-06-19T10:42:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Lago-Volta-bambini-forzati-al-lavoro-di-pesca.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ghana-lago-del-volta-il-lavoro-sporco-lo-fanno-fare-ai-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Ghana, Lago del Volta: il lavoro sporco lo fanno fare ai bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:45:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=35628"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35628\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=35628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=35628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=35628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}