﻿


{"id":35671,"date":"2012-06-20T14:30:48","date_gmt":"2012-06-20T12:30:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=35671"},"modified":"2012-06-20T14:30:48","modified_gmt":"2012-06-20T12:30:48","slug":"solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/","title":{"rendered":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35172\" style=\"margin: 5px;\" title=\"On. Elsa Fornero\" src=\"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Ma nel ddl all\u2019esame del Parlamento non ce n\u2019\u00e8 traccia<\/strong>. La riforma del lavoro, in dirittura d&#8217;arrivo, si illude di poter riformare il mondo del lavoro senza <strong>o addirittura contro le famiglie<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00abSiamo invece convinti che solo un lavoro pi\u00f9 <em>family friendly<\/em> possa aiutare la ripresa dell\u2019economia \u2013 interviene Francesco Belletti, presidente del Forum delle Associazioni Familiari \u2013 limitando, ad esempio, il fenomeno dell\u2019abbandono da parte delle donne in occasione della <strong>maternit\u00e0<\/strong>; salvaguardando i <strong>tempi del riposo<\/strong> che sono anche i tempi della famiglia; <strong>potenziando il lavoro part time<\/strong>, che in Italia risulta a malapena tollerato (quando negli altri Paesi europei \u00e8 <strong>spesso strumento strategico<\/strong> per favorire la partecipazione femminile al mercato del lavoro); <strong>volgendo lo sguardo ai giovani<\/strong> che, costretti a scegliere tra lavoro e famiglia, rinunciano a sposarsi ed avere figli.<\/p>\n<p style=\"text-align: justify;\">\u00abSolo conciliando realt\u00e0 del lavoro e realt\u00e0 della famiglia si potr\u00e0 produrre maggiore ricchezza e quindi rilanciare consumi ed economia. Per conciliare le due dimensioni della persona, il Forum ha elaborato una proposta articolata che discende direttamente dagli accordi che il Forum, insieme alle altre parti sociali ed al ministero del Lavoro, ha sottoscritto un anno fa. Abbiamo proposto <strong>l\u2019inserimento della conciliazione tra i diritti fondamentali di ogni lavoratore<\/strong>, <strong>la creazione di un Fondo paritetico per ulteriori congedi parentali<\/strong>, la riforma del part time, la proroga dei contratti a tempo determinato in caso di maternit\u00e0&#8230; Tutte proposte di cui <strong>non c\u2019\u00e8 traccia nel disegno di legge in esame in Parlamento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u2019Non ci sono le risorse\u2019, \u00e8 stata la risposta\u00bb conclude <strong>Belletti<\/strong>. \u00abMa quello che manca davvero \u00e8 la convinzione che una vera <strong>conciliazione famiglia\/lavoro<\/strong>, come dimostra l\u2019esperienza di altri Paesi, sia lo strumento efficace ed indispensabile per l\u2019aumento della produttivit\u00e0 del lavoratore e delle aziende, oltre che un elemento di civilt\u00e0 e di coesione sociale. Se ci fosse questa convinzione, ci sarebbero certamente anche le risorse, perch\u00e9 la conciliazione sarebbe una delle leve essenziali della riforma\u00bb.<\/p>\n<p style=\"text-align: justify;\"><em>(Forum delle Associazioni Familiari, 19 giugno 2012)<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSiamo convinti che solo un lavoro pi\u00f9 <em>family friendly<\/em> possa aiutare la ripresa dell\u2019economia,\u00a0salvaguardando i <strong>tempi del riposo<\/strong> che sono anche i tempi della famiglia; <strong>potenziando il lavoro part time<\/strong>\u00bb.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-35671","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione\" \/>\n<meta property=\"og:description\" content=\"\u00abSiamo convinti che solo un lavoro pi\u00f9 family friendly possa aiutare la ripresa dell\u2019economia,\u00a0salvaguardando i tempi del riposo che sono anche i tempi della famiglia; potenziando il lavoro part time\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-20T12:30:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione\",\"datePublished\":\"2012-06-20T12:30:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/\"},\"wordCount\":338,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/On.-Elsa-Fornero.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/\",\"name\":\"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/On.-Elsa-Fornero.jpg\",\"datePublished\":\"2012-06-20T12:30:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/On.-Elsa-Fornero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/On.-Elsa-Fornero.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/","og_locale":"it_IT","og_type":"article","og_title":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione","og_description":"\u00abSiamo convinti che solo un lavoro pi\u00f9 family friendly possa aiutare la ripresa dell\u2019economia,\u00a0salvaguardando i tempi del riposo che sono anche i tempi della famiglia; potenziando il lavoro part time\u00bb.","og_url":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-06-20T12:30:48+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione","datePublished":"2012-06-20T12:30:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/"},"wordCount":338,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/","url":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/","name":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg","datePublished":"2012-06-20T12:30:48+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/On.-Elsa-Fornero.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/solo-la-conciliazione-tra-lavoro-e-famiglia-rilancera-economia-e-produzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Solo la conciliazione tra lavoro e famiglia rilancer\u00e0 economia e produzione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:45:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=35671"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/35671\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=35671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=35671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=35671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}