﻿


{"id":36484,"date":"2012-07-11T17:53:17","date_gmt":"2012-07-11T15:53:17","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=36484"},"modified":"2012-07-11T17:53:17","modified_gmt":"2012-07-11T15:53:17","slug":"il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/","title":{"rendered":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-36486\" style=\"margin: 5px;\" title=\"Alessandro Meluzzi\" src=\"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Pubblichiamo il botta e risposta tra due genitori adottivi e un esperto, uscito in questi giorni sulla stampa nazionale, circa <strong>un tema che inizia a farsi caldo<\/strong>.<\/em><\/p>\n<p>Caro professore, siamo Maria e Alfredo, una coppia di genitori adottivi. Non potendo avere figli, dieci anni fa abbiamo adottato due bambini, un maschio e una femmina, che vivevano in un orfanotrofio di Citt\u00e0 del Capo, in Sudafrica. All&#8217;inizio i piccoli sembravano essersi inseriti quasi alla perfezione nella nuova realt\u00e0, ma i problemi dovevano ancora venire. Mentre la femmina, che oggi ha 17 anni, \u00e8 sempre stata promossa con il massimo dei voti in tutte le materie e ha pure un fidanzatino, <strong>il fratello di 15 \u00e8 il classico ragazzo &#8220;problematico&#8221;<\/strong>. Bocciato due volte, \u00e8 timidissimo e sembra non avere interessi, oltre che evidenti difficolt\u00e0 nell&#8217;apprendimento. Noi siamo molto preoccupati, anche perch\u00e9 nostro figlio non riesce ad aprirsi. Il mese scorso lo abbiamo ascoltato mentre si confidava con sua sorella. Diceva di non sentirsi <strong>n\u00e9 italiano n\u00e9 africano<\/strong> , e ci incolpava di non avergli mai raccontato nulla delle sue origini.<br \/>\nMa se lo abbiamo fatto, \u00e8 stato solo per proteggerlo da un passato di stenti e sofferenza. Insomma, non sappiamo come porci , anche perch\u00e9 nostro figlio \u00e8 appena entrato nel delicato periodo dell&#8217;adolescenza. E non ha amici. In attesa di una risposta, la ringraziamo con affetto.<\/p>\n<p><em><strong>Risponde l&#8217;esperto<\/strong><br \/>\n<\/em>Le adozioni internazionali rappresentano la feconda volont\u00e0 di diventare genitori attraverso un&#8217;assunzione di responsabilit\u00e0 e rispondono a un bisogno generale di fraternit\u00e0 e giustizia. Per\u00f2, non sempre sentimenti e motivazioni cos\u00ec nobili hanno esiti concreti proporzionati alla bont\u00e0 del progetto.<br \/>\nLa mia personale esperienza in almeno vent&#8217;anni di osservazione clinica ha evidenziato che molti figli adottivi vivono, soprattutto nell&#8217;adolescenza, momenti di crisi e faticano a relazionarsi con l&#8217;ambiente, la scuola e la famiglia. \u00ab<strong>Chi sono?<\/strong> Quali sono le mie radici? Perch\u00e9 i miei genitori mi hanno abbandonato? \u00c8 giusto che voi mi abbiate sradicato dal mio mondo per portarmi a crescere qui, sia pure con abbondanza di beni materiali e di affetti?\u00bb, si chiedono questi ragazzi.<br \/>\nNon potendo trovare una risposta definitiva, l&#8217;incertezza a volte si esprime in una forma di autoaggressivit\u00e0 e sottile distruttivit\u00e0 nei confronti di chi li ha tanto amati. Quindi, con molta probabilit\u00e0, cari Maria e Alfredo , anche vostro figlio \u00e8 in crisi perch\u00e9 non riesce a dare una spiegazione a certi dolorosi perch\u00e9.<br \/>\nSi tratta in fondo di domande legittime, anche se difficili e spesso senza risposta. Quando poi tali quesiti vanno di pari passo con <strong>i fisiologici disagi dell&#8217;adolescenza<\/strong> possono dare luogo a una miscela esplosiva, che alimenta insicurezze normali e presenti in tutti i suoi coetanei. <strong>Non sottovaluterei la crisi<\/strong> di questo quindicenne: per superarla, potrebbe essere utile l&#8217;aiuto di uno psicoterapeuta. Si tratta di situazioni pi\u00f9 diffuse di quanto non si creda e che non devono in alcun modo alimentare ingiustificati sensi di colpa o la ricerca di che cosa si \u00e8 sbagliato.<br \/>\nProbabilmente non avete commesso errori nell&#8217;educare il ragazzo: adottare un figlio <strong>\u00e8 una sfida entusiasmante. Ma anche complessa<\/strong>.<\/p>\n<p>Prof. Alessandro Meluzzi<\/p>\n<p><em>(Da VeroTV, 10 luglio 2012)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><em><strong>Risponde l&#8217;esperto:<\/strong>\u00a0<\/em>La mia personale esperienza ha evidenziato che molti figli adottivi vivono, soprattutto nell&#8217;adolescenza, momenti di crisi e faticano a relazionarsi&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-36484","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026 - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato\u2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026\" \/>\n<meta property=\"og:description\" content=\"Risponde l&#039;esperto:\u00a0La mia personale esperienza ha evidenziato che molti figli adottivi vivono, soprattutto nell&#039;adolescenza, momenti di crisi e faticano a relazionarsi...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato\u2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-11T15:53:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026\",\"datePublished\":\"2012-07-11T15:53:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/\"},\"wordCount\":521,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Alessandro-Meluzzi.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/\",\"name\":\"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026 - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Alessandro-Meluzzi.jpg\",\"datePublished\":\"2012-07-11T15:53:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Alessandro-Meluzzi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Alessandro-Meluzzi.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026 - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato\u2026\/","og_locale":"it_IT","og_type":"article","og_title":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026","og_description":"Risponde l'esperto:\u00a0La mia personale esperienza ha evidenziato che molti figli adottivi vivono, soprattutto nell'adolescenza, momenti di crisi e faticano a relazionarsi...","og_url":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato\u2026\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-07-11T15:53:17+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026","datePublished":"2012-07-11T15:53:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/"},"wordCount":521,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/","url":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/","name":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026 - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg","datePublished":"2012-07-11T15:53:17+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Alessandro-Meluzzi.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-nostro-ragazzo-ci-fa-sentire-in-colpa-perche-adottato%e2%80%a6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Il nostro ragazzo ci fa sentire in colpa perch\u00e9 adottato\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=36484"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36484\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=36484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=36484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=36484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}