﻿


{"id":36566,"date":"2012-07-13T15:56:09","date_gmt":"2012-07-13T13:56:09","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=36566"},"modified":"2013-04-08T09:34:14","modified_gmt":"2013-04-08T07:34:14","slug":"rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/","title":{"rendered":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#8217;abbandono"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-36571\" style=\"margin: 5px;\" title=\"Giuda, by A. Schirone\" src=\"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-150x86.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-96x55.jpg 96w, https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p><strong>30 agosto 2012<\/strong>, IX Giornata di Studi sulla spiritualit\u00e0 dell\u2019adozione: l\u2019appuntamento annuale di Ai.Bi. centrato sui personaggi legati al mistero dell&#8217;abbandono giunge alla sua nona edizione. Dopo Mos\u00e8, figlio della prima adozione internazionale della storia della salvezza, e dopo Giuseppe, padre adottivo di Ges\u00f9, quest\u2019anno il dibattito si apre sulla figura di <strong>Giuda Iscariota<\/strong>.<\/p>\n<p>Il convegno, organizzato dal Movimento di famiglie adottive e affidatarie La Pietra Scartata presso il Piccolo Paese del Lago di Monte Colombo, Rimini, si occuper\u00e0 di un personaggio scomodo, di un traditore, sul quale la coscienza letteraria si \u00e8 divisa tra la rimozione e la riscoperta. Infatti Giuda \u00e8 \u00abin un certo senso <strong>la figura pi\u00f9 importante del Nuovo Testamento<\/strong>, fatta eccezione per Ges\u00f9\u00bb.<\/p>\n<p>Perch\u00e9 scegliere perci\u00f2 proprio la figura di Giuda, che non suscita simpatie n\u00e9 voglia di parlarne? Perch\u00e9 Giuda parla <strong>il linguaggio della spiritualit\u00e0 dell\u2019adozione<\/strong>: un abbandono che sembra un tradimento, ma che apre ad un progetto di salvezza.<\/p>\n<p><strong>E che cosa c\u2019entra Giuda con il progetto di salvezza?<\/strong> Il fitto mistero che avvolge il personaggio verr\u00e0 affrontato negli\u00a0interrogativi che la tradizione lascia insoluti:\u00a0se\u00a0la salvezza si sarebbe comunque compiuta\u00a0senza la consegna da parte di Giuda, e\u00a0perch\u00e9 Ges\u00f9 non abbia esorcizzato il suo demone;\u00a0sul perch\u00e9 i Sacerdoti avessero accettato\u00a0di pagare\u00a0per una collaborazione inutile e,\u00a0infine, il mistero\u00a0dell&#8217;inerzia di tutti gli Apostoli davanti al traditore.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Programma<\/span><\/strong><\/p>\n<p><strong>ore 9.30 <\/strong>introduce e coordina<\/p>\n<p><strong>Gianmario Fogliazza &#8211; <\/strong>responsabile Centro Studi Ai.Bi. Amici dei Bambini &#8211; La Pietra Scartata<\/p>\n<p><strong>ore 9.40<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">\u201cAmico, per questo sei qui!\u201d<\/span><\/strong><\/p>\n<p><strong>Marco Griffini &#8211; <\/strong>Presidente Ai.Bi. Amici dei Bambini &#8211; La Pietra Scartata<\/p>\n<p><strong>ore 10.10<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">Quando la salvezza \u00e8 chiamata tradimento<\/span><\/strong><\/p>\n<p><strong>Giuseppe Salomoni <\/strong>&#8211; La Pietra Scartata<\/p>\n<p><strong>ore 10.30<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">Giuda alla ricerca di Ges\u00f9<\/span><\/strong><\/p>\n<p><strong>don Saulo Monti <\/strong>&#8211; Docente di teologia trinitaria presso la Facolt\u00e0 Teologica dell\u2019Italia<\/p>\n<p>settentrionale di Milano<\/p>\n<p><strong>ore 11.15 breve pausa<\/strong><\/p>\n<p><strong>ore 11.30<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">L\u2019abbandono e il dono: occasione o tradimento?<\/span><\/strong><\/p>\n<p><strong>don Maurizio Chiodi <\/strong>&#8211; Docente di teologia morale presso la Facolt\u00e0 Teologica dell\u2019Italia<\/p>\n<p>settentrionale di Milano &#8211; Consigliere spirituale Associazione La Pietra Scartata<\/p>\n<p><strong>ore 12.15<\/strong><\/p>\n<p><strong>primo confronto e condivisione<\/strong><\/p>\n<p><strong>(ore 13.00 \u2013 15.00 pausa)<\/strong><\/p>\n<p><strong>ore 15.00<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">L\u2019accoglienza tra tradimento e compimento<\/span><\/strong><\/p>\n<p><strong>Cristina Riccardi &#8211; Paola Chiminazzo <\/strong>&#8211; La Pietra Scartata<\/p>\n<p><strong>ore 15.30<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">\u00abIl traditore tradito: Giuda tra attese deluse e la fedelt\u00e0 di Ges\u00f9 che \u201ccustodisce i suoi<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">fino alla fine\u201d\u00bb<\/span><\/strong><\/p>\n<p><strong>don Alberto Cozzi <\/strong>&#8211; Docente di teologia sistematica presso la Facolt\u00e0 Teologica dell\u2019Italia<\/p>\n<p>settentrionale di Milano<\/p>\n<p><strong>ore 16.15<\/strong><\/p>\n<p><strong>confronto e condivisione conclusiva<\/strong><\/p>\n<p><strong>ore 17.00<\/strong><\/p>\n<p><strong>chiusura dei lavori<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">Modalit\u00e0 e quota di iscrizione<\/span><\/strong><\/p>\n<p>\u00c8 possibile iscriversi presso la sede dell\u2019incontro oppure inviando entro il 29\/08\/2012 l\u2019attestato<\/p>\n<p>di pagamento (causale \u201cSpiritualit\u00e0 adozione Monte Colombo 2012\u201d) insieme ai dati personali<\/p>\n<p>(nome e cognome, indirizzo, telefono, professione, ente di appartenenza) a: Amici dei Bambini,<\/p>\n<p>C.P. 77, 20077 Melegnano (MI), fax 02.98.23.26.11<\/p>\n<p>Quota: 20 Euro a persona o famiglia (la quota comprende il materiale del convegno<\/p>\n<p>e il fascicolo della rivista \u201c<strong>Lem\u00e0 Sabact\u00e0ni?<\/strong>\u201d dedicato al tema \u201c<strong>Mos\u00e8<\/strong>\u201d n. 6 &#8211; 2010.<\/p>\n<p><strong>La quota di iscrizione potr\u00e0 essere corrisposta ad Amici dei Bambini tramite:<\/strong><\/p>\n<p>\u2022 <strong>conto corrente <\/strong>postale n. 3012<\/p>\n<p>\u2022 <strong>bonifico bancario<\/strong>, conto corrente c\/o INTESA<\/p>\n<p>San Paolo, IBAN IT43E0306933381100000000325, Ag. Melegnano, intestato ad Amici dei Bambini<\/p>\n<p>\u2022 <strong>carta di credito<\/strong>, telefonando al n. 02.988.22.331<\/p>\n<p><strong><span style=\"color: #ff0000;\">Informazioni<\/span><\/strong><\/p>\n<p>Roberta Rossi, tel. <strong>02.988.22.331 <\/strong>&#8211; email: <strong>roberta.rossi@aibi.it<\/strong><\/p>\n<p><strong>www.aibi.it\/rimini<\/strong><\/p>\n<p><strong>Sede del Convegno<\/strong><\/p>\n<p>Auditorium \u201cL. Amici\u201d, Piccolo Paese del Lago, Via Canepa 172 &#8211; Monte Colombo (Rimini)<\/p>\n<p>Monte Colombo (Rimini), gioved\u00ec 30 agosto 2012<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest\u2019anno il dibattito si apre sulla figura di Giuda Iscariota. Un personaggio scomodo. Ma\u00a0Giuda \u00e8 \u00abin un certo senso <strong>la figura pi\u00f9 importante del Nuovo Testamento<\/strong>, fatta eccezione per Ges\u00f9\u00bb.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-36566","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#039;abbandono - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#039;abbandono\" \/>\n<meta property=\"og:description\" content=\"Quest\u2019anno il dibattito si apre sulla figura di Giuda Iscariota. Un personaggio scomodo. Ma\u00a0Giuda \u00e8 \u00abin un certo senso la figura pi\u00f9 importante del Nuovo Testamento, fatta eccezione per Ges\u00f9\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-13T13:56:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-08T07:34:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#8217;abbandono\",\"datePublished\":\"2012-07-13T13:56:09+00:00\",\"dateModified\":\"2013-04-08T07:34:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Giuda-by-A.-Schirone-300x171.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/\",\"name\":\"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell'abbandono - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Giuda-by-A.-Schirone-300x171.jpg\",\"datePublished\":\"2012-07-13T13:56:09+00:00\",\"dateModified\":\"2013-04-08T07:34:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Giuda-by-A.-Schirone-300x171.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Giuda-by-A.-Schirone-300x171.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#8217;abbandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell'abbandono - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/","og_locale":"it_IT","og_type":"article","og_title":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell'abbandono","og_description":"Quest\u2019anno il dibattito si apre sulla figura di Giuda Iscariota. Un personaggio scomodo. Ma\u00a0Giuda \u00e8 \u00abin un certo senso la figura pi\u00f9 importante del Nuovo Testamento, fatta eccezione per Ges\u00f9\u00bb.","og_url":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-07-13T13:56:09+00:00","article_modified_time":"2013-04-08T07:34:14+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#8217;abbandono","datePublished":"2012-07-13T13:56:09+00:00","dateModified":"2013-04-08T07:34:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/"},"wordCount":580,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/","url":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/","name":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell'abbandono - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg","datePublished":"2012-07-13T13:56:09+00:00","dateModified":"2013-04-08T07:34:14+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Giuda-by-A.-Schirone-300x171.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/rimini-la-consegna-di-giuda-tradimento-o-compimento-della-salvezza-un-passo-in-piu-nel-mistero-dellabbandono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Rimini, la consegna di Giuda: tradimento o compimento della salvezza? Un passo in pi\u00f9 nel mistero dell&#8217;abbandono"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:50:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=36566"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36566\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=36566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=36566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=36566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}