﻿


{"id":36608,"date":"2012-07-13T17:27:16","date_gmt":"2012-07-13T15:27:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=36608"},"modified":"2013-04-08T09:33:22","modified_gmt":"2013-04-08T07:33:22","slug":"adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/","title":{"rendered":"Adozioni internazionali, Russia: il Parlamento approva l&#8217;accordo con gli USA"},"content":{"rendered":"<p><strong>E niente pi\u00f9 guerra fredda<\/strong>. \u00c8 notizia dell\u2019agenzia Associated Press, rilanciata dal Washington Post il 10 luglio: la Duma ha ratificato il tanto atteso accordo bilaterale con gli Stati Uniti per le adozioni internazionali, firmato dal segretario di stato americano <strong>Hillary Clinton<\/strong> e il ministro russo degli affari esteri <strong>Sergey Lavrov<\/strong>.<\/p>\n<p><strong>Tutto come previsto<\/strong>. Il gigante asiatico, tra i maggiori Paesi di provenienza dei figli adottivi di tutto il mondo, e il gigante americano, punta di diamante dell\u2019adozione internazionale, sono tornati a stringere il patto. Nei mesi scorsi non sono mancate scintille: la Russia ha impugnato alcuni casi di maltrattamento familiare e le autorit\u00e0 hanno lamentato almeno 19 maltrattamenti avvenuti negli USA nei confronti di figli adottivi di origine russa, che sarebbero terminati con la morte dei piccoli. Le frange nazionaliste hanno addirittura denunciano la \u00abvendita\u00bb dei bambini russi agli USA.<\/p>\n<p>L\u2019attesa \u00e8 stata motivata con ritardi di natura tecnica. Con l\u2019accordo per\u00f2 si intende tagliare la testa al toro delle recriminazioni e intervenire a favore di <strong>migliaia di minori senza alcuna tutela familiare<\/strong>: gli orfanotrofi nel Paese traboccano, a detta delle stime UNICEF, tanto che negli ultimi anni l\u2019adozione di bambini russi negli USA ha conosciuto cifre elevatissime. 970 minori hanno fatto ingresso in America nel solo anno 2011, ma nel 2009 \u00e8 stato vistato l\u2019ingresso a ben 1586 piccoli russi; senza contare l\u2019anno 2004, che conobbe l\u2019adozione internazionale di 5862 minori dal Paese (dati del Dipartimento di Stato americano).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E niente pi\u00f9 guerra fredda.\u00a0La Duma ha ratificato il tanto atteso accordo bilaterale con gli Stati Uniti per le adozioni internazionali, firmato da <strong>Hillary Clinton<\/strong> e <strong>Sergey Lavrov<\/strong>.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-36608","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali, Russia: il Parlamento approva l&#039;accordo con gli USA - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali, Russia: il Parlamento approva l&#039;accordo con gli USA\" \/>\n<meta property=\"og:description\" content=\"E niente pi\u00f9 guerra fredda.\u00a0La Duma ha ratificato il tanto atteso accordo bilaterale con gli Stati Uniti per le adozioni internazionali, firmato da Hillary Clinton e Sergey Lavrov.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-13T15:27:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-08T07:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni internazionali, Russia: il Parlamento approva l&#8217;accordo con gli USA\",\"datePublished\":\"2012-07-13T15:27:16+00:00\",\"dateModified\":\"2013-04-08T07:33:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/\"},\"wordCount\":249,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/\",\"name\":\"Adozioni internazionali, Russia: il Parlamento approva l'accordo con gli USA - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2012-07-13T15:27:16+00:00\",\"dateModified\":\"2013-04-08T07:33:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali, Russia: il Parlamento approva l&#8217;accordo con gli USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali, Russia: il Parlamento approva l'accordo con gli USA - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali, Russia: il Parlamento approva l'accordo con gli USA","og_description":"E niente pi\u00f9 guerra fredda.\u00a0La Duma ha ratificato il tanto atteso accordo bilaterale con gli Stati Uniti per le adozioni internazionali, firmato da Hillary Clinton e Sergey Lavrov.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-07-13T15:27:16+00:00","article_modified_time":"2013-04-08T07:33:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni internazionali, Russia: il Parlamento approva l&#8217;accordo con gli USA","datePublished":"2012-07-13T15:27:16+00:00","dateModified":"2013-04-08T07:33:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/"},"wordCount":249,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/","name":"Adozioni internazionali, Russia: il Parlamento approva l'accordo con gli USA - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2012-07-13T15:27:16+00:00","dateModified":"2013-04-08T07:33:22+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-russia-il-parlamento-approva-laccordo-con-gli-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali, Russia: il Parlamento approva l&#8217;accordo con gli USA"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:47:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=36608"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/36608\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=36608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=36608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=36608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}