﻿


{"id":37540,"date":"2012-08-02T14:51:26","date_gmt":"2012-08-02T12:51:26","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=37540"},"modified":"2012-08-02T15:51:02","modified_gmt":"2012-08-02T13:51:02","slug":"moldova-dimezzati-i-tempi-delle-adozioni-internazionali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/","title":{"rendered":"Moldova: dimezzati i tempi delle adozioni internazionali"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-37551\" style=\"margin: 5px;\" title=\"2 Moldova 100X100\" src=\"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Ieri, durante una seduta del Governo della Moldova \u00e8 stato presentato il <strong>Progetto di Legge per la Modifica della Legge 99 del 28 maggio 2010 <\/strong>sul regime giuridico dell\u2019adozione.<\/p>\n<p>La presentazione del progetto di Legge del quale \u00e8 stata <strong>relatrice il Ministro del Lavoro, Protezione Sociale e Famiglia, Valentina Buliga<\/strong> ha suscitato ampie discussioni tra i Ministri del Governo ma, alla fine, il <strong>Primo Ministro ha proposto la promozione del progetto di Legge in Parlamento.<\/strong><\/p>\n<p>Attraverso questa Legge si <strong>ridurrebbe significativamente il periodo necessario per rendere i bambini adottabili da coppie straniere passando dagli attuali 2 anni a 1 anno per casi &#8220;semplici&#8221; e da 1 anno a 6 mesi per gli special needs<\/strong>.<\/p>\n<p>Per questi ultimi sar\u00e0 anche istituita una procedura speciale.<\/p>\n<p>Il Capo Dipartimento del Ministro del Lavoro, Protezione Sociale e Famiglia, Viorica Dumbraveanu, si \u00e8 complimentata con Ai.Bi. che gi\u00e0 da tempo \u00e8 divenuta interlocutore privilegiato del Governo collaborando prima alla definizione della Legge 99 e, successivamente, allo sviluppo delle proposte di riduzione dei tempi e regolamentazione degli special need contenute nell\u2019attuale riforma.<\/p>\n<p>Durante la seduta, il Ministro Buliga ha anche chiesto al Primo Ministro Vladimir Filat di poter presentare, in una prossima seduta governativa, un report sulla situazione delle adozioni in Moldova, sia nazionali che internazionali, per poter giustificare una volta in piu&#8217; la necessit\u00e0 delle modifiche proposte dal suo Ministero. Il Primo Ministro Filat ha accolto positivamente questa sua proposta.<\/p>\n<p>Avuta l\u2019approvazione del Governo, <strong>La Legge<\/strong><strong> dovr\u00e1 ora essere discussa in Parlamento<\/strong>.<\/p>\n<p>I rappresentanti del Ministro del Lavoro, Protezione Sociale e Famiglia si augurano assieme ad AiBi che l\u2019iter parlamentare si possa concludere in modo positivo.<strong><\/strong><\/p>\n<p>Pe ulteriori sviluppi bisogner\u00e0 <strong>aspettare settembre<\/strong> perch\u00e9 attualmente il <strong>Parlamento \u00e8 chiuso per ferie<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri, durante una seduta del Governo della Moldova \u00e8 stato presentato il <strong>Progetto di Legge per la Modifica della Legge 99 del 28 maggio 2010 <\/strong>sul regime giuridico dell\u2019adozione. La presentazione del progetto di Legge.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-37540","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moldova: dimezzati i tempi delle adozioni internazionali - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldova: dimezzati i tempi delle adozioni internazionali\" \/>\n<meta property=\"og:description\" content=\"Ieri, durante una seduta del Governo della Moldova \u00e8 stato presentato il Progetto di Legge per la Modifica della Legge 99 del 28 maggio 2010 sul regime giuridico dell\u2019adozione. La presentazione del progetto di Legge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-02T12:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-08-02T13:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Moldova: dimezzati i tempi delle adozioni internazionali\",\"datePublished\":\"2012-08-02T12:51:26+00:00\",\"dateModified\":\"2012-08-02T13:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2-Moldova-100X100.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/\",\"name\":\"Moldova: dimezzati i tempi delle adozioni internazionali - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2-Moldova-100X100.jpg\",\"datePublished\":\"2012-08-02T12:51:26+00:00\",\"dateModified\":\"2012-08-02T13:51:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2-Moldova-100X100.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2-Moldova-100X100.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moldova: dimezzati i tempi delle adozioni internazionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moldova: dimezzati i tempi delle adozioni internazionali - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/","og_locale":"it_IT","og_type":"article","og_title":"Moldova: dimezzati i tempi delle adozioni internazionali","og_description":"Ieri, durante una seduta del Governo della Moldova \u00e8 stato presentato il Progetto di Legge per la Modifica della Legge 99 del 28 maggio 2010 sul regime giuridico dell\u2019adozione. La presentazione del progetto di Legge.","og_url":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-08-02T12:51:26+00:00","article_modified_time":"2012-08-02T13:51:02+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Moldova: dimezzati i tempi delle adozioni internazionali","datePublished":"2012-08-02T12:51:26+00:00","dateModified":"2012-08-02T13:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/"},"wordCount":284,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/","url":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/","name":"Moldova: dimezzati i tempi delle adozioni internazionali - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg","datePublished":"2012-08-02T12:51:26+00:00","dateModified":"2012-08-02T13:51:02+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2-Moldova-100X100.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldova-dimezzati-i-tempi-delle-adozioni-internazionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Moldova: dimezzati i tempi delle adozioni internazionali"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:44:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/37540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=37540"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/37540\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=37540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=37540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=37540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}