﻿


{"id":3899,"date":"2008-11-18T17:36:40","date_gmt":"2008-11-18T14:36:40","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=3899"},"modified":"2009-02-18T17:37:52","modified_gmt":"2009-02-18T14:37:52","slug":"peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/","title":{"rendered":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn"},"content":{"rendered":"<p>E&#8217; stata dichiarata \u2018l&#8217;allerta rossa&#8217; nel dipartimento centrale di Jun\u00edn, confinante con la regione di Lima, dove almeno due persone sono morte e diverse decine sono rimaste ferite in confusi incidenti con la polizia durante una manifestazione contro la costruzione di un impianto per il trattamento dei residui solidi.<\/p>\n<p>Gli abitanti di Lastay, localit\u00e0 che dovrebbe ospitare l&#8217;impianto, sono stati dispersi dalle forze dell&#8217;ordine mentre protestavano contro l&#8217;amministrazione di Huancayo, responsabile del progetto; il ministro dell&#8217;Ambiente, Antonio Brack, non ha fornito una dinamica esatta degli incidenti affermando che gli agenti non avrebbero usato la forza e annunciando l&#8217;apertura di un&#8217;inchiesta.<\/p>\n<p>Gli incidenti di Lastay avvengono in concomitanza con l&#8217;apertura della settimana dell&#8217;APEC, il Forum di cooperazione economica Asia-Pacifico che vedr\u00e0 riuniti a Lima il prossimo fine settimana i capi di stato e di governo della regione, e dopo un nuovo attacco attribuito ai guerriglieri di \u2018Sendero Luminoso&#8217; nella regione andina di Ayacucho in cui sono rimasti uccisi tre poliziotti; nella stessa zona, gi\u00e0 \u2018roccaforte&#8217; dei ribelli di ispirazione maoista, ad ottobre si erano verificati altri due attacchi con un bilancio di 17 morti tra i militari governativi. Il governo del presidente Alan Garc\u00eda, la cui popolarit\u00e0 \u00e8 ai minimi storici (-77%, secondo un sondaggio dell&#8217;istituto \u2018Apoyo&#8217;), deve fare fronte anche a una serie di conflitti regionali, ultimo in ordine di tempo quello in corso nella regione meridionale di Tacna, dove dopo l&#8217;annuncio di tagli agli introiti dalle risorse minerarie la popolazione \u00e8 scesa in piazza scontrandosi con la polizia, con almeno tre morti e decine di feriti.<\/p>\n<p>(fonte: Misna)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&rsquo; stata dichiarata &lsquo;l&rsquo;allerta rossa&rsquo; nel dipartimento centrale di Jun&iacute;n, confinante con la regione di Lima, dove almeno due persone sono morte e diverse decine sono rimaste ferite in confusi incidenti con la polizia durante una manifestazione contro la costruzione di un impianto per il trattamento dei residui solidi. Gli [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-3899","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-\u201callerta-rossa\u201d-a-junin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn\" \/>\n<meta property=\"og:description\" content=\"E&rsquo; stata dichiarata &lsquo;l&rsquo;allerta rossa&rsquo; nel dipartimento centrale di Jun&iacute;n, confinante con la regione di Lima, dove almeno due persone sono morte e diverse decine sono rimaste ferite in confusi incidenti con la polizia durante una manifestazione contro la costruzione di un impianto per il trattamento dei residui solidi. Gli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-\u201callerta-rossa\u201d-a-junin\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-18T14:36:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-02-18T14:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn\",\"datePublished\":\"2008-11-18T14:36:40+00:00\",\"dateModified\":\"2009-02-18T14:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/\"},\"wordCount\":278,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/\",\"name\":\"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2008-11-18T14:36:40+00:00\",\"dateModified\":\"2009-02-18T14:37:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-\u201callerta-rossa\u201d-a-junin\/","og_locale":"it_IT","og_type":"article","og_title":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn","og_description":"E&rsquo; stata dichiarata &lsquo;l&rsquo;allerta rossa&rsquo; nel dipartimento centrale di Jun&iacute;n, confinante con la regione di Lima, dove almeno due persone sono morte e diverse decine sono rimaste ferite in confusi incidenti con la polizia durante una manifestazione contro la costruzione di un impianto per il trattamento dei residui solidi. Gli [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-\u201callerta-rossa\u201d-a-junin\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2008-11-18T14:36:40+00:00","article_modified_time":"2009-02-18T14:37:52+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn","datePublished":"2008-11-18T14:36:40+00:00","dateModified":"2009-02-18T14:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/"},"wordCount":278,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/","url":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/","name":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2008-11-18T14:36:40+00:00","dateModified":"2009-02-18T14:37:52+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/peru-dichiarato-stato-di-%e2%80%9callerta-rossa%e2%80%9d-a-junin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Per\u00f9: dichiarato stato di \u201callerta rossa\u201d a Jun\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:10:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=3899"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3899\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=3899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=3899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=3899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}