﻿


{"id":39345,"date":"2012-09-21T17:33:18","date_gmt":"2012-09-21T15:33:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=39345"},"modified":"2012-09-21T17:35:17","modified_gmt":"2012-09-21T15:35:17","slug":"bologna-15-settembre-il-rito-della-benedizione-delle-adozioni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/","title":{"rendered":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-29386\" style=\"margin: 5px;\" title=\"Bologna\" src=\"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/bologna-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Domenica 23 settembre 2012 \u00e8 prevista la celebrazione del Rito Benedizione delle Adozioni<strong> presso la Parrocchia San Giovanni Bosco in Via Bartolomeo dal Monte 11, a Bologna.<\/strong><\/p>\n<p>Il programma:<br \/>\nore <strong>15:00 <\/strong>ritrovo<br \/>\nore <strong>15:30<\/strong> catechesi sul Rito tenuta da Mons. Massimo <strong>Cassani<\/strong> e Don Luigi <strong>Spada<br \/>\n<\/strong>ore <strong>16:15<\/strong> testimonianza di Marco <strong>Griffini<\/strong>, fondatore e presidente di Ai.Bi. Amici dei Bambini<br \/>\nore <strong>18:00<\/strong> S. <strong>Messa<\/strong> con celebrazione Rito della Benedizione delle Adozioni<br \/>\nore <strong>19:00<\/strong> rinfresco <strong>comunitario<\/strong>.<\/p>\n<p><strong>Informazioni<\/strong>: 338.3144424<br \/>\nE-mail: <a title=\"blocked::mailto:giuseppe.salomoni@aibi.it\" href=\"mailto:giuseppe.salomoni@aibi.it\">giuseppe.salomoni@aibi.it<\/a><span style=\"text-decoration: underline;\">.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 23 settembre 2012 &egrave; prevista la celebrazione del Rito Benedizione delle Adozioni presso la Parrocchia San Giovanni Bosco in Via Bartolomeo dal Monte 11, a Bologna. Il programma: ore 15:00 ritrovo ore 15:30 catechesi sul Rito tenuta da Mons. Massimo Cassani e Don Luigi Spada ore 16:15 testimonianza di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-39345","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bologna, 23 settembre: il Rito della Benedizione delle Adozioni - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni\" \/>\n<meta property=\"og:description\" content=\"Domenica 23 settembre 2012 &egrave; prevista la celebrazione del Rito Benedizione delle Adozioni presso la Parrocchia San Giovanni Bosco in Via Bartolomeo dal Monte 11, a Bologna. Il programma: ore 15:00 ritrovo ore 15:30 catechesi sul Rito tenuta da Mons. Massimo Cassani e Don Luigi Spada ore 16:15 testimonianza di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-21T15:33:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-09-21T15:35:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni\",\"datePublished\":\"2012-09-21T15:33:18+00:00\",\"dateModified\":\"2012-09-21T15:35:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/\"},\"wordCount\":81,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bologna.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/\",\"name\":\"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bologna.jpg\",\"datePublished\":\"2012-09-21T15:33:18+00:00\",\"dateModified\":\"2012-09-21T15:35:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bologna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bologna.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/","og_locale":"it_IT","og_type":"article","og_title":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni","og_description":"Domenica 23 settembre 2012 &egrave; prevista la celebrazione del Rito Benedizione delle Adozioni presso la Parrocchia San Giovanni Bosco in Via Bartolomeo dal Monte 11, a Bologna. Il programma: ore 15:00 ritrovo ore 15:30 catechesi sul Rito tenuta da Mons. Massimo Cassani e Don Luigi Spada ore 16:15 testimonianza di [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-09-21T15:33:18+00:00","article_modified_time":"2012-09-21T15:35:17+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni","datePublished":"2012-09-21T15:33:18+00:00","dateModified":"2012-09-21T15:35:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/"},"wordCount":81,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/","url":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/","name":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg","datePublished":"2012-09-21T15:33:18+00:00","dateModified":"2012-09-21T15:35:17+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bologna.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bologna-15-settembre-il-rito-della-benedizione-delle-adozioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Bologna, 23 settembre: il Rito della Benedizione delle Adozioni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/39345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=39345"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/39345\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=39345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=39345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=39345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}