﻿


{"id":3976,"date":"2008-10-27T18:24:02","date_gmt":"2008-10-27T15:24:02","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=3976"},"modified":"2009-02-18T18:24:59","modified_gmt":"2009-02-18T15:24:59","slug":"spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/","title":{"rendered":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia"},"content":{"rendered":"<p>In Spagna \u00e8 stato sventato un traffico di documenti falsi per le famiglie disposte ad adottare bambini russi. Ne d\u00e0 notizia la &#8220;Gazzetta della Federazione Russa&#8221; in un articolo pubblicato lo scorso 23 ottobre.<\/p>\n<p>Lo scandalo dei documenti falsi \u00e8 venuto alla luce ad inizio ottobre, quando una famiglia andalusa ha ricevuto il permesso dall&#8217;organo di competenza per le adozioni per andare in Federazione Russa e adottare una coppia di fratelli. Con tutti i documenti pronti, la coppia \u00e8 partita alla volta di Mosca. Qualcosa non ha funzionato: il permesso di uscita dai confini russi dei fratelli e l&#8217;ingresso in Spagna \u00e9 stato negato in quanto il Consolato spagnolo a Mosca si \u00e8 subito reso conto che i documenti erano falsi.<\/p>\n<p>Tornati in Andalusia, tristi ed amareggiati, gli aspiranti genitori adottivi hanno denunciato l&#8217;organo regionale.<\/p>\n<p>Le autorit\u00e0 andaluse fanno sapere che una consistente parte di bambini provenienti dalla Federazione Russa sono stati adottati attraverso il servizio federale EKAI, con il controllo degli organi centrali del Ministero degli Interni. Alla luce di questa vicenda, le verifiche dei documenti per le adozioni in Federazione Russa saranno sottoposte a un controllo ancora pi\u00f9 serrato.<\/p>\n<p>Altre due regioni in cui sono numerose le adozioni di bambini russi, Arjoke e Asturia, saranno coinvolte nelle indagini per la verifica dei documenti rilasciati alle aspiranti famiglie adottive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Spagna &egrave; stato sventato un traffico di documenti falsi per le famiglie disposte ad adottare bambini russi. Ne d&agrave; notizia la &ldquo;Gazzetta della Federazione Russa&rdquo; in un articolo pubblicato lo scorso 23 ottobre. Lo scandalo dei documenti falsi &egrave; venuto alla luce ad inizio ottobre, quando una famiglia andalusa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-3976","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spagna: scoperto traffico di documenti falsi per le adozioni in Russia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia\" \/>\n<meta property=\"og:description\" content=\"In Spagna &egrave; stato sventato un traffico di documenti falsi per le famiglie disposte ad adottare bambini russi. Ne d&agrave; notizia la &ldquo;Gazzetta della Federazione Russa&rdquo; in un articolo pubblicato lo scorso 23 ottobre. Lo scandalo dei documenti falsi &egrave; venuto alla luce ad inizio ottobre, quando una famiglia andalusa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-10-27T15:24:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-02-18T15:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia\",\"datePublished\":\"2008-10-27T15:24:02+00:00\",\"dateModified\":\"2009-02-18T15:24:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/\",\"name\":\"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2008-10-27T15:24:02+00:00\",\"dateModified\":\"2009-02-18T15:24:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/","og_locale":"it_IT","og_type":"article","og_title":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia","og_description":"In Spagna &egrave; stato sventato un traffico di documenti falsi per le famiglie disposte ad adottare bambini russi. Ne d&agrave; notizia la &ldquo;Gazzetta della Federazione Russa&rdquo; in un articolo pubblicato lo scorso 23 ottobre. Lo scandalo dei documenti falsi &egrave; venuto alla luce ad inizio ottobre, quando una famiglia andalusa [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2008-10-27T15:24:02+00:00","article_modified_time":"2009-02-18T15:24:59+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia","datePublished":"2008-10-27T15:24:02+00:00","dateModified":"2009-02-18T15:24:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/"},"wordCount":228,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/","url":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/","name":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2008-10-27T15:24:02+00:00","dateModified":"2009-02-18T15:24:59+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/spagna-scoperto-traffico-di-documenti-falsi-per-le-adozioni-in-russia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Spagna: scoperto traffico di documenti falsi per le adozioni in Russia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:22:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=3976"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3976\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=3976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=3976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=3976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}