﻿


{"id":3981,"date":"2008-10-07T18:26:19","date_gmt":"2008-10-07T15:26:19","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=3981"},"modified":"2009-02-18T18:27:02","modified_gmt":"2009-02-18T15:27:02","slug":"torino-sventato-traffico-di-romene-orfane","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/","title":{"rendered":"Torino: sventato traffico di romene orfane"},"content":{"rendered":"<p>Per reclutare le donne da avviare alla prostituzione sceglievano, in Romania, adolescenti senza famiglia o ospiti negli orfanotrofi, convincendole a trasferirsi in Italia con la promessa di un lavoro onesto e una vita agiata.<\/p>\n<p>Il gruppo, composto da romeni ed albanesi, \u00e8 stato smantellato dalla polizia a Torino con un&#8217;inchiesta che ha portato anche alla scoperta di una numerosa banda specializzata nei furti di escavatori e altre macchine da lavoro. In tutto sono 21 gli ordini di arresto firmati dal gip Silvia Salvadori, ma il sospetto \u00e8 che ci siano ancora altre persone coinvolte. Cinque, invece, sono le ragazze che, nel capoluogo piemontese, sono state costrette a prostituirsi.<\/p>\n<p>Ad occuparsi della ricerca delle donne in Romania era Cristinel Sarcu, 28 anni, che probabilmente aveva dei complici anche all&#8217;interno degli orfanotrofi. &#8220;Una volta maggiorenni &#8211; \u00e8 stato spiegato in questura &#8211; le ragazze dovevano lasciare l&#8217;istituto, ma non avendo famiglia, denaro e amici diventavano una preda facile per i malintenzionati&#8221;. Ad avviarle alla prostituzione, in Italia, erano due cugini di origine albanese, Roland e Leonardo Shordaj, di 26 e 31 anni, e altri personaggi.<\/p>\n<p>L&#8217;inchiesta \u00e8 ancora in corso, e presto verranno contattate le autorit\u00e0 romene per poter svolgere accertamenti all&#8217;estero. Sarcu, come hanno accertato gli investigatori diretti dal pm Cristina Bianconi, dal capo della squadra mobile Sergio Molino e dal dirigente di polizia Alberto Somma, era anche il contatto tra il gruppo degli sfruttatori e la banda dei ladri di escavatori, capace di mettere a segno decine di colpi nei cantieri. L&#8217;organizzazione agiva con grande efficienza: spesso, per non destare sospetti, i suoi componenti indossavano divise di operatori stradali. I mezzi, nascosti in diversi depositi nel Nord Italia, venivano rivenduti in Romania con falsi documenti. Fra i promotori del gruppo la polizia indica il settantaseienne Nicol\u00f2 Vivona, pregiudicato, chiamato dai compagni &#8220;il vecchio&#8221; per l&#8217;autorevolezza e l&#8217;esperienza maturata negli ambienti della malavita.<\/p>\n<p>(fonte: Ansa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per reclutare le donne da avviare alla prostituzione sceglievano, in Romania, adolescenti senza famiglia o ospiti negli orfanotrofi, convincendole a trasferirsi in Italia con la promessa di un lavoro onesto e una vita agiata. Il gruppo, composto da romeni ed albanesi, &egrave; stato smantellato dalla polizia a Torino con un&rsquo;inchiesta [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-3981","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Torino: sventato traffico di romene orfane - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torino: sventato traffico di romene orfane\" \/>\n<meta property=\"og:description\" content=\"Per reclutare le donne da avviare alla prostituzione sceglievano, in Romania, adolescenti senza famiglia o ospiti negli orfanotrofi, convincendole a trasferirsi in Italia con la promessa di un lavoro onesto e una vita agiata. Il gruppo, composto da romeni ed albanesi, &egrave; stato smantellato dalla polizia a Torino con un&rsquo;inchiesta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-10-07T15:26:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-02-18T15:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Torino: sventato traffico di romene orfane\",\"datePublished\":\"2008-10-07T15:26:19+00:00\",\"dateModified\":\"2009-02-18T15:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/\",\"name\":\"Torino: sventato traffico di romene orfane - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2008-10-07T15:26:19+00:00\",\"dateModified\":\"2009-02-18T15:27:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/torino-sventato-traffico-di-romene-orfane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Torino: sventato traffico di romene orfane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Torino: sventato traffico di romene orfane - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/","og_locale":"it_IT","og_type":"article","og_title":"Torino: sventato traffico di romene orfane","og_description":"Per reclutare le donne da avviare alla prostituzione sceglievano, in Romania, adolescenti senza famiglia o ospiti negli orfanotrofi, convincendole a trasferirsi in Italia con la promessa di un lavoro onesto e una vita agiata. Il gruppo, composto da romeni ed albanesi, &egrave; stato smantellato dalla polizia a Torino con un&rsquo;inchiesta [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2008-10-07T15:26:19+00:00","article_modified_time":"2009-02-18T15:27:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Torino: sventato traffico di romene orfane","datePublished":"2008-10-07T15:26:19+00:00","dateModified":"2009-02-18T15:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/","url":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/","name":"Torino: sventato traffico di romene orfane - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2008-10-07T15:26:19+00:00","dateModified":"2009-02-18T15:27:02+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/torino-sventato-traffico-di-romene-orfane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Torino: sventato traffico di romene orfane"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:30:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=3981"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/3981\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=3981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=3981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=3981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}