﻿


{"id":42188,"date":"2012-11-23T14:52:30","date_gmt":"2012-11-23T13:52:30","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=42188"},"modified":"2012-11-23T15:26:33","modified_gmt":"2012-11-23T14:26:33","slug":"il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/","title":{"rendered":"Il Bello che fa Bene 2012: tradizione &#038; innovazione a Palazzo Serbelloni"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-42191\" title=\"_DSC7092\" src=\"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/DSC7092-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Luned\u00ec 26 Novembre, <\/strong>a<strong> <\/strong>partire dalle 18.45, si terr\u00e0 a <strong>Milano<\/strong> presso la prestigiosa cornice di <strong>Palazzo Serbelloni<\/strong>, <strong>l\u2019undicesima edizione del \u201cBello che fa bene\u201d<\/strong>, evento benefico a sostegno delle attivit\u00e0, in Italia e nel mondo, di <strong>Ai.Bi. Associazione Amici dei Bambini<\/strong>, finalizzate a dare ai minori abbandonati una famiglia.<\/p>\n<p><em>\u201c<strong>Il Bello che fa bene <\/strong>\u00e8 un appuntamento di grande rilievo per la nostra Associazione\u201d<\/em> dichiara <strong>Marco Griffini, Presidente di Ai.Bi.<\/strong> \u201c<em>siamo grati ai partecipanti e alle aziende amiche che ogni anno sostengono questa importante iniziativa, volta a finanziare progetti a favore dell\u2019infanzia abbandonata e a promuovere il diritto di ogni bambino ad essere figlio.\u201d<\/em><em><\/em><\/p>\n<p>L\u2019evento, ospitato dalla <strong>Fondazione Serbelloni<\/strong>, avr\u00e0 luogo presso le magnifiche <strong>Sale Napoleoniche<\/strong>, che hanno recentemente vissuto uno storico intervento di restauro conservativo e di dotazione delle pi\u00f9 sofisticate tecnologie multimediali.<\/p>\n<p>Come ama sottolineare <strong>il Presidente della Fondazione<\/strong>: \u201c<strong><em>Palazzo Serbelloni<\/em><\/strong><em> \u00e8 molto pi\u00f9 che un palazzo: \u00e8 una visione del mondo, un pensiero, che ha ospitato grandi idee e grandi uomini\u201d<\/em> come <strong>Napoleone, Mozart, Metternich, Radetzky e Vittorio Emanuele II<\/strong>.<\/p>\n<p>Anche quest\u2019anno, durante l\u2019evento, si terr\u00e0 la <strong>Smart Auction<\/strong>:<strong> l\u2019asta silenziosa<\/strong> di oggetti donati da prestigiose aziende dell\u2019alta gamma, realizzata mediante tablet e smartphone grazie al contributo di <strong>Fondazione Telecom Italia<\/strong>.<\/p>\n<p><strong>Quattro<\/strong> grandi chef: <strong>Francesco Pesce<\/strong>, <strong>Kotaro Noda<\/strong>, <strong>Lorenzo Cogo e Franco Aliberti<\/strong> si alterneranno in cucina per conquistare i palati dei presenti alla Cena di Gala, attraverso la realizzazione delle loro migliori prelibatezze e al termine della serata, <strong>Liberato Aliberti, <\/strong>manager enogastonomico delizier\u00e0 i presenti con il nuovo format \u201c<strong>Made in Birra<\/strong>\u201d, creando un inedito abbinamento dolce-birra.<\/p>\n<p>Durante la Cena di Gala, destinata alla raccolta fondi, saranno battute all\u2019asta alcune esclusive <strong>borse Limited Edition <\/strong>donate da <strong>Poste Italiane<\/strong> nell\u2019ambito dell\u2019iniziativa <strong>\u201cUn Sacco di Buone Azioni\u201d<\/strong>. Chi si aggiudicher\u00e0 le borse potr\u00e0 godere anche di un\u2019esclusiva esperienza legata al mondo del gusto.<\/p>\n<p>Ospiti d\u2019eccellenza della serata saranno alcuni volti noti dello spettacolo che, come <strong>Max Laudadio <\/strong>di <strong>Striscia La Notizia <\/strong>e <strong>Tania Zamparo <\/strong>di <strong>SKY Sport, <\/strong>hanno sposato la \u201cmission\u201d di Ai.Bi. di aiutare ogni bambino ad avere una famiglia.<\/p>\n<p><strong>Il Bello che fa Bene proseguir\u00e0<\/strong> dal <strong>12 al 23 Dicembre <\/strong>con lo <strong>shopping solidale<\/strong> in Via Scarpa, 9 angolo Corso Vercelli con <strong>sconti davvero eccezionali!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Luned\u00ec 26 Novembre, <\/strong>a<strong> <\/strong>partire dalle 18.45, si terr\u00e0 a <strong>Milano<\/strong> presso la prestigiosa cornice di <strong>Palazzo Serbelloni<\/strong>, <strong>l\u2019undicesima edizione del \u201cBello che fa bene\u201d<\/strong>, evento benefico a sostegno delle attivit\u00e0, in Italia e nel mondo, di <strong>Ai.Bi. Associazione Amici dei Bambini<\/strong>, finalizzate a dare ai minori abbandonati una famiglia.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-42188","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il Bello che fa Bene 2012: tradizione &amp; innovazione a Palazzo Serbelloni - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Bello che fa Bene 2012: tradizione &amp; innovazione a Palazzo Serbelloni\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 26 Novembre, a partire dalle 18.45, si terr\u00e0 a Milano presso la prestigiosa cornice di Palazzo Serbelloni, l\u2019undicesima edizione del \u201cBello che fa bene\u201d, evento benefico a sostegno delle attivit\u00e0, in Italia e nel mondo, di Ai.Bi. Associazione Amici dei Bambini, finalizzate a dare ai minori abbandonati una famiglia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-23T13:52:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-23T14:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Il Bello che fa Bene 2012: tradizione &#038; innovazione a Palazzo Serbelloni\",\"datePublished\":\"2012-11-23T13:52:30+00:00\",\"dateModified\":\"2012-11-23T14:26:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/\"},\"wordCount\":387,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/DSC7092.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/\",\"name\":\"Il Bello che fa Bene 2012: tradizione & innovazione a Palazzo Serbelloni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/DSC7092.jpg\",\"datePublished\":\"2012-11-23T13:52:30+00:00\",\"dateModified\":\"2012-11-23T14:26:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/DSC7092.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/DSC7092.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il Bello che fa Bene 2012: tradizione &#038; innovazione a Palazzo Serbelloni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il Bello che fa Bene 2012: tradizione & innovazione a Palazzo Serbelloni - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/","og_locale":"it_IT","og_type":"article","og_title":"Il Bello che fa Bene 2012: tradizione & innovazione a Palazzo Serbelloni","og_description":"Luned\u00ec 26 Novembre, a partire dalle 18.45, si terr\u00e0 a Milano presso la prestigiosa cornice di Palazzo Serbelloni, l\u2019undicesima edizione del \u201cBello che fa bene\u201d, evento benefico a sostegno delle attivit\u00e0, in Italia e nel mondo, di Ai.Bi. Associazione Amici dei Bambini, finalizzate a dare ai minori abbandonati una famiglia.","og_url":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2012-11-23T13:52:30+00:00","article_modified_time":"2012-11-23T14:26:33+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Il Bello che fa Bene 2012: tradizione &#038; innovazione a Palazzo Serbelloni","datePublished":"2012-11-23T13:52:30+00:00","dateModified":"2012-11-23T14:26:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/"},"wordCount":387,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/","url":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/","name":"Il Bello che fa Bene 2012: tradizione & innovazione a Palazzo Serbelloni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg","datePublished":"2012-11-23T13:52:30+00:00","dateModified":"2012-11-23T14:26:33+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/DSC7092.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-bello-che-fa-bene-2012-tradizione-innovazione-a-palazzo-serbelloni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Il Bello che fa Bene 2012: tradizione &#038; innovazione a Palazzo Serbelloni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:59:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/42188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=42188"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/42188\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=42188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=42188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=42188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}