﻿


{"id":46408,"date":"2013-02-27T11:02:35","date_gmt":"2013-02-27T10:02:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=46408"},"modified":"2013-03-01T17:14:58","modified_gmt":"2013-03-01T16:14:58","slug":"cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/","title":{"rendered":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong"},"content":{"rendered":"<p><span style=\"color: #000000;\"><a href=\"https:\/\/www.aibi.it\/ita\/cina-le-donne-single-potranno-adottare-i-bambini-che-necessitano-di-cure-particolari\/bambina-cina-2\/\" rel=\"attachment wp-att-20785\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20785\" alt=\"bambina cina\" src=\"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg\" width=\"100\" height=\"100\" \/><\/a>A fine 2012, la Xinhua (Agenzia Stampa ufficiale del Governo Cinese) ha registrato un<strong> gran numero di finanziamenti da parte del Governo a favore di molti progetti a sfondo sociale promossi da delle ONG presenti sul territorio nazionale.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Del finanziamento, hanno beneficiato 377 progetti per il recupero sociale di emarginati, e pi\u00f9 di 120 programmi di formazione per il personale coinvolto nei vari progetti.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tali interventi fanno parte di un programma pi\u00f9 ampio lanciato dal Ministero degli Affari Civili cinese che prevede misure a sostegno di organizzazioni sociali e della loro attivit\u00e0.<\/span><\/p>\n<p><span style=\"color: #000000;\">Fonte China Daily<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fine 2012, la Xinhua (Agenzia Stampa ufficiale del Governo Cinese) ha registrato un gran numero di finanziamenti da parte del Governo a favore di molti progetti a sfondo sociale promossi da delle ONG presenti sul territorio nazionale. Del finanziamento, hanno beneficiato 377 progetti per il recupero sociale di emarginati, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-46408","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong\" \/>\n<meta property=\"og:description\" content=\"A fine 2012, la Xinhua (Agenzia Stampa ufficiale del Governo Cinese) ha registrato un gran numero di finanziamenti da parte del Governo a favore di molti progetti a sfondo sociale promossi da delle ONG presenti sul territorio nazionale. Del finanziamento, hanno beneficiato 377 progetti per il recupero sociale di emarginati, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-27T10:02:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-03-01T16:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong\",\"datePublished\":\"2013-02-27T10:02:35+00:00\",\"dateModified\":\"2013-03-01T16:14:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-cina1.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/\",\"name\":\"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-cina1.jpg\",\"datePublished\":\"2013-02-27T10:02:35+00:00\",\"dateModified\":\"2013-03-01T16:14:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-cina1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-cina1.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/","og_locale":"it_IT","og_type":"article","og_title":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong","og_description":"A fine 2012, la Xinhua (Agenzia Stampa ufficiale del Governo Cinese) ha registrato un gran numero di finanziamenti da parte del Governo a favore di molti progetti a sfondo sociale promossi da delle ONG presenti sul territorio nazionale. Del finanziamento, hanno beneficiato 377 progetti per il recupero sociale di emarginati, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-02-27T10:02:35+00:00","article_modified_time":"2013-03-01T16:14:58+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong","datePublished":"2013-02-27T10:02:35+00:00","dateModified":"2013-03-01T16:14:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/"},"wordCount":103,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/","url":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/","name":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg","datePublished":"2013-02-27T10:02:35+00:00","dateModified":"2013-03-01T16:14:58+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-cina1.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cina-stanziati-30-milioni-di-dollari-dal-governo-per-finanziare-le-ong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Cina: stanziati 30 milioni di dollari dal Governo per finanziare le Ong"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/46408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=46408"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/46408\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=46408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=46408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=46408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}