﻿


{"id":49346,"date":"2013-04-18T22:29:42","date_gmt":"2013-04-18T20:29:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=49346"},"modified":"2013-04-18T22:29:42","modified_gmt":"2013-04-18T20:29:42","slug":"kenya-dove-i-bambini-giocano-fra-gli-escrementi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/","title":{"rendered":"Kenya: dove i bambini giocano fra gli escrementi"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-49349\" alt=\"kenya spazzatura\" src=\"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\"><strong>Con queste belle giornate di sole, cosa facciamo con i nostri figli? Li accompagniamo al parco per far loro respirare aria pulita, per portarli in mezzo al verde.<\/strong> E i bambini si divertono con poco, correndo qua e l\u00e0, salendo sull\u2019altalena, scendendo dallo scivolo, o ancora giocando a pallone. E quando, per sbaglio, si avvicinano ai bisogni dei cani, siamo sempre pronti ad allontanarli.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Nelle baraccopoli di Mathare, invece, i bimbi sono molto meno fortunati. E purtroppo non hanno nulla con cui giocare se non proprio con gli escrementi,<\/strong> non quelli degli animali, ma quelli che i poveri mettono nei sacchettini di plastica per risparmiare sui bagni pubblici troppo onerosi.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">&#8220;<em>Noi le chiamiamo toilette volanti. Visto che i bagni pubblici non ci sono o sono troppo costosi, anzich\u00e9 pagare per usarli, ricorriamo a una busta di plastica che poi buttiamo in strada<\/em>\u201d ha detto Mama Annah, un residente di Mathare, a <strong>IRIN (Integrated Regional Information Networks)<\/strong>. \u201c<em>Non abbiamo alternative<\/em>\u201d. La strada \u00e8 un\u2019enorme discarica a cielo aperto ed \u00e8 anche l\u2019unico posto dove i bambini vanno a giocare: di qui <strong>l\u2019enorme problema di salute pubblica.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Oggi sono almeno <strong>100 milioni le persone che in Africa orientale non hanno accesso a servizi igienici<\/strong> adeguati, secondo fonti delle Nazioni Unite.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>L&#8217;Organizzazione Mondiale della Sanit\u00e0, aveva calcolato gi\u00e0, nel 2006, che queste \u201ctoillette volanti\u201d erano l\u2019unica pratica \u201cigienica\u201d disponibile per il 33 per cento della popolazione in Africa orientale.<\/strong> La mancanza di accesso a servizi igienici adeguati, compresa l&#8217;acqua pulita, \u00e8 una delle principali cause di diarrea, la seconda pi\u00f9 grande causa di mortalit\u00e0 infantile nei paesi in via di sviluppo, secondo UNICEF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Molti abitanti delle baraccopoli nelle citt\u00e0 dell&#8217;Africa orientale pagano da cinque a sette volte di pi\u00f9 per un litro di acqua rispetto alla media del Nord America<\/strong>, rileva l\u2019OMS. Ed \u00e8 ovvio, quindi, che a rimetterci siano le fasce di popolazione pi\u00f9 vulnerabili e i pi\u00f9 poveri: fra loro, sono soprattutto le donne e i bambini a soffrire.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #000000;\">Quale soluzione si potrebbe pensare?<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Gli abitanti dei quartieri poveri spesso non possiedono la terra su cui vivono e sono costantemente a rischio di sfratto. Negli slum di Huruma, sempre a Nairobi, <strong>Akiba Mashinani Trust ha aiutato i residenti ad ottenere un terreno negoziando con il governo e il consiglio comunale.<\/strong> &#8220;<em>Se si ha della terra, si hanno pi\u00f9 prospettive e quindi maggiore voglia di investire in qualche miglioria igienica<\/em>&#8220;, ha detto Edith Kalela, un responsabile della comunicazione di Akiba Mashinani Trust.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">\u201c<em>Aiutiamo queste persone a costruire case che siano autonome. Investiamo anche nell\u2019edificazione di servizi igienici pubblici, ma ci sono oltre 200.000 famiglie: impossibile rispondere ai bisogni di tutti<\/em>&#8220;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>KENSUP, il programma Miglioramento degli Slum in Kenya, ha recentemente portato a termine un progetto di bonifica nello slum di Kibera, consegnando sette impianti di acqua igienico-sanitari per i gruppi della comunit\u00e0.<\/strong> Ma la strada per risolvere l\u2019emergenza \u00e8 appena cominciata.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Con queste belle giornate di sole, cosa facciamo con i nostri figli?<\/strong> Li accompagniamo al parco!\u00a0<strong>Nelle baraccopoli di Mathare<\/strong>, invece, <strong>i bimbi sono molto meno fortunati&#8230;<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-49346","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kenya: dove i bambini giocano fra gli escrementi  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kenya: dove i bambini giocano fra gli escrementi\" \/>\n<meta property=\"og:description\" content=\"Con queste belle giornate di sole, cosa facciamo con i nostri figli? Li accompagniamo al parco!\u00a0Nelle baraccopoli di Mathare, invece, i bimbi sono molto meno fortunati...  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-18T20:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Kenya: dove i bambini giocano fra gli escrementi\",\"datePublished\":\"2013-04-18T20:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/\"},\"wordCount\":499,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/kenya-spazzatura.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/\",\"name\":\"Kenya: dove i bambini giocano fra gli escrementi - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/kenya-spazzatura.jpg\",\"datePublished\":\"2013-04-18T20:29:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/kenya-spazzatura.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/kenya-spazzatura.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kenya: dove i bambini giocano fra gli escrementi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kenya: dove i bambini giocano fra gli escrementi  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/","og_locale":"it_IT","og_type":"article","og_title":"Kenya: dove i bambini giocano fra gli escrementi","og_description":"Con queste belle giornate di sole, cosa facciamo con i nostri figli? Li accompagniamo al parco!\u00a0Nelle baraccopoli di Mathare, invece, i bimbi sono molto meno fortunati...  &nbsp;","og_url":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-04-18T20:29:42+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Kenya: dove i bambini giocano fra gli escrementi","datePublished":"2013-04-18T20:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/"},"wordCount":499,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/","url":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/","name":"Kenya: dove i bambini giocano fra gli escrementi - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg","datePublished":"2013-04-18T20:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/kenya-spazzatura.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/kenya-dove-i-bambini-giocano-fra-gli-escrementi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Kenya: dove i bambini giocano fra gli escrementi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:03:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=49346"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49346\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=49346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=49346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=49346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}