﻿


{"id":49634,"date":"2013-04-26T11:41:24","date_gmt":"2013-04-26T09:41:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=49634"},"modified":"2013-04-26T16:57:52","modified_gmt":"2013-04-26T14:57:52","slug":"spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/","title":{"rendered":"Spagna batte Italia: al via la riforma dell&#8217;affido. Due anni o adozione"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\"><a href=\"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-49643\" alt=\"spagna_affido\" src=\"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/spagna_affido-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Pi\u00f9 case e meno istituti. Pi\u00f9 famiglie e meno operatori.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Mentre in Italia Ai.Bi. sta portando avanti, con forza, ma in mezzo a mille resistenze,<strong> il Manifesto per l\u2019adozione e per l\u2019affido,<\/strong> per chiedere una necessaria e urgente riforma della legge, per fronteggiare l\u2019emergenza abbandono, <strong>il governo spagnolo ha gi\u00e0 varato una riforma importantissima.<\/strong> Ha infatti deciso di velocizzare le procedure dell\u2019affido e dell\u2019adozione dei minori in Spagna. Questa misura, indicata nel Piano dell\u2019Infanzia e dell\u2019Adolescenza che il Consiglio dei Ministri ha approvato luned\u00ec 8 aprile, cerca di far in modo che i minori abbandonati vengano tolti dagli istituti per farli vivere presso una famiglia.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Dei 35.000 bambini e adolescenti che l\u2019Amministrazione ha sotto la sua tutela, circa 15.000 vivono nei centri<\/strong>. Per promuovere e velocizzare il loro affido, le procedure saranno amministrative e non pi\u00f9 giudiziarie, come lo sono adesso, e si cercher\u00e0 appoggio presso le cosiddette \u201c<strong>famiglie d\u2019emergenza<\/strong>\u201d, che gi\u00e0 esistono in alcune regioni autonome. (autonomias)<\/span><\/p>\n<p><span style=\"color: #000000;\">Inoltre verr\u00e0 regolamentata, per la prima volta, l\u2019adozione aperta, una formula di affido in cui i minori possono mantenere il contatto con la famiglia biologica.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<em>Si tratta di dare priorit\u00e0 alle soluzioni familiari di accoglienza (affido) e di adozione piuttosto che a quelle istituzionali<\/em>\u201d ha spiegato <strong>Ana Mato, Ministra della Sanit\u00e0, Servizi Sociali e Uguaglianza,<\/strong> il cui Dipartimento ha elaborato il Piano dell\u2019Infanzia, fra i cui obiettivi vi \u00e8 la riforma della Legge sulla protezione Giuridica del Minore e del Codice Civile.<\/span><\/p>\n<p><span style=\"color: #000000;\">In Spagna,<strong> spetta all\u2019amministrazione dichiarare se un minore sia abbandonato,<\/strong> nel caso in cui i genitori non siano in grado di prendersi cura di lui. In quel caso, al bambino si aprono due diverse prospettive: entrare in un centro o essere affidato ad una famiglia. Quest\u2019ultima opzione era sinora fattibile solo ed esclusivamente con il permesso esplicito della famiglia d\u2019origine o, in mancanza della stessa, con quella di un giudice. <strong>Con la nuova riforma, invece, il permesso accordato ad un minore per andare in affido presso una famiglia lo dar\u00e0 l\u2019amministrazione, con o senza l\u2019approvazione dei genitori biologici.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">La direttrice generale del Servizio per le famiglie e l\u2019Infanzia del Ministero, <strong>Salom\u00e9 Adroher<\/strong>, <strong>ha spiegato<\/strong> che la nuova regolamentazione \u2013 che mira a unificare un panorama normativo diverso in 17 regioni autonome \u2013 contempla, inoltre, <strong>che i minori con et\u00e0 inferiore ai 3 anni non debbano mai essere trasferiti nei centri, ma che debbano necessariamente essere accolti da una famiglia<\/strong>, salvo casi estremi in cui risulti del tutto impossibile o non sia nell\u2019interesse del minore.<\/span><\/p>\n<p><span style=\"color: #000000;\">La nuova riforma prevede due tipi di affido: quello temporale, fino a un massimo di 2 anni di durata; e quello definitivo, che pu\u00f2 considerarsi la premessa per l\u2019adozione.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Dal momento in cui il minore viene considerato dall\u2019Amministrazione come un bambino abbandonato, dovranno allora passare 2 anni prima che ne venga confermata l\u2019adottabilit\u00e0, anche se l\u2019abbandono fosse da subito chiaramente definitivo.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">La nuova regolamentazione stabilir\u00e0 un codice di diritti e doveri per i genitori che prendano in affido i bambini abbandonati: avranno, per esempio, il diritto di essere sentiti dalle autorit\u00e0 prima che queste ultime possano prendere delle decisione in merito ai bambini.<\/span><\/p>\n<p>Fonte:\u00a0<a href=\"http:\/\/adopcionlailusionporserpadres.blogspot.it\/2013\/04\/plan-de-infancia-y-adolescencia-se.html\" target=\"_blank\">&#8220;Adopci\u00f3n la ilusi\u00f3n por ser padres&#8221;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre in Italia sono mesi che si sta perdendo tempo per formare un Governo a cui chiedere una necessaria e urgente riforma della legge sull\u2019adozione e sull\u2019affido,<strong> la Spagna ne ha gi\u00e0 varata una importantissima<\/strong>.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-49634","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spagna batte Italia: al via la riforma dell&#039;affido. Due anni o adozione  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spagna batte Italia: al via la riforma dell&#039;affido. Due anni o adozione\" \/>\n<meta property=\"og:description\" content=\"Mentre in Italia sono mesi che si sta perdendo tempo per formare un Governo a cui chiedere una necessaria e urgente riforma della legge sull\u2019adozione e sull\u2019affido, la Spagna ne ha gi\u00e0 varata una importantissima.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-26T09:41:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-26T14:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Spagna batte Italia: al via la riforma dell&#8217;affido. Due anni o adozione\",\"datePublished\":\"2013-04-26T09:41:24+00:00\",\"dateModified\":\"2013-04-26T14:57:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/\"},\"wordCount\":552,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/spagna_affido.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/\",\"name\":\"Spagna batte Italia: al via la riforma dell'affido. Due anni o adozione - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/spagna_affido.jpg\",\"datePublished\":\"2013-04-26T09:41:24+00:00\",\"dateModified\":\"2013-04-26T14:57:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/spagna_affido.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/spagna_affido.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spagna batte Italia: al via la riforma dell&#8217;affido. Due anni o adozione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spagna batte Italia: al via la riforma dell'affido. Due anni o adozione  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/","og_locale":"it_IT","og_type":"article","og_title":"Spagna batte Italia: al via la riforma dell'affido. Due anni o adozione","og_description":"Mentre in Italia sono mesi che si sta perdendo tempo per formare un Governo a cui chiedere una necessaria e urgente riforma della legge sull\u2019adozione e sull\u2019affido, la Spagna ne ha gi\u00e0 varata una importantissima.","og_url":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-04-26T09:41:24+00:00","article_modified_time":"2013-04-26T14:57:52+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Spagna batte Italia: al via la riforma dell&#8217;affido. Due anni o adozione","datePublished":"2013-04-26T09:41:24+00:00","dateModified":"2013-04-26T14:57:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/"},"wordCount":552,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/","url":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/","name":"Spagna batte Italia: al via la riforma dell'affido. Due anni o adozione - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg","datePublished":"2013-04-26T09:41:24+00:00","dateModified":"2013-04-26T14:57:52+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/spagna_affido.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/spagna-spagna-batte-italiaal-via-la-riforma-dell-affido-due-anni-o-adozione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Spagna batte Italia: al via la riforma dell&#8217;affido. Due anni o adozione"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:03:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=49634"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49634\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=49634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=49634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=49634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}