﻿


{"id":49850,"date":"2013-05-02T15:51:36","date_gmt":"2013-05-02T13:51:36","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=49850"},"modified":"2020-05-22T18:41:57","modified_gmt":"2020-05-22T16:41:57","slug":"progetto-cai-creare-un-sistema-di-protezione-allinfanzia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/","title":{"rendered":"Progetto CAI: creare un sistema di protezione all&#8217;infanzia"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/nepal-quando-riapriranno-le-adozioni%e2%80%a6\/nepal-dal-sito-exposed-planet\/\" rel=\"attachment wp-att-35508\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-35508\" alt=\"Nepal (dal sito Exposed Planet)\" src=\"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>In questi giorni, nella cornice del progetto promosso da Ai.Bi. in Nepal, si sta svolgendo la missione di un\u2019importante esperta nel campo del social work e della protezione dell\u2019infanzia, ovvero la Prof Maria Lyra del Castillo dell\u2019Universit\u00e0 delle Filippine. In questa occasione, l\u2019esperta ha condotto diversi incontri con le autorit\u00e0 locali responsabili del welfare dell\u2019infanzia, quali il Ministero delle donne, dei bambini e del Social Welfare (MoWCSW), e con i dipartimenti direttamente responsabili dell\u2019implementazione di interventi per l\u2019infanzia abbandonata o a rischio. Grazie al programma appositamente preparato dallo staff Ai.Bi., l\u2019esperta ha incontrato anche diverse agenzie che lavorano nel campo della protezione dei bambini, quali UNICEF, Save the Children, Plan International e altre, al fine di condividere le best practices. Soprattutto, la Prof Del Castillo ha tenuto due importanti seminari di formazione per i socialworkers e i docenti degli istituti partner, quali il Social Work Institute, e il St Xavier\u2019s College di Kathmandu. Questi due istituti, grazie al sostegno di un team di consulenti e esperti nepalesi, stanno infatti preparando due corsi di formazione sul tema dei diritti e della protezione dell\u2019infanzia, i quali inizieranno a breve. Un incontro di formazione e di riflessione si \u00e8 tenuto anche con i partners del progetto, al fine di sensibilizzarli sulle pratiche di social work e gli strumenti di intervento con l\u2019infanzia a rischio o abbandonata.<\/p>\n<p>Il contributo dell\u2019esperta \u00e8 stato decisivo al fine di avanzare i lavori previsti dal progetto promosso da Ai.Bi. nel paese, mentre una sua prossima missione sar\u00e0 prevista tra qualche mese quando i due corsi di specializzazione saranno stati ultimati e aperti agli operatori del sociale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questi giorni, nella cornice del progetto promosso da Ai.Bi. in Nepal, si sta svolgendo la missione di un&rsquo;importante esperta nel campo del social work e della protezione dell&rsquo;infanzia, ovvero la Prof Maria Lyra del Castillo dell&rsquo;Universit&agrave; delle Filippine. In questa occasione, l&rsquo;esperta ha condotto diversi incontri con le autorit&agrave; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-49850","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Progetto CAI: creare un sistema di protezione all&#039;infanzia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetto CAI: creare un sistema di protezione all&#039;infanzia\" \/>\n<meta property=\"og:description\" content=\"In questi giorni, nella cornice del progetto promosso da Ai.Bi. in Nepal, si sta svolgendo la missione di un&rsquo;importante esperta nel campo del social work e della protezione dell&rsquo;infanzia, ovvero la Prof Maria Lyra del Castillo dell&rsquo;Universit&agrave; delle Filippine. In questa occasione, l&rsquo;esperta ha condotto diversi incontri con le autorit&agrave; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-02T13:51:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-22T16:41:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Progetto CAI: creare un sistema di protezione all&#8217;infanzia\",\"datePublished\":\"2013-05-02T13:51:36+00:00\",\"dateModified\":\"2020-05-22T16:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Nepal-dal-sito-Exposed-Planet.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/\",\"name\":\"Progetto CAI: creare un sistema di protezione all'infanzia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Nepal-dal-sito-Exposed-Planet.jpg\",\"datePublished\":\"2013-05-02T13:51:36+00:00\",\"dateModified\":\"2020-05-22T16:41:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Nepal-dal-sito-Exposed-Planet.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Nepal-dal-sito-Exposed-Planet.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Progetto CAI: creare un sistema di protezione all&#8217;infanzia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Progetto CAI: creare un sistema di protezione all'infanzia - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/","og_locale":"it_IT","og_type":"article","og_title":"Progetto CAI: creare un sistema di protezione all'infanzia","og_description":"In questi giorni, nella cornice del progetto promosso da Ai.Bi. in Nepal, si sta svolgendo la missione di un&rsquo;importante esperta nel campo del social work e della protezione dell&rsquo;infanzia, ovvero la Prof Maria Lyra del Castillo dell&rsquo;Universit&agrave; delle Filippine. In questa occasione, l&rsquo;esperta ha condotto diversi incontri con le autorit&agrave; [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-05-02T13:51:36+00:00","article_modified_time":"2020-05-22T16:41:57+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Progetto CAI: creare un sistema di protezione all&#8217;infanzia","datePublished":"2013-05-02T13:51:36+00:00","dateModified":"2020-05-22T16:41:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/"},"wordCount":291,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/","url":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/","name":"Progetto CAI: creare un sistema di protezione all'infanzia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg","datePublished":"2013-05-02T13:51:36+00:00","dateModified":"2020-05-22T16:41:57+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Nepal-dal-sito-Exposed-Planet.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/progetto-cai-creare-un-sistema-di-protezione-allinfanzia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Progetto CAI: creare un sistema di protezione all&#8217;infanzia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:06:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=49850"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/49850\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=49850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=49850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=49850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}