﻿


{"id":5015,"date":"2009-03-06T16:12:25","date_gmt":"2009-03-06T15:12:25","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=5015"},"modified":"2009-03-06T16:58:01","modified_gmt":"2009-03-06T15:58:01","slug":"al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/","title":{"rendered":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5023\" style=\"margin: 10px;\" title=\"aibi-fila-di-bimbi1\" src=\"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>(Milano) &#8220;Crisi economica e nuova povert\u00e0: la necessit\u00e0 di essere solidali&#8221;, \u00e8 questo il titolo del 10\u00b0 Forum nazionale del Sostegno a Distanza che si apre oggi a Milano.<br \/>\nL&#8217;evento si svolge dal 6 all&#8217;8 marzo presso il Centro Congressi della Provincia di Milano ed \u00e8 organizzato dall&#8217;Assessorato alla Pace, Cooperazione Internazionale, Partecipazione e Politiche Giovanili della Provincia di Milano in collaborazione con il Forum Permanente per il Sostegno a Distanza (ForumSaD) e il Coordinamento Enti Locali Sostegno a distanza ELSAD e con il Patrocinio RAI Segretariato Sociale.<strong>Il Programma in agenda<\/strong><\/p>\n<p>I lavori si aprono <strong>venerd\u00ec 6 marzo con il tema &#8220;Educare ai Saperi, Educare alle Diversit\u00e0<\/strong>&#8221; cui seguir\u00e0 una tavola rotonda e dibattito con gli insegnanti, nonch\u00e9 il lancio del Concorso internazionale per l&#8217;anno scolastico 2009\/2010 &#8220;Il Sostegno a distanza per il diritto all&#8217;istruzione.<\/p>\n<p>Il concorso, aperto alle associazioni di sostegno a distanza, alle scuole, agli studenti e insegnanti nasce dall&#8217;esigenza di illustrare i risultati e le buone pratiche che si realizzano soprattutto in campo scolastico attraverso la partecipazione a progetti di Sostegno a Distanza e ad attivit\u00e0 di educazione multiculturale.<\/p>\n<p>I lavori, le proposte e le esperienze realizzate (racconti, poesie, lettere, disegni, fotografie, diapositive, video, cd, dvd, composizioni musicali) saranno esposti nell&#8217;ambito di una Mostra che sar\u00e0 esposta nel febbraio 2010 a Udine in occasione dell&#8217;XI Forum Nazionale del Sostegno a Distanza. Forumsad ed Elsad saranno impegnati affinch\u00e9 la Mostra divenga itinerante e nel 2010 possa essere esposta anche in altre citt\u00e0.<\/p>\n<p><strong>Sabato 7 marzo sar\u00e0 affrontato il tema &#8220;Dalla crisi globale al nuovo mondo possibile<\/strong>&#8220;, la giornata sar\u00e0 moderata dal giornalista del Segretariato Sociale RAI, Carlo Romeo. Nel corso della mattinata si allargher\u00e0 la prospettiva agli scenari in cui la lotta alla povert\u00e0 rende necessario un cambiamento che sappia cogliere le potenzialit\u00e0 di cui il Sostegno a Distanza \u00e8 uno degli strumenti pi\u00f9 diffusi.<\/p>\n<p>Nella sessione pomeridiana verranno passate in rassegna le buone pratiche del Sostegno a Distanza. Sulla base del Protocollo di Intesa stipulato tra l&#8217;Agenzia per le Onlus e Forumsad, verr\u00e0 approfondito il lavoro che ha coinvolto le Associazioni, gli Enti del coordinamento Elsad e l&#8217;Agenzia per le Onlus per l&#8217;emanazione delle Linee Guida sul Sostegno a Distanza per favorire informazione e trasparenza. La valorizzazione delle buone pratiche di Sostegno a Distanza sar\u00e0 una parte importante di queste Linee Guida e il 10\u00b0 Forum costituir\u00e0 un&#8217;occasione preziosa per farle emergere.<br \/>\nDurante la sessione pomeridiana, il responsabile dell&#8217;ufficio Sostegno a Distanza di Ai.Bi., <strong>Cristiano Campari, illustrer\u00e0 l&#8217;importanza delle attivit\u00e0 di comunicazione<\/strong> destinate ai sostenitori quale elemento di miglioramento del Sostegno a Distanza. Facilitare lo scambio di informazioni con i bambini sostenuti, coinvolgere il sostenitore con visite sul campo: sono tutte attivit\u00e0 indispensabili per rendere significativa la relazione tra sostenitori e bambini.<\/p>\n<p>A conclusione dell&#8217;evento, domenica 8 marzo, i lavori si chiuderanno con una riflessione sul tema &#8220;Coerenze, impegni e sinergie per una nuova cooperazione internazionale&#8221; a cui sono stati invitati a partecipare i rappresentanti del settore<\/p>\n<p><strong>Gli appuntamenti proposti dal Forum<\/strong><\/p>\n<p>Venerd\u00ec 6 marzo viene presentato per le scuole il film &#8220;Parada&#8221;, primo lungometraggio di Marco Pontecorvo ispirato alla storia del clown francese Miloud che parteciper\u00e0 alla proiezione e alla tavola rotonda del giorno successivo.<\/p>\n<p>Sabato 7 marzo, alle ore 21, con l&#8217;Orchestra di Via Padova, l&#8217;orchestra multietnica di Milano composta da 15 musicisti di nove nazionalit\u00e0 diverse, la cui musica meticcia spazia dalle ballate dell&#8217;Europa dell&#8217;Est ai travolgenti ritmi gitani, dai tamburi africani agli archi e ai violini della tradizione mitteleuropea, conditi con ritmi funky, jazz e blues di stampo afroamericano. L&#8217;ingresso \u00e8 gratuito.<\/p>\n<p>Da venerd\u00ec a domenica sar\u00e0 possibile conoscere i progetti delle associazioni aderenti al ForumSad, tra cui Ai.Bi., attraverso le fotografie dei bambini beneficiari dei progetti del Sostegno a distanza. Nel Centro Congressi \u00e8 stata allestita, infatti, una mostra che propone una selezione di immagini e testi che raccontano in maniera semplice e diretta le attivit\u00e0 di Sostegno a distanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Milano) &ldquo;Crisi economica e nuova povert&agrave;: la necessit&agrave; di essere solidali&rdquo;, &egrave; questo il titolo del 10&deg; Forum nazionale del Sostegno a Distanza che si apre oggi a Milano. L&rsquo;evento si svolge dal 6 all&rsquo;8 marzo presso il Centro Congressi della Provincia di Milano ed &egrave; organizzato dall&rsquo;Assessorato alla Pace, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-5015","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/al-via-il-10\u00b0-forum-nazionale-del-sostegno-a-distanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza\" \/>\n<meta property=\"og:description\" content=\"(Milano) &ldquo;Crisi economica e nuova povert&agrave;: la necessit&agrave; di essere solidali&rdquo;, &egrave; questo il titolo del 10&deg; Forum nazionale del Sostegno a Distanza che si apre oggi a Milano. L&rsquo;evento si svolge dal 6 all&rsquo;8 marzo presso il Centro Congressi della Provincia di Milano ed &egrave; organizzato dall&rsquo;Assessorato alla Pace, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/al-via-il-10\u00b0-forum-nazionale-del-sostegno-a-distanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-06T15:12:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-03-06T15:58:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza\",\"datePublished\":\"2009-03-06T15:12:25+00:00\",\"dateModified\":\"2009-03-06T15:58:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-fila-di-bimbi1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/\",\"name\":\"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-fila-di-bimbi1.jpg\",\"datePublished\":\"2009-03-06T15:12:25+00:00\",\"dateModified\":\"2009-03-06T15:58:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-fila-di-bimbi1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-fila-di-bimbi1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/al-via-il-10\u00b0-forum-nazionale-del-sostegno-a-distanza\/","og_locale":"it_IT","og_type":"article","og_title":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza","og_description":"(Milano) &ldquo;Crisi economica e nuova povert&agrave;: la necessit&agrave; di essere solidali&rdquo;, &egrave; questo il titolo del 10&deg; Forum nazionale del Sostegno a Distanza che si apre oggi a Milano. L&rsquo;evento si svolge dal 6 all&rsquo;8 marzo presso il Centro Congressi della Provincia di Milano ed &egrave; organizzato dall&rsquo;Assessorato alla Pace, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/al-via-il-10\u00b0-forum-nazionale-del-sostegno-a-distanza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2009-03-06T15:12:25+00:00","article_modified_time":"2009-03-06T15:58:01+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza","datePublished":"2009-03-06T15:12:25+00:00","dateModified":"2009-03-06T15:58:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/"},"wordCount":661,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/","url":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/","name":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg","datePublished":"2009-03-06T15:12:25+00:00","dateModified":"2009-03-06T15:58:01+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-fila-di-bimbi1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/al-via-il-10%c2%b0-forum-nazionale-del-sostegno-a-distanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Al via il 10\u00b0 Forum Nazionale del Sostegno a Distanza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:22:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=5015"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5015\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=5015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=5015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=5015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}