﻿


{"id":50508,"date":"2013-05-13T19:40:50","date_gmt":"2013-05-13T17:40:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=50508"},"modified":"2013-05-14T12:35:27","modified_gmt":"2013-05-14T10:35:27","slug":"messina-25-maggio-limportanze-delle-adozioni-internazionali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/","title":{"rendered":"Messina, 25 Maggio. L&#8217;importanza delle adozioni internazionali!"},"content":{"rendered":"<p><strong>OPEN DAY ADOZIONI INTERNAZIONALI, Sabato 25 maggio.<\/strong><\/p>\n<p>Nelle principali citt\u00e0 italiane Ai.Bi. Amici dei Bambini, organizza una giornata di informazione sull\u2019Adozione internazionale, dedicata a tutti coloro che vogliono conoscere meglio questa straordinaria forma di accoglienza.<\/p>\n<p>Il Programma della citt\u00e0 di Messina:<\/p>\n<p>ore 15.30 Accoglienza e presentazione degli ospite: l&#8217;attore Gabriele Greco e i Responsabili dei servizi sociali di Messina.<br \/>\nore 15.40 Antonio e Daniela Sanseverini: la nostra storia di adozione e il GFL<br \/>\nore 16.00 Padre Giuseppe Ruggeri e la spiritualit\u00e0 dell\u2019adozione<br \/>\nore 16.20 Martina Musumeci: L\u2019accompagnamento psicologico delle coppie nel percorso adottivo<br \/>\nore 16.40 Cristina e Pietro Raitano: le nostre splendide cilene!<br \/>\nore 17.00 Dinah Caminit: Ai.Bi. e la nuova proposta di legge<br \/>\nore 17.20 Ai.Bi. Giovani: la nuova voce dell\u2019adozione e flesh mob contro l&#8217;abbandono<br \/>\nore 17.40 Famiglia Smedile: Dalla Russia con il piccolo Danilo<br \/>\nore 18.00 Cettina e Mimmo Puleio: la Bulgaria ci ha donato due gemelle eccezionali.<br \/>\nore 18.20 In Cina dal viaggio di nozze all\u2019abbraccio dei nostri figli!<br \/>\nore 18.40 Mariateresa Caminiti: l\u2019inserimento del minore straniero a scuola<br \/>\nore 19.00 Famiglia Vinci: Il nostro tesoro lo abbiamo trovato in Africa!<br \/>\nore 19.30 Rita e Orazio Cavallaro: il nostro pi\u00f9 bel regalo arriva dalla Colombia<\/p>\n<p>Dove?<\/p>\n<p>Palacultura Antonello da Messina<\/p>\n<p>Viale Boccetta, 373 &#8211; Messina P.s.<\/p>\n<p>&nbsp;<\/p>\n<p>Sede Ai.Bi. Messina:<\/p>\n<p>c\/o Parrocchia S. Francesco D\u2019Assisi San<br \/>\nLicanto<br \/>\nVia Leonardo Sciascia 2<br \/>\n98168 Messina<br \/>\nTel 090 48101<br \/>\nmessina@aibi.it<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OPEN DAY ADOZIONI INTERNAZIONALI, Sabato 25 maggio. Nelle principali citt&agrave; italiane Ai.Bi. Amici dei Bambini, organizza una giornata di informazione sull&rsquo;Adozione internazionale, dedicata a tutti coloro che vogliono conoscere meglio questa straordinaria forma di accoglienza. Il Programma della citt&agrave; di Messina: ore 15.30 Accoglienza e presentazione degli ospite: l&rsquo;attore Gabriele [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50508","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Messina, 25 Maggio. L&#039;importanza delle adozioni internazionali! - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messina, 25 Maggio. L&#039;importanza delle adozioni internazionali!\" \/>\n<meta property=\"og:description\" content=\"OPEN DAY ADOZIONI INTERNAZIONALI, Sabato 25 maggio. Nelle principali citt&agrave; italiane Ai.Bi. Amici dei Bambini, organizza una giornata di informazione sull&rsquo;Adozione internazionale, dedicata a tutti coloro che vogliono conoscere meglio questa straordinaria forma di accoglienza. Il Programma della citt&agrave; di Messina: ore 15.30 Accoglienza e presentazione degli ospite: l&rsquo;attore Gabriele [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-13T17:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-05-14T10:35:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Messina, 25 Maggio. L&#8217;importanza delle adozioni internazionali!\",\"datePublished\":\"2013-05-13T17:40:50+00:00\",\"dateModified\":\"2013-05-14T10:35:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/\",\"name\":\"Messina, 25 Maggio. L'importanza delle adozioni internazionali! - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2013-05-13T17:40:50+00:00\",\"dateModified\":\"2013-05-14T10:35:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/messina-25-maggio-limportanze-delle-adozioni-internazionali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Messina, 25 Maggio. L&#8217;importanza delle adozioni internazionali!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Messina, 25 Maggio. L'importanza delle adozioni internazionali! - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/","og_locale":"it_IT","og_type":"article","og_title":"Messina, 25 Maggio. L'importanza delle adozioni internazionali!","og_description":"OPEN DAY ADOZIONI INTERNAZIONALI, Sabato 25 maggio. Nelle principali citt&agrave; italiane Ai.Bi. Amici dei Bambini, organizza una giornata di informazione sull&rsquo;Adozione internazionale, dedicata a tutti coloro che vogliono conoscere meglio questa straordinaria forma di accoglienza. Il Programma della citt&agrave; di Messina: ore 15.30 Accoglienza e presentazione degli ospite: l&rsquo;attore Gabriele [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-05-13T17:40:50+00:00","article_modified_time":"2013-05-14T10:35:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Messina, 25 Maggio. L&#8217;importanza delle adozioni internazionali!","datePublished":"2013-05-13T17:40:50+00:00","dateModified":"2013-05-14T10:35:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/"},"wordCount":238,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/","url":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/","name":"Messina, 25 Maggio. L'importanza delle adozioni internazionali! - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2013-05-13T17:40:50+00:00","dateModified":"2013-05-14T10:35:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/messina-25-maggio-limportanze-delle-adozioni-internazionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Messina, 25 Maggio. L&#8217;importanza delle adozioni internazionali!"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:24:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/50508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=50508"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/50508\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=50508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=50508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=50508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}