﻿


{"id":51610,"date":"2013-05-31T16:00:57","date_gmt":"2013-05-31T14:00:57","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=51610"},"modified":"2013-06-03T11:45:56","modified_gmt":"2013-06-03T09:45:56","slug":"10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/","title":{"rendered":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d.  Un momento dedicato alle famiglie"},"content":{"rendered":"<p><strong>Luned\u00ec 10 Giugno,dalle ore 9.15 alle ore 14.00,<\/strong> si terr\u00e0 a Bologna, presso l&#8217;aula 3 &#8211; Centro Riesco &#8211; Via Ca Selvatica, 7, un incontro formativo con l&#8217;esperto giuridico <strong>Avv.Dario Vinci<\/strong> sulla tematica: <em>\u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned&igrave; 10 Giugno,dalle ore 9.15 alle ore 14.00, si terr&agrave; a Bologna, presso l&rsquo;aula 3 &ndash; Centro Riesco &ndash; Via Ca Selvatica, 7, un incontro formativo con l&rsquo;esperto giuridico Avv.Dario Vinci sulla tematica: &ldquo;Responsabilit&agrave; giuridica delle comunit&agrave; per minori, dei servizi e delle famiglie affidatarie&rdquo;. &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-51610","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie\" \/>\n<meta property=\"og:description\" content=\"Luned&igrave; 10 Giugno,dalle ore 9.15 alle ore 14.00, si terr&agrave; a Bologna, presso l&rsquo;aula 3 &ndash; Centro Riesco &ndash; Via Ca Selvatica, 7, un incontro formativo con l&rsquo;esperto giuridico Avv.Dario Vinci sulla tematica: &ldquo;Responsabilit&agrave; giuridica delle comunit&agrave; per minori, dei servizi e delle famiglie affidatarie&rdquo;. &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-31T14:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-06-03T09:45:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie\",\"datePublished\":\"2013-05-31T14:00:57+00:00\",\"dateModified\":\"2013-06-03T09:45:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/\"},\"wordCount\":66,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/\",\"name\":\"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2013-05-31T14:00:57+00:00\",\"dateModified\":\"2013-06-03T09:45:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/","og_locale":"it_IT","og_type":"article","og_title":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie","og_description":"Luned&igrave; 10 Giugno,dalle ore 9.15 alle ore 14.00, si terr&agrave; a Bologna, presso l&rsquo;aula 3 &ndash; Centro Riesco &ndash; Via Ca Selvatica, 7, un incontro formativo con l&rsquo;esperto giuridico Avv.Dario Vinci sulla tematica: &ldquo;Responsabilit&agrave; giuridica delle comunit&agrave; per minori, dei servizi e delle famiglie affidatarie&rdquo;. &nbsp; &nbsp;","og_url":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-05-31T14:00:57+00:00","article_modified_time":"2013-06-03T09:45:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie","datePublished":"2013-05-31T14:00:57+00:00","dateModified":"2013-06-03T09:45:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/"},"wordCount":66,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/","url":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/","name":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2013-05-31T14:00:57+00:00","dateModified":"2013-06-03T09:45:56+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/10-giugno-bologna-incontro-informativo-responsabilita-giuridica-delle-comunita-per-minori-dei-servizi-e-delle-famiglie-affidatarie-un-momento-dedicato-alle-famiglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"10 Giugno, Bologna: Incontro informativo \u201cResponsabilit\u00e0 giuridica delle comunit\u00e0 per minori, dei servizi e delle famiglie affidatarie\u201d. Un momento dedicato alle famiglie"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/51610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=51610"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/51610\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=51610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=51610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=51610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}