﻿


{"id":5242,"date":"2009-03-17T10:59:05","date_gmt":"2009-03-17T09:59:05","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=5242"},"modified":"2009-03-17T13:01:14","modified_gmt":"2009-03-17T12:01:14","slug":"congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/","title":{"rendered":"Congo, Vescovo di Bondo: &#8220;dopo attacchi situazione civili critica&#8221;"},"content":{"rendered":"<p>(Kinshasa) &#8220;I ribelli stanno tuttora occupando i villaggi di Banda e Boeli, almeno 2000 persone sono in fuga e le loro condizioni sono rese pi\u00f9 difficili dal caldo e dalla scarsit\u00e0 di acqua; qui \u00e8 la stagione secca e le temperature vanno dai 40 ai 45 gradi&#8221;: raggiunto dalla MISNA, <strong>il vescovo di Bondo, monsignor Etienne Ung&#8217;eyowun, conferma la notizia di un&#8217;incursione dei ribelli ugandesi<\/strong> dell&#8217;Esercito di resistenza del Signore (Lord&#8217;s resistance army, Lra) nella sua diocesi aggiungendo che si tratta di piccoli gruppi armati: &#8220;In passato la loro presenza era stata pi\u00f9 volte segnalata &#8211; ha detto ancora il vescovo &#8211; questa \u00e8 la prima volta che attaccano la popolazione civile in maniera cos\u00ec brutale e in una zona distante centinaia di chilometri dal parco della Garamba, area in cui erano soliti operare; in base alle informazioni in nostro possesso almeno due persone sono state uccise, in 200 sono stati sequestrati, alcune migliaia sono in fuga, hanno raggiunto o stanno raggiungendo le localit\u00e0 di Amadi e Dakwa&#8221;.<\/p>\n<p>Secondo il presule, non \u00e8 un caso che l&#8217;attacco sia avvenuto domenica, nel giorno in cui si \u00e8 svolta la cerimonia che ha segnato l&#8217;inizio del ritiro dell&#8217;esercito ugandese dalla Provincia orientale dove da dicembre era in corso un&#8217;operazione militare congiunta contro i ribelli: &#8220;Potrebbe essere stato un segnale per dire che nonostante bombardamenti e operazioni militari, i ribelli sono ancora attivi e capaci di resistere &#8211; ha concluso monsignor Ung&#8217;eyowun &#8211; ma ci\u00f2 che ci preoccupa maggiormente sono le<strong> conseguenze delle violenze sulla popolazione civile<\/strong> e la quasi completa assenze delle autorit\u00e0 e di organizzazioni umanitarie&#8221;. I pi\u00f9 aggiornati dati dell&#8217;Ufficio dell&#8217;Onu per il coordinamento degli affari umanitari (Ocha) indicano che le incursioni dei ribelli Lra hanno causato da settembre la fuga di oltre 181.000 persone cui bisogna aggiungerne altre 15.581 che hanno trovato rifugio oltreconfine in Sud Sudan; gli attacchi hanno inoltre causato non meno di 900 vittime.<\/p>\n<p>\u00a0<\/p>\n<p>(fonte: Misna)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Kinshasa) &ldquo;I ribelli stanno tuttora occupando i villaggi di Banda e Boeli, almeno 2000 persone sono in fuga e le loro condizioni sono rese pi&ugrave; difficili dal caldo e dalla scarsit&agrave; di acqua; qui &egrave; la stagione secca e le temperature vanno dai 40 ai 45 gradi&rdquo;: raggiunto dalla MISNA, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-5242","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo, Vescovo di Bondo: &quot;dopo attacchi situazione civili critica&quot;  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congo, Vescovo di Bondo: &quot;dopo attacchi situazione civili critica&quot;\" \/>\n<meta property=\"og:description\" content=\"(Kinshasa) &ldquo;I ribelli stanno tuttora occupando i villaggi di Banda e Boeli, almeno 2000 persone sono in fuga e le loro condizioni sono rese pi&ugrave; difficili dal caldo e dalla scarsit&agrave; di acqua; qui &egrave; la stagione secca e le temperature vanno dai 40 ai 45 gradi&rdquo;: raggiunto dalla MISNA, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-17T09:59:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-03-17T12:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Congo, Vescovo di Bondo: &#8220;dopo attacchi situazione civili critica&#8221;\",\"datePublished\":\"2009-03-17T09:59:05+00:00\",\"dateModified\":\"2009-03-17T12:01:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/\",\"name\":\"Congo, Vescovo di Bondo: \\\"dopo attacchi situazione civili critica\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2009-03-17T09:59:05+00:00\",\"dateModified\":\"2009-03-17T12:01:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Congo, Vescovo di Bondo: &#8220;dopo attacchi situazione civili critica&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo, Vescovo di Bondo: \"dopo attacchi situazione civili critica\"  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/","og_locale":"it_IT","og_type":"article","og_title":"Congo, Vescovo di Bondo: \"dopo attacchi situazione civili critica\"","og_description":"(Kinshasa) &ldquo;I ribelli stanno tuttora occupando i villaggi di Banda e Boeli, almeno 2000 persone sono in fuga e le loro condizioni sono rese pi&ugrave; difficili dal caldo e dalla scarsit&agrave; di acqua; qui &egrave; la stagione secca e le temperature vanno dai 40 ai 45 gradi&rdquo;: raggiunto dalla MISNA, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2009-03-17T09:59:05+00:00","article_modified_time":"2009-03-17T12:01:14+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Congo, Vescovo di Bondo: &#8220;dopo attacchi situazione civili critica&#8221;","datePublished":"2009-03-17T09:59:05+00:00","dateModified":"2009-03-17T12:01:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/"},"wordCount":329,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/","url":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/","name":"Congo, Vescovo di Bondo: \"dopo attacchi situazione civili critica\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2009-03-17T09:59:05+00:00","dateModified":"2009-03-17T12:01:14+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/congo-vescovo-di-bondo-dopo-attacchi-situazione-civili-critica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Congo, Vescovo di Bondo: &#8220;dopo attacchi situazione civili critica&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=5242"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5242\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=5242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=5242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=5242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}