﻿


{"id":53150,"date":"2013-07-02T17:00:18","date_gmt":"2013-07-02T15:00:18","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=53150"},"modified":"2013-07-02T17:01:10","modified_gmt":"2013-07-02T15:01:10","slug":"10-luglio-pane-olio-special-lounge-art","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/","title":{"rendered":"10 Luglio: Pane &#038; Olio, Special Lounge Art"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-26692\" alt=\"PANE-E-OLIO\" src=\"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg 100w, https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1-55x55.jpg 55w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/a>Si terr\u00e0 \u00a0mercoled\u00ec <strong>10 Luglio<\/strong> alle<strong> ore 16.30<\/strong>, in Lungo Tevere dei Vallati 10, \u00a0il consueto appuntamento con <strong>Pane &amp; Olio.<\/strong><\/p>\n<p>Lo speciale Lounge Art, vedr\u00e0 la partecipazione di<strong> Laura Anfuso<\/strong>, esperta di animazione e promozione della lettura e di<strong>\u00a0Stefano Degli Abbati,<\/strong> medico della Croce Rossa. Introdurr\u00e0 l&#8217;evento <strong>Luca Pasquale<\/strong> con &#8220;Punti di vista da Hopper a Botticelli&#8221;, legge <strong>Marzia Masiello<\/strong>.<\/p>\n<p>A finire, il <strong>consueto spuntino con pane e olio.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO-luglio-2013.pdf\">Leggi la locandina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si terr&agrave; &nbsp;mercoled&igrave; 10 Luglio alle ore 16.30, in Lungo Tevere dei Vallati 10, &nbsp;il consueto appuntamento con Pane &amp; Olio. Lo speciale Lounge Art, vedr&agrave; la partecipazione di Laura Anfuso, esperta di animazione e promozione della lettura e di&nbsp;Stefano Degli Abbati, medico della Croce Rossa. Introdurr&agrave; l&rsquo;evento Luca Pasquale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-53150","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10 Luglio: Pane &amp; Olio, Special Lounge Art - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Luglio: Pane &amp; Olio, Special Lounge Art\" \/>\n<meta property=\"og:description\" content=\"Si terr&agrave; &nbsp;mercoled&igrave; 10 Luglio alle ore 16.30, in Lungo Tevere dei Vallati 10, &nbsp;il consueto appuntamento con Pane &amp; Olio. Lo speciale Lounge Art, vedr&agrave; la partecipazione di Laura Anfuso, esperta di animazione e promozione della lettura e di&nbsp;Stefano Degli Abbati, medico della Croce Rossa. Introdurr&agrave; l&rsquo;evento Luca Pasquale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-02T15:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-07-02T15:01:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"10 Luglio: Pane &#038; Olio, Special Lounge Art\",\"datePublished\":\"2013-07-02T15:00:18+00:00\",\"dateModified\":\"2013-07-02T15:01:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PANE-E-OLIO1.jpg\",\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/\",\"name\":\"10 Luglio: Pane & Olio, Special Lounge Art - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PANE-E-OLIO1.jpg\",\"datePublished\":\"2013-07-02T15:00:18+00:00\",\"dateModified\":\"2013-07-02T15:01:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PANE-E-OLIO1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PANE-E-OLIO1.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/10-luglio-pane-olio-special-lounge-art\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 Luglio: Pane &#038; Olio, Special Lounge Art\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 Luglio: Pane & Olio, Special Lounge Art - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/","og_locale":"it_IT","og_type":"article","og_title":"10 Luglio: Pane & Olio, Special Lounge Art","og_description":"Si terr&agrave; &nbsp;mercoled&igrave; 10 Luglio alle ore 16.30, in Lungo Tevere dei Vallati 10, &nbsp;il consueto appuntamento con Pane &amp; Olio. Lo speciale Lounge Art, vedr&agrave; la partecipazione di Laura Anfuso, esperta di animazione e promozione della lettura e di&nbsp;Stefano Degli Abbati, medico della Croce Rossa. Introdurr&agrave; l&rsquo;evento Luca Pasquale [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-07-02T15:00:18+00:00","article_modified_time":"2013-07-02T15:01:10+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"10 Luglio: Pane &#038; Olio, Special Lounge Art","datePublished":"2013-07-02T15:00:18+00:00","dateModified":"2013-07-02T15:01:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/"},"wordCount":79,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg","articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/","url":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/","name":"10 Luglio: Pane & Olio, Special Lounge Art - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg","datePublished":"2013-07-02T15:00:18+00:00","dateModified":"2013-07-02T15:01:10+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/PANE-E-OLIO1.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/10-luglio-pane-olio-special-lounge-art\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"10 Luglio: Pane &#038; Olio, Special Lounge Art"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:31:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/53150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=53150"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/53150\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=53150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=53150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=53150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}