﻿


{"id":5368,"date":"2009-03-20T14:25:53","date_gmt":"2009-03-20T13:25:53","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=5368"},"modified":"2009-03-20T15:00:02","modified_gmt":"2009-03-20T14:00:02","slug":"brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/","title":{"rendered":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare"},"content":{"rendered":"<p>(Milano) Si apre sabato 21 marzo, a San Paolo in Brasile, il 7\u00b0 Incontro Nazionale della Pastorale Familiare. La giornata, dedicata alla dimensione spirituale dell&#8217;adozione, vedr\u00e0 la partecipazione del Presidente di Ai.Bi. Marco Griffini e la Responsabile del Settore Adozioni internazionali dell&#8217;associazione Irene Bertuzzi.<\/p>\n<p>Griffini e Bertuzzi, oltre a essere i fondatori di Ai.Bi., hanno costituito nel 2007 <strong>l&#8217;Associazione &#8220;La pietra scartata&#8221;<\/strong>: un movimento di famiglie adottive e affidatarie unite per testimoniare il senso cristiano dell&#8217;accoglienza, arricchito dall&#8217;esperienza di fede e approfondito dalla riflessione teologica. &#8220;La Pietra Scartata&#8221; intende promuovere l&#8217;affido e l&#8217;adozione con attivit\u00e0 di sensibilizzazione e formazione delle famiglie e delle comunit\u00e0 locali.<\/p>\n<p>Proprio dall&#8217;esperienza di Ai.Bi. e &#8220;La pietra scartata&#8221;, Griffini prender\u00e0 spunto per presentare una <strong>serie di proposte per una spiritualit\u00e0 dell&#8217;adozione<\/strong>.<\/p>\n<p>La prima proposta si ispira alle parole di Papa Benedetto XVI \u00a0&#8220;Essere Chiesa, essere famiglia di Dio nel mondo&#8221; per mettere in luce il cammino di Grazia delle coppie sterili che, con l&#8217;accoglienza di un bambino abbandonato, scoprono <strong>una nuova forma di fecondit\u00e0<\/strong>, non pi\u00f9 biologica ma spirituale e sociale. Il non avere figli pu\u00f2 scatenare nella coppia un dolore profondo che tuttavia pu\u00f2 sfociare nella Grazia dell&#8217;adozione di un bambino, destinato dalla Provvidenza alla coppia.<\/p>\n<p>La seconda prende in esame il metodo di formazione di Ai.Bi. e de &#8220;La pietra scartata&#8221; per sottolineare l&#8217;importanza dell<strong>&#8216;accompagnamento delle coppie<\/strong> nel percorso adottivo. Investire sulla formazione degli operatori locali, creare uno staff di psicologi ed educatori sono passaggi fondamentali per seguire nel migliore dei modi una famiglia che si apre all&#8217;adozione.<\/p>\n<p>La <strong>Benedizione delle adozioni<\/strong> rappresenta un&#8217;esperienza innovativa proposta da &#8220;La Pietra scartata&#8221; per riconoscere l&#8217;adozione come atto di fede, non solo giuridico. Verr\u00e0 quindi presentata a San Paolo, come terza proposta operativa, il Rito della Benedizione, con una riflessione sull&#8217;identit\u00e0, il significato e le prospettive di sviluppo di questa originale e importante celebrazione. Prendendo come esempio l&#8217;esperienza che si \u00e8 avuta in Italia si allargher\u00e0 la prospettiva della celebrazione del rito anche al Brasile.<\/p>\n<p>La quarta proposta riguarda il percorso di formazione finalizzato a sostenere la <strong>nascita di Associazioni di genitori<\/strong> e famiglie adottive. Partendo dall&#8217;esperienza di Ai.Bi. e &#8220;La Pietra scartata&#8221;, si tenter\u00e0 di illustrare i passi da seguire per promuovere la creazione di associazioni familiari, linfa vitale del sistema di accoglienza di un Paese.<\/p>\n<p>L&#8217;apertura di una <strong>rete di Centri Studi<\/strong> per la spiritualit\u00e0 dell&#8217;accoglienza familiare \u00e8 un&#8217;ulteriore proposta. Quello del Centro Studi \u00e8 un modello gi\u00e0 seguito da Ai.Bi. per promuovere una serie di attivit\u00e0 (editoriali, seminariali, interconfessionali, di ricerca) finalizzate a far conoscere la dimensione culturale e spirituale dell&#8217;accoglienza familiare, non solo agli addetti ai lavori ma anche all&#8217;intera comunit\u00e0.<\/p>\n<p>Un&#8217;ultima proposta riguarda l&#8217;organizzazione di un <strong>Ciclo di incontri nelle Regioni Episcopali<\/strong> per presentare e promuovere il programma complessivo delle attivit\u00e0, delle prospettive pastorali e sociali dell&#8217;iniziativa. In tal senso \u00e8 prevista l&#8217;organizzazione di un servizio di sportello territoriale e di un programma periodico di appuntamenti nelle Parrocchie e le Comunit\u00e0 locali per assicurare: momenti di sensibilizzazione sulle tematiche del diritto alla famiglia e dell&#8217;adozione; attivit\u00e0 di informazione; cammini di spiritualit\u00e0 dell&#8217;accoglienza familiare; attivit\u00e0 di accompagnamento e sostegno dell&#8217;accoglienza.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Milano) Si apre sabato 21 marzo, a San Paolo in Brasile, il 7&deg; Incontro Nazionale della Pastorale Familiare. La giornata, dedicata alla dimensione spirituale dell&rsquo;adozione, vedr&agrave; la partecipazione del Presidente di Ai.Bi. Marco Griffini e la Responsabile del Settore Adozioni internazionali dell&rsquo;associazione Irene Bertuzzi. Griffini e Bertuzzi, oltre a essere [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-5368","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7\u00b0-incontro-della-pastorale-familiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare\" \/>\n<meta property=\"og:description\" content=\"(Milano) Si apre sabato 21 marzo, a San Paolo in Brasile, il 7&deg; Incontro Nazionale della Pastorale Familiare. La giornata, dedicata alla dimensione spirituale dell&rsquo;adozione, vedr&agrave; la partecipazione del Presidente di Ai.Bi. Marco Griffini e la Responsabile del Settore Adozioni internazionali dell&rsquo;associazione Irene Bertuzzi. Griffini e Bertuzzi, oltre a essere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7\u00b0-incontro-della-pastorale-familiare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-20T13:25:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-03-20T14:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare\",\"datePublished\":\"2009-03-20T13:25:53+00:00\",\"dateModified\":\"2009-03-20T14:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/\"},\"wordCount\":556,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/\",\"name\":\"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2009-03-20T13:25:53+00:00\",\"dateModified\":\"2009-03-20T14:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7\u00b0-incontro-della-pastorale-familiare\/","og_locale":"it_IT","og_type":"article","og_title":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare","og_description":"(Milano) Si apre sabato 21 marzo, a San Paolo in Brasile, il 7&deg; Incontro Nazionale della Pastorale Familiare. La giornata, dedicata alla dimensione spirituale dell&rsquo;adozione, vedr&agrave; la partecipazione del Presidente di Ai.Bi. Marco Griffini e la Responsabile del Settore Adozioni internazionali dell&rsquo;associazione Irene Bertuzzi. Griffini e Bertuzzi, oltre a essere [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7\u00b0-incontro-della-pastorale-familiare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2009-03-20T13:25:53+00:00","article_modified_time":"2009-03-20T14:00:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare","datePublished":"2009-03-20T13:25:53+00:00","dateModified":"2009-03-20T14:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/"},"wordCount":556,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/","url":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/","name":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2009-03-20T13:25:53+00:00","dateModified":"2009-03-20T14:00:02+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/brasile-aibi-al-7%c2%b0-incontro-della-pastorale-familiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Brasile: Ai.Bi. al 7\u00b0 Incontro della Pastorale Familiare"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:10:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=5368"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5368\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=5368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=5368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=5368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}