﻿


{"id":5950,"date":"2009-04-17T10:00:07","date_gmt":"2009-04-17T09:00:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=5950"},"modified":"2009-04-17T12:04:05","modified_gmt":"2009-04-17T11:04:05","slug":"moldova-riconteggio-dei-voti-vittoria-del-partito-comunista","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/","title":{"rendered":"Moldova, riconteggio dei voti: vittoria del partito comunista"},"content":{"rendered":"<p>(Chisinau) La Commissione elettorale ha ribadito <strong>la vittoria dell&#8217;attuale maggioranza.<\/strong> Iuri Ciokan, segretario della Commissione elettorale centrale della Moldova, ha cos\u00ec commentato oggi la chiusura delle procedure di riconteggio dei voti delle elezioni del 5 aprile scorso.\u00a0<\/p>\n<p>La vittoria del partito comunista al potere aveva <strong>scatenato violente manifestazioni da parte degli sconfitti<\/strong> che denunciavano brogli elettorali. &#8220;Le differenze di qualche voto emerse in taluni casi sono talmente minime da non poter cambiare i risultati del voto gi\u00e0 annunciati in precedenza dalla commissione elettorale&#8221;, ha concluso Ciokan.\u00a0<\/p>\n<p>I risultati del nuovo scrutinio &#8211; come ha fatto sapere la Commissione &#8211; verranno ora trasmessi alla Corte costituzionale, alla quale si era rivolto il presidente moldavo, Vladimir Voronin, dopo le contestazioni dell&#8217;esito elettorale da parte dell&#8217;opposizione.<\/p>\n<p>Secondo i risultati ufficiali annunciati dopo il primo scrutinio, ai comunisti era andato il 49,48 percento, seguiti dai liberali col 13,14 percento, dai liberaldemocratici col 12,43 percento e dall&#8217;Alleanza Nostra Moldova con il 9,77 percento dei voti. Tutti gli altri otto partiti partecipanti non avevano superato lo sbarramento del 6 percento richiesto per entrare in parlamento.<\/p>\n<p>(fonte: Peace Reporter)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Chisinau) La Commissione elettorale ha ribadito la vittoria dell&rsquo;attuale maggioranza. Iuri Ciokan, segretario della Commissione elettorale centrale della Moldova, ha cos&igrave; commentato oggi la chiusura delle procedure di riconteggio dei voti delle elezioni del 5 aprile scorso.&nbsp; La vittoria del partito comunista al potere aveva scatenato violente manifestazioni da parte [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-5950","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moldova, riconteggio dei voti: vittoria del partito comunista  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moldova, riconteggio dei voti: vittoria del partito comunista\" \/>\n<meta property=\"og:description\" content=\"(Chisinau) La Commissione elettorale ha ribadito la vittoria dell&rsquo;attuale maggioranza. Iuri Ciokan, segretario della Commissione elettorale centrale della Moldova, ha cos&igrave; commentato oggi la chiusura delle procedure di riconteggio dei voti delle elezioni del 5 aprile scorso.&nbsp; La vittoria del partito comunista al potere aveva scatenato violente manifestazioni da parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-17T09:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-04-17T11:04:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Moldova, riconteggio dei voti: vittoria del partito comunista\",\"datePublished\":\"2009-04-17T09:00:07+00:00\",\"dateModified\":\"2009-04-17T11:04:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/\"},\"wordCount\":188,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/\",\"name\":\"Moldova, riconteggio dei voti: vittoria del partito comunista - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2009-04-17T09:00:07+00:00\",\"dateModified\":\"2009-04-17T11:04:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moldova, riconteggio dei voti: vittoria del partito comunista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moldova, riconteggio dei voti: vittoria del partito comunista  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/","og_locale":"it_IT","og_type":"article","og_title":"Moldova, riconteggio dei voti: vittoria del partito comunista","og_description":"(Chisinau) La Commissione elettorale ha ribadito la vittoria dell&rsquo;attuale maggioranza. Iuri Ciokan, segretario della Commissione elettorale centrale della Moldova, ha cos&igrave; commentato oggi la chiusura delle procedure di riconteggio dei voti delle elezioni del 5 aprile scorso.&nbsp; La vittoria del partito comunista al potere aveva scatenato violente manifestazioni da parte [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2009-04-17T09:00:07+00:00","article_modified_time":"2009-04-17T11:04:05+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Moldova, riconteggio dei voti: vittoria del partito comunista","datePublished":"2009-04-17T09:00:07+00:00","dateModified":"2009-04-17T11:04:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/"},"wordCount":188,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/","url":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/","name":"Moldova, riconteggio dei voti: vittoria del partito comunista - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2009-04-17T09:00:07+00:00","dateModified":"2009-04-17T11:04:05+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/moldova-riconteggio-dei-voti-vittoria-del-partito-comunista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Moldova, riconteggio dei voti: vittoria del partito comunista"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:22:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=5950"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/5950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=5950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=5950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=5950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}